{"id":75,"date":"2013-09-13T19:57:50","date_gmt":"2013-09-13T17:57:50","guid":{"rendered":"https:\/\/francoisbelliot.fr\/?p=75"},"modified":"2018-08-13T15:58:50","modified_gmt":"2018-08-13T13:58:50","slug":"jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001","status":"publish","type":"post","link":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/","title":{"rendered":"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>En cette p\u00e9riode d&rsquo;anniversaire des attentats du 11 septembre 2001,\u00a0 je publie un morceau manquant de mon accusation de la pand\u00e9mie conspirationniste, consacr\u00e9 au comportement scandaleux de certaines familles de victimes.<br \/>\n<\/strong><\/span><\/p>\n<p><em>Nota Bene : Donald Forestier est un auteur fictif invent\u00e9 pour imiter le style des ap\u00f4tres de la version officielle des attentats du 11 septembre 2011 dans les grands m\u00e9dias<\/em>.<\/p>\n<p><!--more--><\/p>\n<p><span style=\"color: #000000;\">Rien ne montre mieux l&rsquo;immoralit\u00e9 des truthers que ce culot avec lequel ils invoquent, \u00e0 l&rsquo;occasion, l&rsquo;argument des \u00ab\u00a0familles de victimes\u00a0\u00bb des attentats du 11 septembre. Non contents d&rsquo;\u00e9garer leurs interlocuteurs dans des d\u00e9veloppements immenses et labyrinthiques, passant sans cesse du coq \u00e0 l&rsquo;\u00e2ne avec une constante mauvaise foi, ceux-ci aiment en effet lancer, telle une brique dans une mare, cette remarque subtile\u00a0: \u00ab\u00a0<i>Mais vous oubliez une chose, les proches des victimes eux-m\u00eames doutent de la version officielle. Plus encore, parmi les truthers, nul sans doute n&rsquo;est plus acharn\u00e9 que ces proches pour critiquer le rapport de la commission d&rsquo;enqu\u00eate et d\u00e9noncer publiquement l&rsquo;administration Bush.<\/i>\u00a0\u00bb Apr\u00e8s quoi ils ajoutent\u00a0: \u00ab\u00a0<i>D&rsquo;ailleurs, si une commission d&rsquo;enqu\u00eate a \u00e9t\u00e9 mise en place, c&rsquo;est uniquement \u00e0 cause de la pression des familles de victimes.\u00a0\u00bb<\/i> Croyant avoir trouv\u00e9 la faille, alors ils ass\u00e8nent, comble de l&rsquo;ironie \u00ab\u00a0<i>Ainsi en d\u00e9fendant la version officielle aveugl\u00e9ment, vous insultez tous ces gens qui ont perdu des proches dans ces \u00e9v\u00e9nements.<\/i>\u00ab\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Cette histoire des familles de victimes m\u00e9fiantes et hargneuses envers l&rsquo;administration Bush p\u00e8se d&rsquo;un poids si lourd dans le d\u00e9bat, qu&rsquo;il m&rsquo;\u00e9tait impossible de couper \u00e0 une plong\u00e9e en profondeur dans cet aspect de l&rsquo;affaire. Je ne cache pas que cette accusation en r\u00e8gle que je m&rsquo;appr\u00eate \u00e0 faire de <i>certaines <\/i>de ces familles est encore plus d\u00e9licate que celle des secouristes du 11 septembre. En effet, c&rsquo;est \u00e0 des p\u00e8res, des fr\u00e8res, des \u00e9pouses, des fils de personnes mortes dans les attentats que je vais m\u2019attaquer \u00e0 pr\u00e9sent.<\/span><\/p>\n<p><span style=\"color: #000000;\">Je rassure tout de suite mon lecteur quant au caract\u00e8re apparemment scandaleux d&rsquo;une telle d\u00e9marche. Connaissant \u00e0 pr\u00e9sent tous les tenants et aboutissants de ce point de l&rsquo;affaire, c&rsquo;est en toute tranquillit\u00e9 que je peux me prononcer et trier le bon grain de l&rsquo;ivraie.<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_71 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57cb4d7fc11\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57cb4d7fc11\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#La_version_officielle_nest_contestee_que_par_une_poignee_de_familles\" title=\"La version officielle n&rsquo;est contest\u00e9e que par une poign\u00e9e de familles\">La version officielle n&rsquo;est contest\u00e9e que par une poign\u00e9e de familles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Les_conditions_dindemnisation_des_familles\" title=\"Les conditions d\u2019indemnisation des familles\">Les conditions d\u2019indemnisation des familles<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Lhistoire_des_70_familles_et_le_role_moteur_des_Jersey_Girls\" title=\"L&rsquo;histoire des 70 familles et le r\u00f4le moteur des Jersey Girls\">L&rsquo;histoire des 70 familles et le r\u00f4le moteur des Jersey Girls<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Precision_sur_la_composition_de_ce_chapitre\" title=\"Pr\u00e9cision sur la composition de ce chapitre\">Pr\u00e9cision sur la composition de ce chapitre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Quatre_veuves_partent_en_campagne%E2%80%A6\" title=\"Quatre veuves partent en campagne&#8230;\">Quatre veuves partent en campagne&#8230;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Les_Jersey_Girls_poussent_Henry_Kissinger_a_la_demission\" title=\"Les Jersey Girls poussent Henry Kissinger \u00e0 la d\u00e9mission\">Les Jersey Girls poussent Henry Kissinger \u00e0 la d\u00e9mission<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Les_Jersey_Girls_font_fleche_de_tout_bois\" title=\"Les Jersey Girls font fl\u00e8che de tout bois\">Les Jersey Girls font fl\u00e8che de tout bois<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Laudition_publique_du_31_mars_2003\" title=\"L&rsquo;audition publique du 31 mars 2003\">L&rsquo;audition publique du 31 mars 2003<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Inutilite_de_la_commission_denquete\" title=\"Inutilit\u00e9 de la commission d\u2019enqu\u00eate\">Inutilit\u00e9 de la commission d\u2019enqu\u00eate<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#Ce_que_sont_devenues_les_Jersey_Girls\" title=\"Ce que sont devenues les Jersey Girls\">Ce que sont devenues les Jersey Girls<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"La_version_officielle_nest_contestee_que_par_une_poignee_de_familles\"><\/span><span style=\"color: #000000;\"><b>La version officielle n&rsquo;est contest\u00e9e que par une poign\u00e9e de familles<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">L\u00e0 o\u00f9 les truthers sous entendent que \u00ab\u00a0toutes\u00a0\u00bb les familles de victimes contestent la version officielle, il se trouve en fait que seule une poign\u00e9e d&rsquo;entre elles se situe dans cette d\u00e9marche. Une poign\u00e9e, combien\u00a0? 5% d&rsquo;entre elles \u00e0 peine, soit environ 70, sur un total de plusieurs milliers. Premi\u00e8re remarque donc, la proportion de familles de victimes exprimant publiquement des doutes est la m\u00eame, grosso modo, que celles des marginaux en tous genres que l&rsquo;on retrouve dans toute soci\u00e9t\u00e9.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cette proportion est encore moins impressionnante si l\u2019on consid\u00e8re la situation psychologique de ces familles. La perte accidentelle d\u2019un proche est un \u00e9v\u00e9nement \u00e0 tous points de vue bouleversant. Confront\u00e9s \u00e0 l\u2019inacceptable, nous pouvons nous fermer \u00e0 toute explication rationnelle et nous perdre dans les \u00e9lucubrations les plus insens\u00e9es.<\/span><\/p>\n<p><span style=\"color: #000000;\">On aurait m\u00eame d\u00fb s&rsquo;attendre, dans ce cas extraordinaire, \u00e0 ce qu&rsquo;une proportion encore plus grande de proches succombent aux sir\u00e8nes de la pand\u00e9mie conspirationniste.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Les_conditions_dindemnisation_des_familles\"><\/span><span style=\"color: #000000;\"><b>Les conditions d\u2019indemnisation des familles<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Les truthers ayant toujours une roue de secours pr\u00eate \u00e0 l\u2019emploi, vous imaginez qu\u2019ils ont trouv\u00e9 une objection \u00e0 cette explication pourtant \u00e9vidente. Ainsi ils arguent\u00a0: \u00ab\u00a0<i>oui, il n\u2019y a que 5% des familles \u00e0 prendre publiquement position contre la version officielle, mais c\u2019est parce que l\u2019immense majorit\u00e9 des familles a accept\u00e9 l\u2019accord que leur proposait le gouvernement conditionnant l\u2019octroi d\u2019indemnit\u00e9s \u00e0 l\u2019abandon de toute poursuite envers les compagnies et les diff\u00e9rents corps d\u2019\u00e9tat concern\u00e9es par les attentats.<\/i>\u00a0<i>Par ailleurs elles ne disposaient que d&rsquo;un temps limit\u00e9 pour se prononcer, ce qui a pu fausser leur d\u00e9cision<\/i>\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Si l\u2019administration Bush a beaucoup tard\u00e9 \u00e0 mettre en place une commission d\u2019enqu\u00eate, en revanche elle a \u00e9t\u00e9 tr\u00e8s prompte \u00e0 mettre en place un fonds d\u2019indemnisation des proches des victimes des attentats. Quelques jours apr\u00e8s les \u00e9v\u00e9nements, le secr\u00e9taire d&rsquo;\u00e9tat \u00e0 la justice, John Aschcroft<a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-les-familles-de-victimes-140846#sdendnote1sym\" rel=\"nofollow\" name=\"sdendnote1anc\"><sup>i<\/sup><\/a> nomme un avocat, Kenneth Feinberg, pour mettre en place un dispositif permettant d\u2019indemniser les proches des victimes. Un fonds de compensation est vot\u00e9 le 21 septembre au Congr\u00e8s. 7 milliards de dollars seront finalement vers\u00e9s aux proches des victimes, au terme du processus.<\/span><\/p>\n<p><span style=\"color: #000000;\">Il est vrai qu&rsquo;au d\u00e9part, les conditions d\u2019indemnisation, suscitent la pol\u00e9mique et de vives r\u00e9actions de la part de nombreuses familles.<\/span><\/p>\n<p><span style=\"color: #000000;\">1) les familles qui acceptent les indemnit\u00e9s se voient interdites d\u2019engager des poursuites envers quiconque, hormis bien s\u00fbr les terroristes islamistes d\u00e9sign\u00e9s dans les jours suivant les attentats suite \u00e0 l\u2019enqu\u00eate \u00e9clair du gouvernement. Pour protester contre cette clause, un millier de proches de victimes se r\u00e9unissent devant le capitole le 1<sup>er<\/sup> Novembre pour demander son annulation. Ils voudraient en effet en particulier attaquer en justice des officiels saoudiens qu\u2019ils pensent impliqu\u00e9s dans les attentats, et tiennent \u00e0 montrer leur indignation contre ce qu&rsquo;ils interpr\u00e8tent comme une tentative d&rsquo;acheter leur silence.<\/span><\/p>\n<p><span style=\"color: #000000;\">2) le caract\u00e8re flou et in\u00e9galitaire des crit\u00e8res d\u2019octroi des indemnit\u00e9s. C\u2019est le 20 d\u00e9cembre 2001 que Kenneth Feinberg les d\u00e9voile. Fabrice Rousselot les d\u00e9taille dans <u><a style=\"color: #000000;\" href=\"http:\/\/www.liberation.fr\/monde\/0101399022-tous-les-morts-du-11-septembre-ne-valent-pas-la-meme-somme\" target=\"_blank\" rel=\"nofollow noopener\">un article de Lib\u00e9ration du 9 janvier 2002<\/a><\/u>. Les proches seront indemnis\u00e9s \u00ab\u00a0<i>selon l&rsquo;\u00e2ge, le salaire et la taille de la famille du d\u00e9funt, tout en y ajoutant une compensation dite \u00ab\u00a0non \u00e9conomique\u00a0\u00bb correspondant \u00e0 la \u00ab\u00a0perte psychologique\u00a0\u00bb.<\/i> Ainsi, \u00ab\u00a0<i>Selon la charte propos\u00e9e, le veuf d&rsquo;une femme de m\u00e9nage avec deux enfants toucherait l&rsquo;\u00e9quivalent de 500 000 dollars. La veuve d&rsquo;un courtier de Wall Street avec deux enfants disposerait, elle, de 4,3 millions de dollars&#8230;\u00a0<\/i>\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">3) les proches des victimes doivent donner leur r\u00e9ponse dans un d\u00e9lai donn\u00e9, \u00e0 savoir avant<a style=\"color: #000000;\" href=\"http:\/\/www.justice.gov\/archive\/victimcompensation\/\" target=\"_blank\" rel=\"nofollow noopener\"> le 22 d\u00e9cembre 2003<\/a>. Au-del\u00e0 de cette date butoir elles ne peuvent plus pr\u00e9tendre \u00e0 rien.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pour ce qui a trait \u00e0 la clause de non poursuite en justice, je trouve tout simplement scandaleux que des gens, aveugl\u00e9s fussent-ils par la perte d\u2019un proche, osent imaginer attaquer des membres de leur gouvernement ou de leurs corps d\u2019\u00e9tat, quand on a en t\u00eate l\u2019enjeu qui s\u2019est imm\u00e9diatement impos\u00e9 apr\u00e8s les attentats, \u00e0 savoir le commencement de la guerre contre la terreur, qui aurait \u00e9t\u00e9 tr\u00e8s d\u00e9licate \u00e0 mettre en \u0153uvre si ces instances avaient \u00e9t\u00e9 mis en cause et embrouill\u00e9es dans des proc\u00e8s odieux et interminables.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le second point semble en effet discutable en apparence\u00a0: on peut \u00eatre choqu\u00e9 de cette disparit\u00e9 des sommes propos\u00e9s en fonction du rang social. Cependant on oublie trop souvent en France que les Etats-Unis sont une soci\u00e9t\u00e9 d&rsquo;entrepreneurs, qui n\u2019a pu atteindre et occuper durablement le rang de premi\u00e8re \u00e9conomie du monde que par la constitution d\u2019une caste d\u2019entrepreneurs fortun\u00e9s, dont beaucoup sont devenus par la suite milliardaires. Et c\u2019est oublier encore que la majorit\u00e9 des milliardaires \u00e9tasuniens respectent tacitement une philosophie qui refl\u00e8te bien le g\u00e9nie de ce peuple, \u00e0 savoir le \u00ab\u00a0<u><a style=\"color: #000000;\" href=\"http:\/\/en.wikipedia.org\/wiki\/The_Gospel_of_Wealth\" target=\"_blank\" rel=\"nofollow noopener\">Gospel of Wealth<\/a><\/u>\u00a0\u00bb. Cette philosophie, r\u00e9v\u00e9l\u00e9e par Andrew Carnegie (surnomm\u00e9 le roi de l\u2019acier) \u00e0 la fin du XIX\u00e8me si\u00e8cle, enjoint aux riches de reverser d\u2019eux-m\u00eames une partie de leur fortune dans des \u0153uvres de charit\u00e9 et des fondations. C\u2019est gr\u00e2ce \u00e0 cette philosophie que sont n\u00e9es <u><a style=\"color: #000000;\" href=\"http:\/\/carnegieendowment.org\/#\/slide_459_does-egypt-s-constitutional-process-still-matter\" target=\"_blank\" rel=\"nofollow noopener\">la fondation Carnegie pour la paix<\/a><\/u>, <u><a style=\"color: #000000;\" href=\"http:\/\/www.opensocietyfoundations.org\/\" target=\"_blank\" rel=\"nofollow noopener\">l\u2019Open Society Institute<\/a><\/u> de George Soros, ou encore la <u><a style=\"color: #000000;\" href=\"http:\/\/www.fordfoundation.org\/\" target=\"_blank\" rel=\"nofollow noopener\">fondation Ford<\/a><\/u> et <u><a style=\"color: #000000;\" href=\"http:\/\/www.gatesfoundation.org\/\" rel=\"nofollow\">la fondation Bill et Melinda Gates<\/a><\/u>. En laissant le g\u00e9nie \u00e9tasunien s&rsquo;exprimer librement plut\u00f4t que de le corseter aux noms de chim\u00e9riques principes \u00e9galitaires, \u00e0 coup s\u00fbr, d&rsquo;elles-m\u00eames, les familles les plus g\u00e9n\u00e9reusement indemnis\u00e9es se seraient spontan\u00e9ment d\u00e9lest\u00e9es d&rsquo;une partie de leurs millions pour en faire profiter les moins nanties.<\/span><\/p>\n<p><span style=\"color: #000000;\">Quant au probl\u00e8me de la date butoir, il suffit simplement de consid\u00e9rer les faits\u00a0: le 22 d\u00e9cembre 2003 au soir, 95\u00a0% des proches des victimes avaient accept\u00e9 le deal, et repartaient avec une somme moyenne, tout de m\u00eame, de 1,6 million de dollars\u00a0! Cette proportion massive montre que les doutes n\u2019\u00e9taient pas si profonds et r\u00e9pandus que cela\u2026 Et contrairement \u00e0 ce que pr\u00e9tendent certains, les familles avaient largement le temps de peser le pour et le contre puisqu&rsquo;elles disposaient de plus de deux ans pour accepter ou non les indemnit\u00e9s du fond de compensation.<\/span><\/p>\n<p><span style=\"color: #000000;\">Mais c\u2019est toujours la m\u00eame chose, les minorit\u00e9s agissantes font toujours plus de bruit que les majorit\u00e9s silencieuses. Les extr\u00e9mistes sont toujours minoritaires mais comme ils crient plus fort que tout le monde et avec le plus de constance, on finit par ne plus entendre qu\u2019eux. Comme l&rsquo;explique G\u00e9rard Br\u00f6nner dans un beau livre paru en mars dernier, \u00ab\u00a0la d\u00e9mocratie des cr\u00e9dules\u00a0\u00bb\u00a0: \u00ab\u00a0<i>Ces situations (&#8230;) sont toujours favorables aux groupes, m\u00eame tr\u00e8s minoritaires, qui sont motiv\u00e9s pour imposer leur point de vue. Ces petits groupes peuvent donc dominer des groupes plus importants, agac\u00e9s, sid\u00e9r\u00e9s, voire atterr\u00e9s par les prises de position du petit groupe, mais il ne se trouve pas parmi eux suffisamment de contradicteurs motiv\u00e9s pour occuper le march\u00e9 de l&rsquo;offre cognitive\u00a0.<\/i>\u00a0\u00bb (p 84)<\/span><\/p>\n<p><span style=\"color: #000000;\">C&rsquo;est ainsi que ces 5% de familles restantes, au nombre de 70 environ, tr\u00e8s vite vont se mettre \u00e0 faire un bruit pas possible, et se rendre c\u00e9l\u00e8bres en for\u00e7ant, pratiquement \u00e0 elles seules, l\u2019administration Bush \u00e0 ouvrir une commission d\u2019enqu\u00eate qui n\u2019aurait jamais d\u00fb voir le jour.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Lhistoire_des_70_familles_et_le_role_moteur_des_Jersey_Girls\"><\/span><span style=\"color: #000000;\"><b>L&rsquo;histoire des 70 familles et le r\u00f4le moteur des Jersey Girls<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Pour raconter l\u2019histoire de ces 70 familles, je me baserai, comme pour <u><a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-richard-gage-et-sibel-82411\" target=\"_blank\" rel=\"noopener\">le chapitre<\/a><\/u> o\u00f9 je traite de l\u2019affaire Sibel Edmonds et <u><a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-les-sauveteurs-du-11-09-102031\">celui<\/a><\/u> sur les sauveteurs du 11 septembre, d\u2019un documentaire r\u00e9alis\u00e9 \u00e0 leur gloire en 2006 intitul\u00e9 <u><a style=\"color: #000000;\" href=\"http:\/\/www.youtube.com\/watch?v=tpSLAWdJ5DE\" target=\"_blank\" rel=\"nofollow noopener\">911 press for truth<\/a><\/u>. Comme \u00ab\u00a0<u><a style=\"color: #000000;\" href=\"http:\/\/nemesistv.info\/video\/7OAMDY49YMD6\/sibel-edmonds-une-femme-a-abattre\" target=\"_blank\" rel=\"nofollow noopener\">une femme \u00e0 abattre\u00a0<\/a><\/u>\u00a0\u00bb, et \u00ab\u00a0<u><a style=\"color: #000000;\" href=\"http:\/\/www.dailymotion.com\/video\/xetmdd_docu-les-heros-sacrifies-du-11-sept_news\" target=\"_blank\" rel=\"nofollow noopener\">les h\u00e9ros sacrifi\u00e9s du 11 septembre\u00a0<\/a><\/u>\u00a0\u00bb, c&rsquo;est un documentaire de propagande des plus grossiers dont le seul et \u00e9vident dessein est de jeter la suspicion sur l\u2019administration Bush, pour lui faire porter le chapeau des attentats. L\u2019objet de ce documentaire, plus largement, est de raconter l\u2019histoire de la mise en place de la commission d\u2019enqu\u00eate sur les attentats du 11 septembre 2001, en prenant pour fil directeur le r\u00f4le pr\u00e9pond\u00e9rant jou\u00e9 par 4 veuves du New Jersey. Comme le fait en effet remarquer le journaliste Matthew Purdy dans un article du New York Times du 22 d\u00e9cembre 2002\u00a0: \u00ab\u00a0<i>Si la commission a \u00e9t\u00e9 mise en place, c\u2019est en grande partie sous la pression des familles de victimes, parmi lesquelles quatre veuves du New Jersey qui s\u2019appelaient elles-m\u00eames les Jersey Girls.\u00a0<\/i>\u00a0\u00bb Je compl\u00e9terai ma pr\u00e9sentation au besoin par des informations pioch\u00e9es ailleurs, en particulier sur le site conspirationniste <a style=\"color: #000000;\" href=\"http:\/\/www.historycommons.org\/project.jsp?project=911_project\" target=\"_blank\" rel=\"nofollow noopener\">911 Complete Timeline<\/a> de Daniel Thompson, sur lequel s&rsquo;appuie abondamment l&rsquo;auteur du documentaire sur les Jersey Girls. Il ne m&rsquo;importe en effet pas seulement de restituer sans la d\u00e9former la parole officielle, je veux aussi, pour \u00eatre cr\u00e9dible jusqu&rsquo;au bout, affronter ses adversaires <i>sur leur terrain<\/i> et <i>avec leurs armes<\/i>.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Precision_sur_la_composition_de_ce_chapitre\"><\/span><span style=\"color: #000000;\"><b>Pr\u00e9cision sur la composition de ce chapitre<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">L&rsquo;histoire des familles de victimes douteuses \u00e9tant \u00e9troitement li\u00e9e \u00e0 celle de la mise en place de la commission d&rsquo;enqu\u00eate, et le chapitre suivant traitant des doutes nourris par les commissionnaires eux-m\u00eames envers leurs conditions de travail et leur travail final, j&rsquo;ai opt\u00e9 pour une s\u00e9paration chronologique dans le r\u00e9cit de <i>l&rsquo;histoire de la commission d&rsquo;enqu\u00eate<\/i>\u00a0: Si le r\u00f4le des Jersey Girls est pr\u00e9pond\u00e9rant au d\u00e9but de l&rsquo;histoire, il tend ensuite \u00e0 s&rsquo;estomper, les commissionnaires semblant en quelque sorte prendre leur relais dans l&rsquo;expression de divers doutes. Je m&rsquo;arr\u00eaterai donc dans ce chapitre au d\u00e9but de l&rsquo;ann\u00e9e 2003, en prenant pour date symbolique la journ\u00e9e du 31 mars, qui voit la commission tenir sa premi\u00e8re audition publique.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Quatre_veuves_partent_en_campagne%E2%80%A6\"><\/span><span style=\"color: #000000;\"><b>Quatre veuves partent en campagne&#8230;<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Au commencement \u00e9taient les Jersey Girls, quatre femmes de l\u2019\u00e9tat du New Jersey, voisin de celui de New York, quatre femmes ayant en commun d\u2019avoir perdu leur mari dans les attentats du 11 septembre.<\/span><\/p>\n<p><span style=\"color: #000000;\">Patty Casazza et Lorie van Auken \u00e9taient mari\u00e9es \u00e0 deux gestionnaires d\u2019obligations d\u2019\u00e9tat chez Cantor Fitzgerald, au 104 \u00e9tage de la tour nord. Le mari de Mindy Kleinberg \u00e9tait gestionnaire financier dans la m\u00eame entreprise et au m\u00eame \u00e9tage. Kristen Breitweiser \u00e9tait l\u2019\u00e9pouse du vice pr\u00e9sident senior de la fiduciary trust international dans la tour sud. Les quatre hommes sont morts dans l\u2019effondrement des tours jumelles subs\u00e9quent au crach des avions.<\/span><\/p>\n<p><span style=\"color: #000000;\">J\u2019imagine le moment o\u00f9 la vie de ces femmes a bascul\u00e9. Certaines \u00e9taient au t\u00e9l\u00e9phone avec leur mari en m\u00eame temps qu\u2019elles regardaient la t\u00e9l\u00e9vision lorsque les tours se sont effondr\u00e9es. J\u2019imagine la surprise, l\u2019angoisse folle, puis soudain, la compr\u00e9hension, le choc, le traumatisme.<\/span><\/p>\n<p><span style=\"color: #000000;\">J\u2019imagine ensuite l\u2019incr\u00e9dulit\u00e9, l\u2019annonce aux enfants, la premi\u00e8re nuit blanche\u2026<\/span><\/p>\n<p><span style=\"color: #000000;\">J\u2019imagine les jours suivants, \u00e0 rester riv\u00e9es \u00e0 la t\u00e9l\u00e9vision, \u00e0 appeler un par un les proches pour annoncer la terrible nouvelle.<\/span><\/p>\n<p><span style=\"color: #000000;\">J\u2019imagine enfin le moment fatal ou le virus conspirationniste a commenc\u00e9 \u00e0 s\u2019insinuer dans leurs esprits, la question terrible\u00a0: pourquoi\u00a0? pourquoi\u00a0? se r\u00e9percutant lancinante \u00e0 l\u2019int\u00e9rieur de leurs cervelles meurtries. J\u2019imagine\u2026<\/span><\/p>\n<p><span style=\"color: #000000;\">Certainement moins solides que d\u2019autres veuves, qui avaient d\u00e9j\u00e0 le couteau entre les dents pour aller bouffer du taliban dans les montagnes d\u2019Afghanistan, elles cherchent une signification plus haute \u00e0 la mort de leurs maris. Premier grain de sable qui se met \u00e0 gripper leur intellect, elles s\u2019\u00e9tonnent qu\u2019aucune commission d\u2019enqu\u00eate n\u2019ait \u00e9t\u00e9 imm\u00e9diatement mise en place. Les pauvrettes oublient que les \u00e9vidents coupables ont tous \u00e9t\u00e9 identifi\u00e9s les jours suivants, gr\u00e2ce, entre autres, \u00e0 des passeports et des cartes d&rsquo;identit\u00e9 trouv\u00e9s dans les d\u00e9combres\u00a0. C\u2019est alors qu\u2019elles se lancent, sans la moindre pr\u00e9paration, dans cette mer houleuse et sans bornes qu\u2019est le World Wide Web. L\u2019une confesse qu\u2019elle a \u00ab\u00a0<i>pass\u00e9 beaucoup de temps devant l\u2019ordinateur\u00a0<\/i>\u00a0\u00bb. L\u2019autre qu\u2019elle s\u2019est mise \u00e0 passer des \u00ab\u00a0<i>nuits \u00e0 faire des recherches\u00a0<\/i>\u00a0\u00bb, parce qu\u2019elle \u00ab\u00a0<i>n\u2019arrivait pas \u00e0 dormir \u00e0 cause de la souffrance\u00a0<\/i>\u00a0\u00bb. Elles commencent \u00e0 faire leurs certaines questions\u00a0: \u00ab\u00a0<i>Pourquoi aucun des 4 avions n\u2019a-t-il \u00e9t\u00e9 intercept\u00e9\u00a0?\u00a0<\/i>\u00a0\u00bb, \u00ab\u00a0<i>Pourquoi le pr\u00e9sident Bush n\u2019a-t-il pas r\u00e9agi imm\u00e9diatement\u00a0<\/i>\u00a0\u00bb, \u00ab\u00a0<i>Pourquoi les enqu\u00eateurs du FBI \u00e9taient-ils continuellement remplac\u00e9s\u00a0?<\/i>\u00a0\u00bb \u00ab\u00a0<i>Comment des gratte-ciel peuvent-ils s\u2019\u00e9crouler au sol en dix secondes\u00a0<\/i>\u00a0?\u00a0\u00bb, et tant d\u2019autres&#8230;<\/span><\/p>\n<p><span style=\"color: #000000;\">Le documentaire ne d\u00e9taille pas les circonstances de leur rencontre. En tous cas c\u2019est en octobre 2001 que s\u2019op\u00e8re la jonction entre les quatre \u00ab\u00a0Jersey Girls\u00a0\u00bb. Alors qu\u2019elles doutaient seules face \u00e0 leur \u00e9cran d&rsquo;ordinateur, les voil\u00e0 qui se confortent mutuellement dans leurs suspicions, et se mettent \u00e0 compiler ensemble des listes de faits et argumentaires sur les diff\u00e9rents points de l\u2019affaire qui leur semblent douteux. Elles re\u00e7oivent rapidement dans leur qu\u00eate le concours de la journaliste Gail Sheehy qui d\u00e9cide de se d\u00e9vouer corps et \u00e2me \u00e0 leur cause.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dans les mois qui suivent elles rencontrent d\u2019autres membres des familles des victimes qui comme elles \u00e9prouvent des doutes envers la version officielle \u00e9tablie par l\u2019administration Bush.<\/span><\/p>\n<p><span style=\"color: #000000;\">Elles rencontrent \u00e9galement un membre des familles de victimes du crach du Pan Am 103 au-dessus de Lockerbie le 21 d\u00e9cembre 1988, qui leur donne le conseil suivant\u00a0: \u00ab\u00a0<i>Si vous n\u2019obtenez pas de r\u00e9ponses (du gouvernement), alors constituez un collectif.\u00a0<\/i>\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Enhardies par ces conseils et le fait de se retrouver dans la s\u00e9curit\u00e9 d\u2019un groupe, elles d\u00e9cident d\u2019organiser un rassemblement devant le Capitole \u00e0 Washington, <u><a style=\"color: #000000;\" href=\"http:\/\/www.nytimes.com\/2002\/06\/12\/us\/traces-of-terror-survivors-trade-center-widows-lobby-for-independent-inquiry.html\" target=\"_blank\" rel=\"nofollow noopener\">le 11 juin 2002<\/a><\/u>. Des parents, amis, et sympathisants, viennent produire un effet de nombre en affluant dans quatre cars affr\u00e9t\u00e9s pour la circonstance, pour applaudir leurs interventions.<\/span><\/p>\n<p><span style=\"color: #000000;\">Toute cette troupe, munie de pancartes arborant les portraits de proches disparus, se rend ensuite dans les halls du congr\u00e8s pour exiger la tenue d\u2019une commission d\u2019enqu\u00eate ind\u00e9pendante sur les attentats du 11 septembre 2001. Ils rallient \u00e0 leur cause une poign\u00e9e de R\u00e9publicains, parmi lesquels le Repr\u00e9sentant Christopher H. Smith du New Jersey, qui accepte de parrainer un projet de loi appelant \u00e0 la mise en place d\u2019une telle commission, dont le pr\u00e9sident Bush et le vice pr\u00e9sident Cheney, absorb\u00e9s qu&rsquo;il sont corps et \u00e2me dans les premi\u00e8res man\u0153uvres de la \u00ab\u00a0guerre contre la terreur\u00a0\u00bb, ne veulent pas entendre parler. De telles commissions avaient \u00e9t\u00e9 mises en place pour faire la lumi\u00e8re sur des \u00e9v\u00e9nements graves engageant le destin des \u00c9tats-Unis, par exemple le raid sur Pearl Harbour en 1941, l\u2019assassinat du pr\u00e9sident Kennedy en 1963, ou encore les relations sexuelles entre le pr\u00e9sident Clinton et une stagiaire de la Maison Blanche de 1995 \u00e0 1997.<\/span><\/p>\n<p><span style=\"color: #000000;\">En bonnes propagandistes, les Jersey Girls savent toutefois que pour parvenir \u00e0 leurs fins, ce \u00ab\u00a0happening\u00a0\u00bb ne suffira pas. Dans nos d\u00e9mocraties modernes, c\u2019est par les grands m\u00e9dias qu\u2019il faut passer pour se faire entendre. Elles profitent donc du d\u00e9part de feu m\u00e9diatique d\u00e9clench\u00e9 par leur d\u00e9marche pour poser comme condition aux journalistes d\u00e9sireux de les interviouver de signaler obligatoirement le fait qu\u2019aucune enqu\u00eate digne de ce nom n\u2019a \u00e9t\u00e9 diligent\u00e9e \u00e0 ce jour.<\/span><\/p>\n<p><span style=\"color: #000000;\">T\u00e9l\u00e9g\u00e9niques, jouant \u00e0 fond sur leur statut de veuves \u00e9plor\u00e9es, elles parviennent \u00e0 susciter un engouement public qui met sur l\u2019administration Bush une pression jusqu\u2019alors inconnue, et le 27 novembre 2002, soit 441 jours apr\u00e8s les \u00e9v\u00e9nements, George W. Bush et le Congr\u00e8s des \u00c9tats-Unis actent la mise en place de la commission, avec \u00e0 sa pr\u00e9sidence et sa vice-pr\u00e9sidence, l\u2019ancien secr\u00e9taire d\u2019\u00e9tat des administrations Nixon et Ford, Henry Kissinger, et le s\u00e9nateur George Mitchell.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Les_Jersey_Girls_poussent_Henry_Kissinger_a_la_demission\"><\/span><span style=\"color: #000000;\"><b>Les Jersey Girls poussent Henry Kissinger \u00e0 la d\u00e9mission<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Le r\u00f4le des Jersey Girls ne s\u2019est pas seulement limit\u00e9e \u00e0 forcer l\u2019administration Bush \u00e0 mettre en place une commission d\u2019enqu\u00eate inutile et susceptible de saper la cr\u00e9dibilit\u00e9 des Etats-Unis dans la guerre \u00e0 la Terreur d\u00e9clar\u00e9e dans la foul\u00e9e des attentats, elles n\u2019ont eu de cesse en effet par la suite d\u2019en perturber le fonctionnement en mettant incessamment des b\u00e2tons dans les roues des commissionnaires.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cela commence presque imm\u00e9diatement. Kristen Breitweiser, que l\u2019on peut regarder comme la t\u00eate pensante du quatuor, nourrit rapidement des doutes quant \u00e0 la nomination d\u2019Henry Kissinger. Est-ce bien la personne\u00a0idoine\u00a0? Elle fait une petite recherche sur des sites conspirationnistes et croit lui d\u00e9couvrir quelques casseroles. N\u2019aurions-nous pas l\u00e0 un homme qui aurait \u00ab\u00a0<i>un penchant pour le secret\u00a0<\/i>\u00a0\u00bb\u00a0? Il y aurait des \u00ab\u00a0<i>questions \u00e0 propos de son r\u00f4le pendant la guerre du Viet Nam<\/i>\u00a0\u00bb et \u00ab\u00a0<i>dans le coup d\u2019\u00e9tat au Chili\u00a0<\/i>\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">Remplies de doutes, les Jersey Girls se rendent \u00e0 son bureau \u00e0 New York pour lui poser d\u2019autres questions plus pointues. Breitweiser pense avoir lev\u00e9 des li\u00e8vres encore plus compromettants et se figure qu\u2019il y aurait m\u00eame des conflits d\u2019int\u00e9r\u00eats politiques dans la nomination d\u2019une telle personnalit\u00e9 \u00e0 un poste aussi sensible.<\/span><\/p>\n<p><span style=\"color: #000000;\">Lors de cet entretien elle lui pose notamment la question suivante\u00a0: \u00ab\u00a0<i>Avez-vous des clients en Arabie Saoudite\u00a0dont vous aimeriez nous parler\u00a0?<\/i>\u00a0\u00bb, qu\u2019elle compl\u00e8te avec cette autre\u00a0: \u00ab\u00a0<i>avez-vous un client du nom de Ben Laden\u00a0<\/i>\u00a0?\u00a0\u00bb Selon la l\u00e9gende rapport\u00e9e par Patty Cassaza, \u00ab\u00a0<i>il n\u2019\u00e9tait pas tr\u00e8s \u00e0 l\u2019aise, il gigotait sur son canap\u00e9\u00a0<\/i>\u00a0\u00bb, et en entendant la deuxi\u00e8me question il aurait failli renverser sa tasse de caf\u00e9. Vous imaginez bien que nos quatre luronnes y ont imm\u00e9diatement vu un \u00ab\u00a0aveu physique\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">Somm\u00e9 de r\u00e9v\u00e9ler la liste de ses clients, il s\u2019y refuse et d\u00e9cide de d\u00e9missionner, ce qui est act\u00e9 le 13 d\u00e9cembre 2002.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les truthers y ont voulu voir un exemple \u00e9clatant des vices de forme initiaux de la commission d\u2019enqu\u00eate mais on peut faire une toute autre interpr\u00e9tation. Pour commencer, la question du coup d\u2019\u00e9tat au Chili et de son r\u00f4le au Vietnam ne sauraient en aucun cas constituer des arguments. En effet, en 1973, Kissinger recevait le prix Nobel de la paix pour son r\u00f4le dans la r\u00e9solution des accords de paix avec le Vietnam\u00a0; or c\u2019est pr\u00e9cis\u00e9ment l\u2019ann\u00e9e o\u00f9 survient le coup d\u2019\u00e9tat au Chili, un 11 septembre au passage. S\u2019il avait eu un r\u00f4le trouble dans ces deux affaires, jamais \u00e0 coup s\u00fbr il n\u2019aurait \u00e9t\u00e9 honor\u00e9 d&rsquo;une distinction aussi prestigieuse. Quant \u00e0 la s\u00e9quence de \u00ab\u00a0panique\u00a0\u00bb suscit\u00e9e dans son bureau par les Jersey Girls, j\u2019y vois quant \u00e0 moi la marque d\u2019un homme bless\u00e9 par une \u00e9ni\u00e8me suspicion sans fondement sur sa carri\u00e8re et son CV. L\u2019homme, d\u00e9j\u00e0 tr\u00e8s \u00e2g\u00e9, n\u2019a pas support\u00e9 d\u2019\u00eatre une nouvelle fois harcel\u00e9 de la sorte apr\u00e8s toute une vie pass\u00e9e \u00e0 servir fid\u00e8lement son pays sans compter ses forces. Apr\u00e8s m\u00fbre r\u00e9flexion il a d\u00e9cid\u00e9 de jeter l&rsquo;\u00e9ponge, pour laisser \u00e0 un autre la charge \u00e9crasante de pr\u00e9sider cette commission d\u2019enqu\u00eate.<\/span><\/p>\n<p><span style=\"color: #000000;\">Peut-\u00eatre aussi avait-il \u00e9t\u00e9 \u00e9chaud\u00e9 par les soup\u00e7ons semblables port\u00e9s contre le vice pr\u00e9sident de la commission le s\u00e9nateur Mitchell, <a style=\"color: #000000;\" href=\"http:\/\/edition.cnn.com\/2002\/ALLPOLITICS\/12\/11\/mitchell.resigns\/\" target=\"_blank\" rel=\"nofollow noopener\">qui avait d\u00e9missionn\u00e9 deux jours plus t\u00f4t<\/a> pour les m\u00eames raisons.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nombre de truthers et familles de victimes ont point\u00e9 la lenteur et la difficult\u00e9 de la mise en route de la commission d&rsquo;enqu\u00eate, mais on voit bien, sous cet \u00e9clairage que ces retards du d\u00e9but sont largement imputables \u00e0 l\u2019activisme n\u00e9faste des Jersey Girls.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Les_Jersey_Girls_font_fleche_de_tout_bois\"><\/span><span style=\"color: #000000;\"><b>Les Jersey Girls font fl\u00e8che de tout bois<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Apr\u00e8s ces deux d\u00e9missions spectaculaires, les Jersey Girls, en compagnie d&rsquo;autres proches de victimes, d\u00e9cident de mettre sur pied le Comit\u00e9 Directeur des Familles (FSC), dont l&rsquo;un des objectifs avou\u00e9s est de contr\u00f4ler le travail de la commission d&rsquo;enqu\u00eate. Les 12 membres de ce comit\u00e9 directeur n&rsquo;ont aucune exp\u00e9rience en la mati\u00e8re mais le virus conspirationniste a d\u00e9j\u00e0 fait dans leurs esprits des d\u00e9g\u00e2ts irr\u00e9versibles. Ils sont d\u00e9sormais \u00e0 l\u2019aff\u00fbt du moindre conflit d&rsquo;int\u00e9r\u00eat, de la moindre zone d&rsquo;ombre, guettent chaque h\u00e9sitation, analysent chaque silence, et br\u00fblent d&rsquo;accrocher de nouveaux scalps \u00e0 leurs ceintures.<\/span><\/p>\n<p><span style=\"color: #000000;\">Elles se trouveront bient\u00f4t un bouc \u00e9missaire, sur lequel elles ne cesseront de s&rsquo;acharner jusqu&rsquo;\u00e0 la fin, en l&rsquo;occurrence le directeur ex\u00e9cutif de la commission d&rsquo;enqu\u00eate lui-m\u00eame, Philip Zelikow, nomm\u00e9 en janvier 2003 et que l&rsquo;on peut consid\u00e9rer comme le ma\u00eetre d&rsquo;oeuvre du rapport. Comme pour Kissinger, elles exigeront sa d\u00e9mission \u00e0 plusieurs reprises, et croiront lui d\u00e9couvrir des conflits d&rsquo;int\u00e9r\u00eat plus incroyables encore.<\/span><\/p>\n<p><span style=\"color: #000000;\">Elles s&rsquo;int\u00e9resseront aux conditions de travail des commissionnaires, remettront en cause les conditions d&rsquo;acc\u00e8s aux documents utiles, \u00e0 l&rsquo;impossibilit\u00e9 pour les commissionnaires d&rsquo;interroger directement les d\u00e9tenus, aux r\u00e9ticences de la Maison Blanche \u00e0 coop\u00e9rer pleinement, elles croiront d\u00e9busquer des mensonges de la FAA, du NORAD, de la CIA et de membres de l&rsquo;administration Bush. Elles forceront Condoleeza Rice, secr\u00e9taire d&rsquo;\u00e9tat \u00e0 la s\u00e9curit\u00e9 nationale, \u00e0 un humiliant t\u00e9moignage sous serment devant la commission.<\/span><\/p>\n<p><span style=\"color: #000000;\">Je reviendrai en d\u00e9tails sur ces diff\u00e9rents points dans le chapitre suivant. En attendant, en ce d\u00e9but d&rsquo;ann\u00e9e 2003, les Jersey Girls et les 70 familles fourbissent leurs armes en vue d&rsquo;un \u00e9v\u00e9nement qu&rsquo;elles attendent avec une extr\u00eame impatience\u00a0: la premi\u00e8re audition publique de la commission d&rsquo;enqu\u00eate, qui doit se tenir le 31 mars 2003.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Laudition_publique_du_31_mars_2003\"><\/span><span style=\"color: #000000;\"><b>L&rsquo;audition publique du 31 mars 2003<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Le moment est solennel. Les jersey Girls ne sont pas les seules \u00e0 avoir coch\u00e9 cette date dans leur calendrier. Parlementaires, traders, femmes de m\u00e9nage, soldats, c&rsquo;est tout un peuple qui ce jour-l\u00e0 se retrouve devant son petit \u00e9cran pour \u00e9couter les premi\u00e8res auditions.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dans sa pr\u00e9sentation inaugurale le pr\u00e9sident de la commission Thomas Kean d\u00e9clare, entre autres choses, que le r\u00f4le de la commission d&rsquo;enqu\u00eate ne saurait en aucun cas consister \u00e0 pointer les responsabilit\u00e9s d&rsquo;un tel ou un tel dans les diff\u00e9rents corps d&rsquo;\u00e9tat \u00e9tasuniens implicables dans les attentats. Ces mots provoquent une rumeur dans la foule de proches qui s&rsquo;est press\u00e9e ce jour-l\u00e0. En effet, les membres du FSC n&rsquo;avaient eu de cesse de rappeler qu&rsquo;ils tenaient absolument \u00e0 ce que des responsabilit\u00e9s \u00e9tasuniennes soient mises en lumi\u00e8re, et des officiels \u00e9ventuellement poursuivis pour manquements graves.<\/span><\/p>\n<p><span style=\"color: #000000;\">L&rsquo;\u00e9motion est port\u00e9e \u00e0 son comble quand Mindy Kleinberg prend la parole au nom du FSC dans la foul\u00e9e. Les commissionnaires ont en effet autoris\u00e9 quatre membres repr\u00e9sentant les quatre organisations de familles existantes \u00e0 s&rsquo;exprimer t\u00f4t dans cette premi\u00e8re journ\u00e9e. Dans un ton path\u00e9tique, aux bords des larmes, la Jersey Girl se lance dans <u><a style=\"color: #000000;\" href=\"http:\/\/govinfo.library.unt.edu\/911\/hearings\/hearing1\/witness_kleinberg.htm\" target=\"_blank\" rel=\"nofollow noopener\">un long discours<\/a><\/u> dont j&rsquo;isole la diatribe suivante\u00a0: \u00ab\u00a0<i>Concernant les attaques du 11 septembre,\u00a0il a \u00e9t\u00e9 dit que les agences de renseignement doivent avoir raison 100% du temps et que les terroristes n&rsquo;ont besoin d&rsquo;avoir de la chance qu&rsquo;une seule fois. Cette explication des attaques d\u00e9vastatrices du 11 septembre, \u00e9l\u00e9mentaire \u00e0 premi\u00e8re vue, est fausse et ne tient pas. Car les terroristes du 11 septembre n&rsquo;ont pas \u00e9t\u00e9 chanceux seulement une fois. Ils ont eu constamment de la chance, encore et encore.\u00a0\u00bb<\/i><\/span><\/p>\n<p><span style=\"color: #000000;\">Kleinberg se lance alors dans une s\u00e9rie de questions cens\u00e9es illustrer son propos\u00a0: Pourquoi la SEC n&rsquo;a-t-elle pas relev\u00e9, dans la semaine pr\u00e9c\u00e9dant les attentats les op\u00e9rations fianci\u00e8res suspectes concernant les deux compagnies a\u00e9riennes impliqu\u00e9es dans les attentats\u00a0? Comment 15 des terroristes ont-ils pu obtenir des visas en violation des proc\u00e9dures en vigueur\u00a0? Comment ont-ils pu passer le contr\u00f4le des a\u00e9roports alors que nombre d&rsquo;entre eux \u00e9taient fich\u00e9s\u00a0sensibles\u00a0? Comment ont-ils pu embarquer des cutters dans les avions\u00a0? Comment se fait-il qu&rsquo;aucun avion n&rsquo;ait \u00e9t\u00e9 intercept\u00e9, surtout apr\u00e8s le crach inaugural du vol AA 11\u00a0? Pourquoi le secr\u00e9taire \u00e0 la d\u00e9fense (Rumsfled) n&rsquo;a-t-il pas \u00e9t\u00e9 inform\u00e9 qu&rsquo;un des quatre avions d\u00e9tourn\u00e9 fon\u00e7ait droit vers le lieu o\u00f9 il travaillait, \u00e0 savoir le Pentagone\u00a0? Pourquoi le pr\u00e9sident Bush n&rsquo;a-t-il pas tout de suite \u00e9t\u00e9 mis en s\u00fbret\u00e9 apr\u00e8s le crach du premier avion\u00a0?<\/span><\/p>\n<p><span style=\"color: #000000;\">Je ne vais pas m&rsquo;\u00e9tendre sur cette liste de questions qui font partie du cat\u00e9chisme que tout bon truther doit conna\u00eetre par c\u0153ur. J&rsquo;ai r\u00e9pondu au probl\u00e8me des op\u00e9rations financi\u00e8res suspectes <u><a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/09\/25\/jaccuse-4-12-les-delits-dinities-du-11-septembre\/\" target=\"_blank\" rel=\"noopener\">dans le chapitre 2<\/a><\/u> et quant aux autres, le rapport de la commission d&rsquo;enqu\u00eate que j&rsquo;ai r\u00e9sum\u00e9 <u><a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/09\/18\/jaccuse-3-12-resume-du-rapport-de-la-commission-denquete\/\" target=\"_blank\" rel=\"noopener\">dans le chapitre 1<\/a><\/u> y a selon moi excellemment r\u00e9pondu. Je ferais seulement remarquer qu&rsquo;alors que Thomas Kean et Lee Hamilton avaient ouvert cette premi\u00e8re journ\u00e9e d&rsquo;auditions par <u><a style=\"color: #000000;\" href=\"http:\/\/govinfo.library.unt.edu\/911\/archive\/hearing1\/9-11Commission_Hearing_2003-03-31.htm#remarks\" target=\"_blank\" rel=\"nofollow noopener\">deux interventions extr\u00eament convaincantes et \u00e9mouvantes<\/a><\/u>, toute de suite, cette intervention de la Jersey Girl a compl\u00e8tement plomb\u00e9 l&rsquo;ambiance. Les deux hommes, qui avaient remplac\u00e9 au pied lev\u00e9 Kissinger et Mitchell \u00e0 la mi d\u00e9cembre, ont d\u00fb tout de suite d\u00fb se sentir d\u00e9courag\u00e9s, de m\u00eame pour les commissionnaires et l&rsquo;\u00e9quipe d&rsquo;enqu\u00eateurs dirig\u00e9e par Philip Zelikow. Cela, j&rsquo;en suis certain, les a ralentis dans leur travail par la suite et a \u00e9t\u00e9 en partie cause des quelques passages discutables du rapport final sur lesquels quelques proches des victimes se sont ensuite acharn\u00e9s.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pressions populistes sur leur gouvernement, m\u00e9fiance malsaine envers les \u00e9lites de leurs pays, retardement de la mise en route de la commission d&rsquo;enqu\u00eate, accusations de conflits d&rsquo;int\u00e9r\u00eat sans fondement contre des patriotes irr\u00e9prochables, d\u00e9clarations incendiaires et hors de propos par le biais du comit\u00e9 Directeur des Familles, d&rsquo;un bout \u00e0 l&rsquo;autre de l&rsquo;histoire de la commission d&rsquo;enqu\u00eate, l&rsquo;influence des Jersey Girls et des 70 familles ultra-minoritaires s&rsquo;est r\u00e9v\u00e9l\u00e9 n\u00e9gatif et dommageable.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Inutilite_de_la_commission_denquete\"><\/span><span style=\"color: #000000;\"><b>Inutilit\u00e9 de la commission d\u2019enqu\u00eate<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">O\u00f9 l\u2019on voit bien que cette commission d\u2019enqu\u00eate n\u2019aurait jamais d\u00fb \u00eatre mise en place, c\u2019est que, quoique l\u2019enqu\u00eate f\u00fbt boucl\u00e9e pratiquement d\u00e8s le soir du 11 septembre 2001 et tous les \u00e9vidents coupables d\u00fbment identifi\u00e9s, quoique les Jersey Girls et d\u2019autres membres des familles de victimes ont tout fait, comme on l\u2019a vu, pour en saboter le d\u00e9roulement, ces derniers ont eu lors de la parution de son rapport final en novembre 2004 les mots les plus durs et les plus injustes pour qualifier ses conclusions.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les Jersey Girls ont \u00e9videmment \u00e9t\u00e9 les premi\u00e8res \u00e0 monter au cr\u00e9neau. Voici ce qu\u2019en ont dit 3 d\u2019entre elles\u00a0: pour <u><a style=\"color: #000000;\" href=\"http:\/\/www.reopen911.info\/temoignages\/survivants-familles-de-victimes.html\" target=\"_blank\" rel=\"nofollow noopener\">Patty Casazza\u00a0<\/a><\/u>\u00a0:\u00a0\u00bb<b> <\/b><i>C\u2019est dur pour nous d\u2019arriver \u00e0 la conclusion que la Commission du 11\/9 \u00e9tait, d\u2019entr\u00e9e de jeu, une tentative politique d\u2019\u00e9touffer l\u2019affaire.<\/i>\u00a0\u00bb\u00a0; pour <u><a style=\"color: #000000;\" href=\"http:\/\/www.reopen911.info\/temoignages\/survivants-familles-de-victimes.html\" target=\"_blank\" rel=\"nofollow noopener\">Lorie Van Auken<\/a><\/u>\u00a0: <i>\u00ab\u00a0Si vous cachez de l\u2019information, si vous maintenez portes closes partout, les gens deviennent suspicieux. Si le gouvernement prenait la peine de nous r\u00e9pondre, \u00e7a nous encouragerait. Au lieu de \u00e7a, le gouvernement ne r\u00e9pond quasiment \u00e0 rien. C\u2019est scandaleux que six ans plus tard, apr\u00e8s deux guerres pr\u00e9ventives au Moyen-Orient et peut-\u00eatre une troisi\u00e8me \u00e0 venir, nous n\u2019ayons toujours pas une explication compl\u00e8te sur le 11 septembre.\u00a0\u00bb\u00a0<\/i>\u00a0; pour <u><a style=\"color: #000000;\" href=\"http:\/\/911citizenswatch.org\/modules.php?op=modload&amp;name=News&amp;file=article&amp;sid=913&amp;mode=thread&amp;order=0&amp;thold=0\" target=\"_blank\" rel=\"nofollow noopener\">Mindy Kleinberg<\/a><\/u>\u00a0: \u00ab\u00a0<i>Nous nous sommes battues pour obtenir la cr\u00e9ation d\u2019une Commission ind\u00e9pendante sur le 11\/9 parce que nous croyions que les citoyens am\u00e9ricains seraient mieux servis par une nation qui reconna\u00eet ses faiblesses et qui les corrige.<\/i>\u00a0\u00bb \u00ab\u00a0<i>La Commission du 11\/9 a failli \u00e0 ses devoirs. Ce que nous attendions d\u2019elle, c\u2019\u00e9tait une investigation minutieuse sur les \u00e9v\u00e9nements du 11\/9. Il est inexcusable que cinq ans apr\u00e8s, nous attendions encore.\u00a0\u00bb<\/i><\/span><\/p>\n<p><span style=\"color: #000000;\">Les Jersey Girls ayant donn\u00e9 le \u00ab\u00a0la\u00a0\u00bb, d\u2019autres membres de ces familles qui avaient refus\u00e9 les indemnit\u00e9s g\u00e9n\u00e9reuses du fonds de compensation en ont profit\u00e9 pour se l\u00e2cher semblablement. J\u2019en cite 3 qui ne sont qu\u2019un \u00e9chantillon.<\/span><\/p>\n<p><span style=\"color: #000000;\">Pour <u><a style=\"color: #000000;\" href=\"http:\/\/www.cbc.ca\/sunday\/911mcilvaine.html\" target=\"_blank\" rel=\"nofollow noopener\">Bob Mcilvaine<\/a><\/u>, dont le fils est mort dans la tour nord, \u00ab\u00a0<i>Je crois \u00e0 100% que les \u00c9tats-Unis ont orchestr\u00e9 les \u00e9v\u00e9nements du 11 septembre avec l\u2019aide d\u2019autres services de renseignements dans le monde. Mais je bl\u00e2me particuli\u00e8rement les USA parce que c\u2019est arriv\u00e9 chez nous. Il y a des gens aux USA qui savaient ce qui se passaient, qui ont planifi\u00e9 \u00e7a&#8230;<\/i>\u00a0\u00bb Pour <u><a style=\"color: #000000;\" href=\"http:\/\/www.arcticbeacon.com\/articles\/6-Aug-2005.html\" target=\"_blank\" rel=\"nofollow noopener\">Bill Doyle<\/a><\/u>, qui perdu son fils dans la tour nord, \u00ab\u00a0<i>Le rapport de la Commission du 11\/9 n&rsquo;est m\u00eame pas une \u00e9bauche conduisant \u00e0 la v\u00e9rit\u00e9.<\/i>\u00a0\u00bb \u00ab\u00a0<i>La Commission du 11\/9 est probablement la pire <\/i><i>repr\u00e9sentation des familles du 11\/9 ou d&rsquo;ailleurs tout le public am\u00e9ricain parce que c&rsquo;est un simulacre. Elle l&rsquo;est vraiment. Nous avions des tonnes de questions diff\u00e9rentes que nous leur avions demand\u00e9 de poser. Ils ne voulaient pas le faire. Et la continuation des tentatives faites pour \u00e9touffer l&rsquo;affaire est tout bonnement <\/i><i>incroyable.<\/i>\u00a0\u00bb Pour <u><a style=\"color: #000000;\" href=\"http:\/\/youtube.com\/watch?v=yZlNNo-w4EU\" target=\"_blank\" rel=\"nofollow noopener\">Donna Marsch O&rsquo;Connor<\/a><\/u><b>,<\/b> qui a perdu sa fille dans la tour sud, \u00ab\u00a0<i>Ce gouvernement a fait de moi la victime d\u2019une <\/i><i>th\u00e9orie du complot parce qu\u2019il n\u2019a pas r\u00e9pondu pleinement, et n\u2019a pas permis qu\u2019on soul\u00e8ve les vraies <\/i><i>questions sur le 11 septembre.<\/i>\u00ab\u00a0<a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-les-familles-de-victimes-140846#sdendnote2sym\" rel=\"nofollow\" name=\"sdendnote2anc\"><sup>ii<\/sup><\/a><\/span><\/p>\n<p><span style=\"color: #000000;\">Dans le premier chapitre de cette \u00e9tude, j\u2019ai r\u00e9sum\u00e9 ainsi le rapport de la commission d\u2019enqu\u00eate\u00a0: \u00ab\u00a0<i>en plus de faire la lumi\u00e8re d\u00e9finitive sur les attentats du 11 septembre 2001, c\u2019est un texte extr\u00eamement bien \u00e9crit, dans lequel on rentre comme dans du beurre et qui ne se referme qu\u2019apr\u00e8s avoir atteint le point final.\u00a0<\/i>\u00a0\u00bb Maintenant, si je mets de c\u00f4t\u00e9 sa qualit\u00e9 litt\u00e9raire, que pas un des proches des victimes ne s\u2019est risqu\u00e9 \u00e0 nier, un tel travail ne peut \u00e9videmment pas \u00eatre parfait. Quand on brasse autant de mati\u00e8re il est fatal que l\u2019on erre sur quelques points et que l\u2019on s&rsquo;\u00e9loigne de la perfection. Comme dit le po\u00e8te latin Horace, dans son <u><a style=\"color: #000000;\" href=\"http:\/\/bcs.fltr.ucl.ac.be\/HOR\/PisonsTrad.html\" target=\"_blank\" rel=\"nofollow noopener\">Art Po\u00e9tique<\/a><\/u>, \u00e9voquant certains passages un peu faibles de <i>l\u2019Odyss\u00e9e\u00a0<\/i>\u00a0: \u00ab\u00a0<i>je suis furieux quand il arrive au bon Hom\u00e8re de sommeiller, sans songer que, dans un long po\u00e8me, il est permis de se laisser un peu aller au sommeil.\u00a0<\/i>\u00a0\u00bb Ces proches des victimes qui ont refus\u00e9 de g\u00e9n\u00e9reuses indemnit\u00e9s compensatoires, pour obliger l\u2019administration Bush \u00e0 mettre en place une commission d\u2019enqu\u00eate s\u2019\u00e9taient lanc\u00e9s dans l\u2019aventure avec l\u2019id\u00e9e folle et pr\u00e9con\u00e7ue d\u2019y trouver d\u2019innombrables preuves d\u2019omissions et de manipulations. C\u2019est pourquoi ils ont c\u00e9d\u00e9 \u00e0 la pente fatale de voir derri\u00e8re chaque indice de <i>sommeil<\/i> la marque de l\u2019impensable, \u00e0 savoir que des officiels \u00e9tasuniens \u00e9taient bel et bien mouill\u00e9s dans la mise en \u0153uvre des attentats du 11 septembre 2001, et devaient \u00eatre ch\u00e2ti\u00e9s en cons\u00e9quence.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cela nous ram\u00e8ne au ph\u00e9nom\u00e8ne de <i>dissonance cognitive <\/i> que j\u2019ai \u00e9voqu\u00e9 dans <u><a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/page\/7\/\" target=\"_blank\" rel=\"noopener\">l\u2019Introduction G\u00e9n\u00e9rale<\/a>\u00a0:<\/u> alors qu\u2019\u00e0 l\u2019\u00e9vidence le rapport de la commission d\u2019enqu\u00eate apportait, quoi qu\u2019elles disent, l&rsquo;essentiel des r\u00e9ponses \u00e0 leurs questions, elles n\u2019ont eu d\u2019autre choix, tant elles avaient \u00e9t\u00e9 plong\u00e9es pendant des mois dans le doute et les sentiments n\u00e9gatifs, de rejeter en bloc l\u2019ensemble des conclusions pourtant convaincantes du rapport. A ce seul prix leurs cervelles devenues incurablement malades purent passer outre l\u2019\u00e9vidence \u00e0 laquelle elle \u00e9taient confront\u00e9es, et les maintenir dans leur nouvelle structure mentale devenue habituelle.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cela explique largement selon moi, le ton unanimement agressif et empreint de m\u00e9chancet\u00e9 de la part de ces 70 familles de victimes ren\u00e9gates \u00e0 l\u2019\u00e9gard de l\u2019establishment \u00e9tasunien et le travail de la commission d\u2019enqu\u00eate.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ce_que_sont_devenues_les_Jersey_Girls\"><\/span><span style=\"color: #000000;\"><b>Ce que sont devenues les Jersey Girls<\/b><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Il n\u2019est que de voir ce que les Jersey Girls sont <i>devenues <\/i>par la suite pour s\u2019assurer de la pertinence de mon accusation. Un <u><a style=\"color: #000000;\" href=\"http:\/\/blog.nj.com\/njv_bob_braun\/2012\/09\/braun_sept_11_jersey_girls_mos.html\" target=\"_blank\" rel=\"nofollow noopener\">article de Bob Braun<\/a><\/u> du 9 septembre 2012 expose leur \u00e9volution tragique quoique pr\u00e9visible. Trait commun, aucune d\u2019elles ne s\u2019est jusqu\u2019\u00e0 pr\u00e9sent remari\u00e9e, enferm\u00e9es qu\u2019elles sont chacune dans une tranche de vie pass\u00e9e dont elles sont incapables de s\u2019extraire. Plus particuli\u00e8rement, si Mindy Kleinberg et Patricia Casazza ont l\u2019air de s\u2019en \u00eatre \u00e0 peu pr\u00e8s sorties en se recentrant sur l\u2019\u00e9ducation de leurs enfants, les autres veuves du \u00ab\u00a0club des 4\u00a0\u00bb n\u2019ont pas tr\u00e8s bien tourn\u00e9\u2026 Kristen Breitweiser s\u2019est mise en t\u00eate d\u2019\u00e9crire <u><a style=\"color: #000000;\" href=\"http:\/\/www.freerepublic.com\/focus\/news\/1655394\/posts\" target=\"_blank\" rel=\"nofollow noopener\">un livre<\/a><\/u> relatant son exp\u00e9rience de veuve du 11 septembre\u00a0; elle \u00e9crit r\u00e9guli\u00e8rement sur <u><a style=\"color: #000000;\" href=\"http:\/\/www.huffingtonpost.com\/kristen-breitweiser\/\" target=\"_blank\" rel=\"nofollow noopener\">son blog<\/a><\/u> des articles conspirationnistes dans lesquels elle n\u2019h\u00e9site pas \u00e0 pr\u00e9tendre que Barack Obama est un clone de George W. Bush, et pousse le culot jusqu\u2019\u00e0 demander au pr\u00e9sident actuel de rendre le prix Nobel de la paix qui lui avait \u00e9t\u00e9 d\u00e9cern\u00e9 la premi\u00e8re ann\u00e9e de son mandat en 2009, en r\u00e9compense des promesses qu\u2019il incarnait lors de sa nomination. Lorie Van Auken a \u00e9t\u00e9 encore plus atteinte par la pand\u00e9mie conspirationniste puisqu\u2019elle est pass\u00e9e de la critique de la version officielle du 11 septembre, \u00e0 la d\u00e9nonciation d\u2019autres sujets \u00ab\u00a0douteux\u00a0\u00bb, comme la fracturation hydraulique pour l\u2019extraction du gaz de schiste. Je f\u00e9licite au passage notre Ministre du Redressement Productif, Arnaud Montebourg, <u><a style=\"color: #000000;\" href=\"http:\/\/www.lemonde.fr\/planete\/article\/2013\/07\/15\/montebourg-un-opposant-farouche-re-devenu-partisan-des-gaz-de-schiste_3447925_3244.html\" target=\"_blank\" rel=\"nofollow noopener\">pour son lobbying intense<\/a><\/u> en faveur de l\u2019exploitation de cette source d\u2019\u00e9nergie r\u00e9volutionnaire qui n\u2019aura aucun impact n\u00e9gatif sur l\u2019environnement, quoi qu\u2019en disent les ayatollahs de l\u2019\u00e9cologie de gauche comme de droite. Van Auken est \u00e9galement mobilis\u00e9e contre la culture des OGM, alors que chacun sait que <a style=\"color: #000000;\" href=\"http:\/\/www.agriculture-environnement.fr\/revue-de-livre,3\/jean-claude-jaillette-sauvez-les-ogm,549.html\" target=\"_blank\" rel=\"nofollow noopener\">sans des firmes comme Monsanto<\/a>, leader mondial dans ce domaine, l&rsquo;esp\u00e8ce humaine risque \u00e0 terme de mourir de faim.<\/span><\/p>\n<p><span style=\"color: #000000;\">L\u2019histoire des Jersey Girls est un cas d\u2019\u00e9cole pour comprendre le mode d\u2019action du virus conspirationniste. C\u2019est dans les esprits affaiblis ou foudroy\u00e9s par une violente \u00e9motion, en l\u2019occurrence le d\u00e9c\u00e8s brutal d\u2019un proche dans des circonstances dramatiques et aux r\u00e9percussions g\u00e9opolitiques inimaginables, qu\u2019il p\u00e9n\u00e8tre avec le plus de facilit\u00e9\u00a0; une fois dans la place, il se multiplie \u00e0 toute vitesse entra\u00eenant l\u2019irruption de pens\u00e9es et questions obs\u00e9dantes qui avec le temps entra\u00eenent le d\u00e9veloppement de comportements qui confinent \u00e0 l\u2019autisme. Quand c\u2019est de l\u2019esprit de personnes oisives qu\u2019il prend possession, en l\u2019occurrence de femmes au foyer, il se r\u00e9pand \u00e0 une vitesse encore plus grande. Toutes les heures que les Jersey Girls auraient pu passer dans des t\u00e2ches plus terre-\u00e0-terre et apaisantes pour leurs esprits \u00e9corch\u00e9s, elles les ont pass\u00e9es sur internet \u00e0 visionner des documentaires de propagande, \u00e0 tenter de d\u00e9cortiquer des rapports trop compliqu\u00e9s pour elles, ou \u00e8 organiser des pique-nique avec des fr\u00e8res et s\u0153urs de mis\u00e8re infect\u00e9s comme elles. Puis, les ann\u00e9es passant, et les attentats du 11 septembre tendant \u00e0 s\u2019enfoncer dans les brumes de l\u2019histoire, le virus mute, prenant diverses formes tout aussi pernicieuses et virulentes. Partis de la contestation de la version officielle de ces \u00e9v\u00e9nements, tous ces gens sont par la suite pass\u00e9s au gaz de schiste, aux OGM, et d\u2019autres sujets pris\u00e9s par les conspirationnistes qu\u2019il est ais\u00e9 de deviner, comme le virus H1N1, le trucage des \u00e9lections pr\u00e9sidentielles, les pyramides bosniaques, le projet HAARP, les chemtrails, les hommes l\u00e9zards, la remise en cause de l\u2019existence des chambres \u00e0 gaz, le Nouvel Ordre Mondial, et j\u2019en passe et des meilleures.<\/span><\/p>\n<p><span style=\"color: #000000;\">L&rsquo;univers conspirationniste est un manoir aux mille pi\u00e8ces dont la plupart sont inapparentes mais dont la plus rayonnante, celle du 11 septembre 2001, r\u00e9v\u00e8le \u00e0 la longue toutes les autres si on commet l&rsquo;erreur fatale d&rsquo;y p\u00e9n\u00e9trer sans pr\u00e9caution ni exp\u00e9rience, et ceux qui y font un trop long s\u00e9jour finissent par formuler cette folle pens\u00e9e\u00a0: \u00ab\u00a0<i>Il faut avoir compris le 11 septembre pour comprendre le monde dans lequel on vit.<\/i>\u00ab\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Donald Forestier<\/span><\/p>\n<p><span style=\"color: #000000;\"><em>co-\u00e9crit avec Charles Aissani, sous le pseudonyme de Donald Forestier, publi\u00e9 sur le site <a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-les-sauveteurs-du-11-09-102031\" target=\"_blank\" rel=\"noopener\">Agoravox<\/a> le\u00a0 13 septembre 2013. Le d\u00e9calage de parution d&rsquo;un an s&rsquo;explique par le retard irrattrapable pris \u00e0 l&rsquo;automne 2010 dans la r\u00e9daction de l&rsquo;ensemble des articles. Seules se trouvent dans cette situation les parties 7\/12 et 8\/12.<\/em><\/span><\/p>\n<p><strong>Notes<\/strong><\/p>\n<div id=\"sdendnote1\">\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-les-familles-de-victimes-140846#sdendnote1anc\" rel=\"nofollow\" name=\"sdendnote1sym\">i<\/a>J&rsquo;ai \u00e9voqu\u00e9 ce personnage dans le <a href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/10\/15\/jaccuse-6-12-richard-gage-et-sibel-edmonds\/\" target=\"_blank\" rel=\"noopener\">chapitre 4<\/a>, o\u00f9 je d\u00e9taille le r\u00f4le cl\u00e9 qui a \u00e9t\u00e9 le sien dans la r\u00e9solution de l&rsquo;affaire Sibel Edmonds.<\/span><\/p>\n<\/div>\n<div id=\"sdendnote2\">\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-les-familles-de-victimes-140846#sdendnote2anc\" rel=\"nofollow\" name=\"sdendnote2sym\">ii<\/a>Je remercie l&rsquo;association reopen911 qui a traduit et mis en ligne le dossier complet des t\u00e9moignages traduits de proches de victimes et autres \u00ab\u00a0sp\u00e9cialistes\u00a0\u00bb. Si je ne partage pas leurs conclusions je leur fais tout \u00e0 fait confiance pour des t\u00e2ches m\u00e9caniques de ce type.<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cette p\u00e9riode d&rsquo;anniversaire des attentats du 11 septembre 2001,\u00a0 je publie un morceau manquant de mon accusation de la pand\u00e9mie conspirationniste, consacr\u00e9 au comportement scandaleux de certaines familles de victimes. Nota Bene : Donald Forestier est un auteur fictif invent\u00e9 pour imiter le style des ap\u00f4tres de la version officielle des attentats du 11 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":78,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[13,19,37,8],"class_list":["post-75","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-donald-forestier","tag-11-septembre-2001","tag-commission-denquete","tag-familles-des-victimes","tag-theories-du-complot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001 - Fran\u00e7ois Belliot<\/title>\n<meta name=\"description\" content=\"Sans l\u2019acharnement de certaines familles de victimes, jamais une commission d\u2019enqu\u00eate sur les attentats du 11 septembre n\u2019aurait \u00e9t\u00e9 mise en place.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001 - Fran\u00e7ois Belliot\" \/>\n<meta property=\"og:description\" content=\"Sans l\u2019acharnement de certaines familles de victimes, jamais une commission d\u2019enqu\u00eate sur les attentats du 11 septembre n\u2019aurait \u00e9t\u00e9 mise en place.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/\" \/>\n<meta property=\"og:site_name\" content=\"Fran\u00e7ois Belliot\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-13T17:57:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-13T13:58:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"618\" \/>\n\t<meta property=\"og:image:height\" content=\"328\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francoisbelliot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"francoisbelliot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"33 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/\",\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/\",\"name\":\"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001 - Fran\u00e7ois Belliot\",\"isPartOf\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg\",\"datePublished\":\"2013-09-13T17:57:50+00:00\",\"dateModified\":\"2018-08-13T13:58:50+00:00\",\"author\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\"},\"description\":\"Sans l\u2019acharnement de certaines familles de victimes, jamais une commission d\u2019enqu\u00eate sur les attentats du 11 septembre n\u2019aurait \u00e9t\u00e9 mise en place.\",\"breadcrumb\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#primaryimage\",\"url\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg\",\"contentUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg\",\"width\":618,\"height\":328,\"caption\":\"les quatre \\\"Jersey Girls\\\" \u00e0 l'origine de l'ouverture d'ue Commission d'enqu\u00eate aux USA sur les attentats du 11 septembre 2001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/francoisbelliot.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/francoisbelliot.fr\/#website\",\"url\":\"https:\/\/francoisbelliot.fr\/\",\"name\":\"Fran\u00e7ois Belliot\",\"description\":\"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/francoisbelliot.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\",\"name\":\"francoisbelliot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"caption\":\"francoisbelliot\"},\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001 - Fran\u00e7ois Belliot","description":"Sans l\u2019acharnement de certaines familles de victimes, jamais une commission d\u2019enqu\u00eate sur les attentats du 11 septembre n\u2019aurait \u00e9t\u00e9 mise en place.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/","og_locale":"fr_FR","og_type":"article","og_title":"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001 - Fran\u00e7ois Belliot","og_description":"Sans l\u2019acharnement de certaines familles de victimes, jamais une commission d\u2019enqu\u00eate sur les attentats du 11 septembre n\u2019aurait \u00e9t\u00e9 mise en place.","og_url":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/","og_site_name":"Fran\u00e7ois Belliot","article_published_time":"2013-09-13T17:57:50+00:00","article_modified_time":"2018-08-13T13:58:50+00:00","og_image":[{"width":618,"height":328,"url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg","type":"image\/jpeg"}],"author":"francoisbelliot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"francoisbelliot","Dur\u00e9e de lecture estim\u00e9e":"33 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/","url":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/","name":"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001 - Fran\u00e7ois Belliot","isPartOf":{"@id":"https:\/\/francoisbelliot.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#primaryimage"},"image":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#primaryimage"},"thumbnailUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg","datePublished":"2013-09-13T17:57:50+00:00","dateModified":"2018-08-13T13:58:50+00:00","author":{"@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9"},"description":"Sans l\u2019acharnement de certaines familles de victimes, jamais une commission d\u2019enqu\u00eate sur les attentats du 11 septembre n\u2019aurait \u00e9t\u00e9 mise en place.","breadcrumb":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#primaryimage","url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg","contentUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2018\/07\/familles911.jpg","width":618,"height":328,"caption":"les quatre \"Jersey Girls\" \u00e0 l'origine de l'ouverture d'ue Commission d'enqu\u00eate aux USA sur les attentats du 11 septembre 2001"},{"@type":"BreadcrumbList","@id":"https:\/\/francoisbelliot.fr\/index.php\/2013\/09\/13\/jaccuse-8-12-les-familles-de-victimes-du-11-septembre-2001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francoisbelliot.fr\/"},{"@type":"ListItem","position":2,"name":"J\u2019accuse (8\/12) : les familles de victimes du 11 septembre 2001"}]},{"@type":"WebSite","@id":"https:\/\/francoisbelliot.fr\/#website","url":"https:\/\/francoisbelliot.fr\/","name":"Fran\u00e7ois Belliot","description":"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francoisbelliot.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9","name":"francoisbelliot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","caption":"francoisbelliot"},"url":"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/"}]}},"_links":{"self":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/comments?post=75"}],"version-history":[{"count":0,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/75\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media\/78"}],"wp:attachment":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media?parent=75"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/categories?post=75"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/tags?post=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}