{"id":71,"date":"2011-10-10T14:19:55","date_gmt":"2011-10-10T12:19:55","guid":{"rendered":"https:\/\/francoisbelliot.fr\/?p=71"},"modified":"2018-08-13T18:17:48","modified_gmt":"2018-08-13T16:17:48","slug":"jaccuse-7-12-les-sauveteurs-du-11-septembre","status":"publish","type":"post","link":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/","title":{"rendered":"J&rsquo;accuse (7\/12) : les pompiers du 11 septembre"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Il y a un an j&rsquo;ai publi\u00e9 sur ce site mon livre \u00ab J&rsquo;accuse la pand\u00e9mie conspirationniste \u00bb au rythme d&rsquo;un chapitre par semaine. Les lecteurs attentifs auront peut-\u00eatre remarqu\u00e9 qu&rsquo;il en manquait deux dans la seconde section : celui sur les pompiers et les familles de victime remettant en cause la version officielle, et celui \u00e9voquant les \u00e9tats d&rsquo;\u00e2mes des membres de la commission Kean Hamilton. Le premier chapitre se divisera en deux articles. Voici le premier traitant des pompiers.<\/strong><\/span><!--more--><\/p>\n<p><span style=\"color: #000000;\"><em>Nota Bene : Donald Forestier est un auteur fictif invent\u00e9 pour imiter le style des ap\u00f4tres de la version officielle des attentats du 11 septembre 2011 dans les grands m\u00e9dias<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Les attentats du 11 septembre 2001 sont de tr\u00e8s loin les attentats plus meurtriers de toute l&rsquo;histoire.\u00a0Au total ce sont pr\u00e8s de 2986 citoyens de 30 nationalit\u00e9s diff\u00e9rentes qui ont p\u00e9ri en cette journ\u00e9e funeste.<\/span><\/p>\n<p><span style=\"color: #000000;\">On n&rsquo;a retrouv\u00e9 que 293 corps complets\u00a0; plus de 1500 personnes ont pu \u00eatre identifi\u00e9es \u00e0 partir de 20 000 fragments de bouts d&rsquo;os et de tissus, dont des centaines <a style=\"color: #000000;\" href=\"http:\/\/books.google.fr\/books?id=AFcqqr3KhlAC&amp;pg=PA52&amp;lpg=PA52&amp;dq=fragment+de+corps+deutsche+bank&amp;source=bl&amp;ots=Vh_dPFAEVB&amp;sig=U0ylzdS8UvSWBOC1HSestLL9FUQ&amp;hl=fr&amp;ei=kM6NTrf-KMqUswap2-H8Dw&amp;sa=X&amp;oi=book_result&amp;ct=result&amp;resnum=1&amp;ved=0CB8Q6AEwAA#v=onepage&amp;q=fragment%20de%20corps%20deutsche%20bank&amp;f=false\" target=\"_blank\" rel=\"noopener\">seront retrouv\u00e9s en 2006 <\/a>sur le toit de la\u00a0tour de la Deutsche Bank situ\u00e9e \u00e0 un jet de pierre de la tour sud. 1151 personnes ont disparu sans laisser la moindre trace.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ces chiffres impressionnants t\u00e9moignent \u00e0 la fois de l&rsquo;immensit\u00e9 du d\u00e9sastre, et de la violence inou\u00efe de l&rsquo;effondrement des tours. Je veux me joindre, avant de commencer ce chapitre, aux familles qui ont perdu des proches en cet \u00e9v\u00e9nement de basculement. Je m&rsquo;associe en pens\u00e9e \u00e0 leur douleur et \u00e0 leur deuil, et partage leurs pri\u00e8res quelle que soit leur confession religieuse. O\u00f9 que soient les victimes du 11 septembre, qu&rsquo;elles reposent en paix.<\/span><\/p>\n<p><span style=\"color: #000000;\">A pr\u00e9sent je me sens un peu mieux, plus serein. Aucun chapitre de cette \u00e9tude ne m&rsquo;a pos\u00e9 un cas de conscience plus aig\u00fc, et je tenais \u00e0 me mettre un peu en condition. Si certains ont \u00e9t\u00e9 choqu\u00e9s par tel ou tel des morceaux pr\u00e9c\u00e9dents, j&rsquo;ai peur, malheureusement, d&rsquo;\u00e9lever leur indignation \u00e0 un cran encore sup\u00e9rieur dans ce nouveau chapitre. Il peut en effet para\u00eetre scandaleux que je tienne \u00e0 faire le proc\u00e8s des associations de citoyens sans comp\u00e9tence particuli\u00e8re comme les familles de victimes et les pompiers demandant la r\u00e9ouverture d&rsquo;une enqu\u00eate sur les attentats du 11\/09. On ne parle pas, comme <a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/10\/15\/jaccuse-6-12-richard-gage-et-sibel-edmonds\/\" target=\"_blank\" rel=\"noopener\">au chapitre pr\u00e9c\u00e9dent<\/a>, de sp\u00e9cialistes, comme Richard Gage ou Sibel Edmonds, qui ont v\u00e9cu les \u00e9v\u00e9nements de loin et ne sont entr\u00e9s dans la ronde conspirationniste que des ann\u00e9es plus tard, mais de ceux qui ont \u00e9t\u00e9 touch\u00e9s dans leur chair au plus profond d&rsquo;eux-m\u00eames. La pudeur aurait pu me retenir d&rsquo;en parler, mais comme nous avons l\u00e0 affaire, avec les deux associations de pompiers et de familles de victimes, aux deux fers de lance de la pand\u00e9mie les plus redoutables, j&rsquo;aurais p\u00e9ch\u00e9 par faiblesse, manque de <em>cran<\/em>, si j&rsquo;avais oubli\u00e9 de jeter avec les autres ces deux sacs poubelles dans la benne.<\/span><\/p>\n<p><span style=\"color: #000000;\">La morale de l&rsquo;histoire n&rsquo;est pas en effet celle que tout le monde conna\u00eet. Un deuil, aussi immense soit-il, ne doit pas servir de pr\u00e9texte \u00e0 des combats politiques honteux et hors de propos. C&rsquo;est bien de pleurer, \u00e7a soulage, mais c&rsquo;est mal de d\u00e9tourner ses larmes pour son profit personnel. Les larmes ne sont ni une monnaie d&rsquo;achat, ni un moyen de pression. Quand on sort du cimeti\u00e8re il faut retrouver ses esprits, et savoir rester digne, et discret.<\/span><\/p>\n<p><span style=\"color: #000000;\">Autant de principes que n&rsquo;ont pas respect\u00e9s les deux associations de secouristes et de familles de victimes, et dont je veux d\u00e9noncer les abus et errances dans ce chapitre.<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_71 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57cc8f9bb53\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57cc8f9bb53\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#Lassociation_des_secouristes_du_11_septembre\" title=\"L&rsquo;association des secouristes du 11 septembre\">L&rsquo;association des secouristes du 11 septembre<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#Les_temoignages_dexplosion\" title=\"Les t\u00e9moignages d&rsquo;explosion\">Les t\u00e9moignages d&rsquo;explosion<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#La_loi_James_Zadroga_et_la_polemique_des_pompiers_malades_du_11_septembre\" title=\"La loi James Zadroga et la pol\u00e9mique des pompiers malades du 11 septembre.\">La loi James Zadroga et la pol\u00e9mique des pompiers malades du 11 septembre.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#_Conclusion\" title=\"\u00a0Conclusion\">\u00a0Conclusion<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Lassociation_des_secouristes_du_11_septembre\"><\/span><span style=\"color: #000000;\"><strong>L&rsquo;association des secouristes du 11 septembre<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">J\u2019ai d\u00e9j\u00e0 eu l&rsquo;occasion d&rsquo;\u00e9voquer les pompiers du 11 septembre dans le <a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/10\/02\/jaccuse-5-12-leffondrement-de-la-tour-7\/\" target=\"_blank\" rel=\"noopener\">chapitre 3<\/a> sur la tour WTC7, le comportement douteux de certains d\u2019entre eux, leur refus d\u2019ob\u00e9ir aux ordres d\u2019\u00e9vacuation, leur comportement excessivement t\u00e9m\u00e9raire, \u00ab\u00a0\u00e0 la John Wayne\u00a0\u00bb, leur vanit\u00e9 d\u00e9mesur\u00e9e en raison de la pr\u00e9sence de cam\u00e9ras, leurs t\u00e9moignages la plupart du temps bancals\u2026 C&rsquo;est n\u00e9anmoins une belle \u00e9pine dans le pied de l&rsquo;establishment \u00e9tasunien, que <a style=\"color: #000000;\" href=\"http:\/\/firefightersfor911truth.org\/\" target=\"_blank\" rel=\"noopener\">l&rsquo;association des Fire Fighters for 9-11 truth<\/a> mont\u00e9e en ao\u00fbt 2008 par Erik Lawyer et demandant la r\u00e9ouverture d&rsquo;une enqu\u00eate. Certes les pompiers sont la corporation, qui, avec 343 soldats du feu engloutis en faisant leur devoir, a pay\u00e9 le plus lourd tribut humain dans ces \u00e9v\u00e9nements tragiques. L&rsquo;esprit de sacrifice dont ils ont fait montre ce jour-l\u00e0 suscite encore aujourd&rsquo;hui l&rsquo;admiration universelle. Pour avoir \u00e9t\u00e9 dans les tours, parfois jusqu&rsquo;au point d&rsquo;impact des avions, ce sont les t\u00e9moins les plus proches et les plus directs de ce qui se passait dans les tours entre l&rsquo;impact des avions et leur effondrement. Leur association par ailleurs ne regroupe pas une minorit\u00e9 des secouristes ayant particip\u00e9 au d\u00e9blaiement du site de Ground Zero, mais une majorit\u00e9 d&rsquo;entre eux.<\/span><\/p>\n<p><span style=\"color: #000000;\">Bref, non seulement les pompiers du 11 septembre disposent d&rsquo;un cr\u00e9dit de compassion consid\u00e9rable, mais en plus leur t\u00e9moignage a une port\u00e9e qu&rsquo;il est impossible d&rsquo;\u00e9luder.<\/span><\/p>\n<p><span style=\"color: #000000;\">Comme les architectes et ing\u00e9nieurs f\u00e9d\u00e9r\u00e9s autour de Richard Gage, les secouristes de <a style=\"color: #000000;\" href=\"http:\/\/firefightersfor911truth.org\/\" target=\"_blank\" rel=\"noopener\">l&rsquo;association des Fire Fighters for 9-11 truth<\/a>\u00a0pr\u00e9tendent que les trois tours n&rsquo;ont pas \u00e9t\u00e9 d\u00e9truites des suites de l&rsquo;impact des avions et des incendies, mais du fait d&rsquo;une d\u00e9molition contr\u00f4l\u00e9e. Leurs porte-parole participent souvent \u00e0 des conf\u00e9rences conjointes avec leurs coll\u00e8gues en col blanc.<\/span><\/p>\n<p><span style=\"color: #000000;\">Voil\u00e0 comment ils \u00e9talent leur doutes sur la p\u00e9tition qu&rsquo;ils ont mise en ligne sur leur site\u00a0: \u00ab\u00a0<em>Au nom du peuple des \u00c9tats-Unis, nous soussign\u00e9s pompiers pour la v\u00e9rit\u00e9 sur le 11 septembre et affili\u00e9s, sommes profond\u00e9ment troubl\u00e9s par la version \u00ab\u00a0officielle\u00a0\u00bb, et la fa\u00e7on dont les secouristes de Ground Zero ont \u00e9t\u00e9 oubli\u00e9s.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><em>\u00a0Nous pensons qu&rsquo;il existe des preuves accablantes d&rsquo;obstruction de la justice, de destruction d&rsquo;\u00e9l\u00e9ments de la sc\u00e8ne du crime, d\u00e9nonc\u00e9e par les commissionnaires eux-m\u00eames. Le s\u00e9nateur Cleland a d\u00e9missionn\u00e9 de la commission en d\u00e9clarant\u00a0: \u00ab\u00a0l&rsquo;enqu\u00eate est \u00e0 pr\u00e9sent compromise.<\/em>\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Un\u00a0peu plus loin ils posent l&rsquo;hypoth\u00e8se de l&rsquo;utilisation d&rsquo;\u00a0\u00ab\u00a0acc\u00e9l\u00e9rateurs exotiques\u00a0\u00bb pour expliquer l&rsquo;effondrement. Entendez\u00a0: des explosifs et de la nanothermite.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ils formulent pour finir une s\u00e9rie de demandes parmi lesquelles\u00a0: la r\u00e9ouverture d&rsquo;une enqu\u00eate ind\u00e9pendante sur les attentats du 11 septembre, l&rsquo;examen de l&rsquo;hypoth\u00e8se d&rsquo;une destruction des immeubles au moyens d&rsquo;\u00a0\u00ab\u00a0acc\u00e9l\u00e9rateurs exotiques\u00a0\u00bb, des poursuites judiciaires contre ceux qui dans l&rsquo;appareil d&rsquo;\u00e9tat auraient fait obstruction \u00e0 l&rsquo;investigation ou auraient contribu\u00e9 \u00e0 la destruction des preuves, enfin, l&rsquo;application de la <em>loi Zadroga<\/em>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cette loi, vot\u00e9e en d\u00e9cembre 2010 dans des circonstances que je d\u00e9taillerai plus loin, pr\u00e9voit l&rsquo;octroi, pour les secouristes ayant particip\u00e9 au d\u00e9blayage du site de Ground Zero, un fonds d&rsquo;indemnisation pour les maladies qu&rsquo;ils auraient contract\u00e9es lors de ces op\u00e9rations ingrates mais n\u00e9cessaires. Nous touchons l\u00e0 un point tr\u00e8s pol\u00e9mique de l&rsquo;affaire\u00a0: non seulement dans les pompiers nous avons la corporation qui a pay\u00e9 le plus lourd tribut humain dans l&rsquo;effondrement des tours, mais, \u00e0 l&rsquo;occasion des op\u00e9rations de d\u00e9blayage du site, nombre d&rsquo;entre eux auraient \u00e9t\u00e9 empoisonn\u00e9s par l&rsquo;air ambiant charg\u00e9 de poussi\u00e8re toxique. Beaucoup seraient en train de mourir \u00e0 petit feu du fait d&rsquo;une exposition prolong\u00e9e aux effluves toxiques \u00e9manant des d\u00e9combres de Ground Zero. L&rsquo;administration Bush serait coupable pour avoir garanti l&rsquo;innocuit\u00e9 du cocktail de poussi\u00e8re d\u00e8s les premiers jours, et frein\u00e9 des quatre fers pour accorder des indemnit\u00e9s aux pompiers malades ou mourants dont beaucoup seraient dans l&rsquo;incapacit\u00e9 de financer leur traitement.<\/span><\/p>\n<p><span style=\"color: #000000;\">J&rsquo;ai d\u00e9j\u00e0 d\u00e9bunqu\u00e9 les hypoth\u00e8ses de la nanothermite et de la d\u00e9molition contr\u00f4l\u00e9e dans les <a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/10\/02\/jaccuse-5-12-leffondrement-de-la-tour-7\/\" target=\"_blank\" rel=\"noopener\">chapitres 3<\/a> et <a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/10\/15\/jaccuse-6-12-richard-gage-et-sibel-edmonds\/\" target=\"_blank\" rel=\"noopener\">4<\/a>. Je ne m&rsquo;appesantirai donc pas sur ces \u00e9l\u00e9ments de controverse. Deux points maintenant me semblent d&rsquo;une urgence absolue \u00e0 traiter, en terme de debunking\u00a0: les t\u00e9moignages d&rsquo;explosions qui ont tant fait jaser dans les chaumi\u00e8res des truthers, et, surtout, les pr\u00e9tendues maladies professionnelles des secouristes du 11 septembre.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Les_temoignages_dexplosion\"><\/span><span style=\"color: #000000;\"><strong>Les t\u00e9moignages d&rsquo;explosion <\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Il existe de nombreux enregistrements de t\u00e9moignages audio ou vid\u00e9o faisant \u00e9tat d&rsquo;explosions dans les tours avant leur effondrement. Ces t\u00e9moignages, au nombre d&rsquo;une grosse centaine, \u00e9manent de pompiers, de journalistes, ou de citoyens qui se trouvaient l\u00e0 par hasard.<\/span><\/p>\n<p><span style=\"color: #000000;\">Je commencerai par r\u00e9p\u00e9ter (ce que doit commencer faire tout bon journaliste qui veut se faire une id\u00e9e d\u00e9finitive sur ces questions ardues) l&rsquo;argumentaire lucide auquel recourt le scientifique J\u00e9r\u00f4me Quirant dans un courriel au conspirationniste Charmord <a style=\"color: #000000;\" href=\"http:\/\/forum.reopen911.info\/viewtopic.php?id=11969&amp;p=1\" target=\"_blank\" rel=\"noopener\">publi\u00e9 sur le forum de reopen911<\/a>\u00a0: \u00ab\u00a0<em>Les t\u00e9moignages humains ne sont pas des preuves surtout dans ces conditions de catastrophes. La premi\u00e8re d\u00e9marche du scientifique est JUSTEMENT DE LES \u00c9CARTER\u2026 On conna\u00eet tous l\u2019histoire de l\u2019homme qui a vu l\u2019homme qui a vu l\u2019ours\u2026\u00a0Les l\u00e9gendes entourant la journ\u00e9e du 11 septembre sont largement au-dessus de toute rationalit\u00e9\u2026 Pour ce qui est des bruits de d\u00e9molition contr\u00f4l\u00e9e, il faudrait organiser un p\u00e8lerinage pour ceux qui croient \u00e0 cela pour voir quel est le bruit que cr\u00e9ent ces explosions.<\/em>\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Je me joins absolument \u00e0 cette analyse qui suffit \u00e0 expliquer un ensemble de questions litigieuses soulev\u00e9es par les truthers\u00a0:\u00a0<em>comment se fait-il que pendant 5 ans l&rsquo;administration de Michael Bloomberg, le maire de New York, ait refus\u00e9 cat\u00e9goriquement de rendre publics les t\u00e9moignages d&rsquo;explosions\u00a0? Comment se fait-il, mieux, qu&rsquo;elle ait refus\u00e9 de communiquer ces enregistrements aux membres de la commission d&rsquo;enqu\u00eate Kean Hamilton, puis aux enqu\u00eateurs du NIST qui avaient \u00e9t\u00e9 mandat\u00e9s pour expliquer les effondrements des trois tours\u00a0?<\/em> Ces centaines de t\u00e9moignages ne valant gu\u00e8re mieux, pour d\u00e9tourner une expression heureuse de M Quirant, \u00ab\u00a0<em>que ceux faisant \u00e9tat d&rsquo;une sardine bouchant le port de Marseille\u00a0<\/em>\u00a0\u00bb, il est facile de comprendre que c&rsquo;est par professionnalisme, et souci d&rsquo;\u00e9pargner aux commissionnaires de longues et inutiles tergiversations, qu&rsquo;ils ont maintenu si longtemps secrets ces enregistrements. Le Fire Comissioner Nicholas Scoppetta invoque deux autres arguments \u00e0 l&rsquo;appui de cette th\u00e8se\u00a0: un que, Zacarias Moussaoui ayant pu disposer de ces enregistrements pour la pr\u00e9paration de son proc\u00e8s, ce proc\u00e8s aurait \u00e9t\u00e9 annul\u00e9 s&rsquo;ils avaient \u00e9t\u00e9 rendus publics\u00a0; deux que leur d\u00e9voilement constituerait une violation de la dignit\u00e9 de ces h\u00e9ros tomb\u00e9s au champ d&rsquo;honneur, et plongerait de nouveau dans la d\u00e9tresse leurs proches \u00e9plor\u00e9s. A vrai dire, pour \u00eatre honn\u00eate, m\u00eame apr\u00e8s avoir creus\u00e9 je ne comprends pas trop le premier argument, mais le second, en plus d&rsquo;\u00eatre parfaitement convaincant,\u00a0montre avec \u00e9clat les profondes qualit\u00e9s humaines de quelqu&rsquo;un comme M Bloomberg.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ces explications n&rsquo;ont malheureusement pas suffi. Menac\u00e9e de proc\u00e8s par certaines familles de victimes, <a style=\"color: #000000;\" href=\"http:\/\/www.nytimes.com\/2005\/08\/13\/nyregion\/nyregionspecial3\/13records.html\" target=\"_blank\" rel=\"noopener\">la ville de New York a \u00e9t\u00e9 finalement contrainte de d\u00e9voiler certains enregistrements en 2005<\/a>. Je ne surprendrai pas mon lecteur en lui r\u00e9v\u00e9lant que ces t\u00e9moignages n&rsquo;apportent aucun grain \u00e0 moudre aux truthers, rien de plus en tous cas que ceux d\u00e9j\u00e0 r\u00e9v\u00e9l\u00e9s par le Times par des canaux non officiels. Enfin s&rsquo;il veut s&rsquo;en faire une id\u00e9e par lui-m\u00eame, en voici trois, extrait d&rsquo;un dossier conspirationniste intitul\u00e9 \u00ab\u00a0<a style=\"color: #000000;\" href=\"http:\/\/www.darksideofgravity.com\/Collapse.pdf\" target=\"_blank\" rel=\"noopener\">Collapse\u00a0<\/a><strong>\u00a0\u00bb.<\/strong> Un dit\u00a0: \u00ab\u00a0<em>Alors que nous regardions le b\u00e2timent, ce que j&rsquo;ai vu, c&rsquo;\u00e9tait comme si les 4 c\u00f4t\u00e9s du b\u00e2timent explosaient. Nous avons r\u00e9ellement entendu les \u00ab\u00a0pops\u00a0\u00bb, dans les b\u00e2timents.\u00a0\u00bb <\/em>Un autre\u00a0: \u00ab\u00a0<em>J&rsquo;ai pens\u00e9 que les terroristes avaient install\u00e9 des explosifs quelque part dans le b\u00e2timent. C&rsquo;\u00e9tait aussi fort que \u00e7\u00e0, des claquements d&rsquo;explosifs.\u00a0\u00bb <\/em>Un autre\u00a0: \u00ab\u00a0<em>Soudain il y a eu un autre boom sonore aux \u00e9tages sup\u00e9rieurs, et il y a eu une s\u00e9rie de petites explosions qui semblaient faire le tour du b\u00e2timent, aux \u00e9tages sup\u00e9rieurs. Et un autre souffle venant du sol, avec une grosse boule de feu qui crachait beaucoup de d\u00e9bris.\u00a0<\/em>\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Certes, on doit faire confiance aux pompiers qui sont habitu\u00e9s \u00e0 p\u00e9n\u00e9trer dans toutes sortes de brasiers, qui savent faire la diff\u00e9rence entre une explosion et une vitre qui p\u00e8te, et sur les 118 t\u00e9moignages d\u00e9classifi\u00e9s la plupart semblent aller dans le m\u00eame sens. Mais il faut avoir bien en t\u00eate le caract\u00e8re exceptionnel de la situation. Jamais les pompiers ne s&rsquo;\u00e9taient retrouv\u00e9s sur un terrain de jeu aussi immense, il y avait toutes ces cam\u00e9ras et tous ces appareils photos&#8230; Il me semble donc \u00e9vident que les pompiers ont \u00e9t\u00e9 victimes d&rsquo;une hallucination collective, <a style=\"color: #000000;\" href=\"http:\/\/synchronicite.blog4ever.com\/blog\/lire-article-119957-525307-les_travaux_du_grand_psychanalyste_carl_gustav_jun.html\" target=\"_blank\" rel=\"noopener\">du type de celles que C. G. Jung d\u00e9crit dans son livre sur les ovnis<\/a> pour expliquer les visions collectives de soucoupes ou de cigares volants. Remarquez au passage comment ils gesticulent sur certaines vid\u00e9os, en faisant de grands mouvements des bras, comme s&rsquo;ils voulaient mimer par des gestes ce qu&rsquo;ils seraient incapables de faire avec des phrases.<\/span><\/p>\n<p><span style=\"color: #000000;\">D&rsquo;autres faits encore plus incroyables\u00a0doivent nous amener \u00e0 reconna\u00eetre que les pompiers du 11 septembre n&rsquo;avaient d\u00e9cid\u00e9ment pas les yeux en face des trous\u00a0: on dispose <a style=\"color: #000000;\" href=\"http:\/\/web.archive.org\/web\/20090103142426\/http:\/www.firehouse.com\/terrorist\/wtcaudio\/wtcaudio9.html\">de l&rsquo;enregistrement audio du t\u00e9moignage de deux pompiers<\/a> au moment o\u00f9 ils atteignent le 78\u00e8me \u00e9tage de la tour nord. Que dit-il\u00a0? \u00ab\u00a0<em>Nous avons\u00a0deux foyers d&rsquo;incendie isol\u00e9s\u00a0; faites monter deux lances\u00a0: nous devrions \u00eatre capables de les r\u00e9duire avec deux lances<\/em>\u00a0\u00bb Les pauvres hommes seront emport\u00e9s dans l&rsquo;effondrement de la tour qui survient quelques minutes plus tard. Rendez-vous compte\u00a0! Alors que l&rsquo;incendie \u00e9tait forc\u00e9ment gigantesque (nous sommes quelques \u00e9tages en-dessous du point d&rsquo;impact), l&rsquo;homme pr\u00e9tend ni plus ni moins qu&rsquo;il est pratiquement \u00e9teint, et qu&rsquo;\u00e0 la limite quelques seaux d&rsquo;eau suffiraient \u00e0 l&rsquo;\u00e9teindre\u00a0! Ce fait est \u00e9videmment impossible au vu des conclusions sans appel du rapport de la commission Kean Hamilton et de ceux du NIST, qui \u00e9noncent que ce sont les incendies, et les incendies seuls qui ont entra\u00een\u00e9s l&rsquo;effondrement des trois tours. On est oblig\u00e9 de conclure que les deux hommes nageaient en plein d\u00e9lire, puisqu&rsquo;ils ne sentaient ni ne voyaient les flammes incandescentes qui forc\u00e9ment les environnaient de toutes part.<\/span><\/p>\n<p><span style=\"color: #000000;\">On doit \u00e9galement noter l&rsquo;utilisation abusive de chalumeaux oxy-ethyl\u00e8ne par les pompiers\u00a0: en effet on voit, <a style=\"color: #000000;\" href=\"http:\/\/www.luogocomune.net\/site\/modules\/911\/911\/5-WTC\/20domande\/240406tho.jpg\" target=\"_blank\" rel=\"noopener\">sur certains segments de poutres<\/a> jaillissant des ruines des tours jumelles, des traces nettes de d\u00e9coupage\u00a0r\u00e9alis\u00e9es \u00e0 l&rsquo;aide de cet instrument.<\/span><\/p>\n<p><span style=\"color: #000000;\">Lorsque certains truthers, pour expliquer l&rsquo;existence de plaques de m\u00e9tal en fusion dans les d\u00e9combres du site, invoquent l&rsquo;hypoth\u00e8se de la d\u00e9molition contr\u00f4l\u00e9e au moyen d&rsquo;acc\u00e9l\u00e9rateurs exotiques, J\u00e9r\u00f4me Quirant les rappelle \u00e0 la raison en expliquant que cela ne peut \u00eatre que la r\u00e9sultante de l&rsquo;utilisation de tels chalumeaux. Il en donne la raison\u00a0<a style=\"color: #000000;\" href=\"http:\/\/www.bastison.net\/APPROXIMATIONS\/approximations.html\" target=\"_blank\" rel=\"noopener\">sur son site de debunking bastison.net<\/a>\u00a0: certaines poutres pour \u00eatre \u00e9vacu\u00e9es plus facilement ont \u00e9t\u00e9 d\u00e9coup\u00e9es au chalumeau oxy-\u00e9thyl\u00e8ne, et quant aux concentrations de lave plus volumineuses all\u00e9gu\u00e9s par certains t\u00e9moignages, il s&rsquo;agit certainement (pas besoin d&rsquo;imaginer une autre hypoth\u00e8se) d&rsquo;aluminium dont la temp\u00e9rature de fusion est beaucoup plus basse que celle de l&rsquo;acier, et qui \u00e9tait\u00a0pr\u00e9sent en abondance dans le parement des tours. Maintenant, si c&rsquo;est cela l&rsquo;explication, alors nous sommes face \u00e0 une \u00e9nigme\u00a0: comment se fait-il que <a style=\"color: #000000;\" href=\"http:\/\/www.dailymotion.com\/video\/xee2g6_l-acier-fondu-par-le-feu-ou-bien-pa_news\" target=\"_blank\" rel=\"noopener\">sur certaines images<\/a> on\u00a0voit de la lave s&rsquo;\u00e9couler \u00e0 travers les fen\u00eatres, pr\u00e8s des points d&rsquo;impact\u00a0? A quoi cela peut-il bien correspondre\u00a0? Les incendies avaient transform\u00e9 les environs en fournaise, mais certainement pas au point de provoquer des \u00e9coulements de lave. Du reste on voit bien que la lave dans ce cas pr\u00e9cis ne provient pas du parement, qui demeure intact, mais <em>de l&rsquo;int\u00e9rieur de la tour<\/em>.<\/span><\/p>\n<p><span style=\"color: #000000;\">Je sais que l&rsquo;hypoth\u00e8se semblera \u00e0 certains tir\u00e9e par les cheveux, mais \u00e0 mon avis les suspicions doivent donc se tourner vers les seuls susceptibles de parvenir \u00e0 un tel r\u00e9sultat\u00a0: \u00e7a ne peut \u00eatre que certains pompiers de New York qui, au lieu d&rsquo;\u00e9teindre les nombreux foyers d&rsquo;incendie, ont eu la riche id\u00e9e de vouloir baptiser leurs \u00e9normes chalumeaux de comp\u00e9tition dont ils br\u00fblaient de se servir\u00a0! L&rsquo;identit\u00e9 des coupables demeurera malheureusement pour toujours un myst\u00e8re\u00a0: en effet l&rsquo;immeuble s&rsquo;effondre peu de temps apr\u00e8s que l&rsquo;on voit le filet de lave s&rsquo;\u00e9chapper de la fen\u00eatre. Mais la responsabilit\u00e9 des pompiers sur ce coup-l\u00e0 de fait pas l&rsquo;ombre d&rsquo;un doute.<\/span><\/p>\n<p><span style=\"color: #000000;\">Sous cet \u00e9clairage in\u00e9dit, je comprends tout \u00e0 fait que les enqu\u00eateurs du NIST aient d\u00e9cid\u00e9 de ne retenir <em>aucun <\/em>de ces t\u00e9moignages, de la m\u00eame fa\u00e7on qu&rsquo;ils ont d\u00e9lib\u00e9r\u00e9ment d\u00e9cid\u00e9 de ne r\u00e9aliser aucun pr\u00e9l\u00e8vement d&rsquo;\u00e9chantillon de la poussi\u00e8re des ruines&#8230; comme aucun explosif n&rsquo;a \u00e9t\u00e9 utilis\u00e9, il est inutile d&rsquo;en chercher des traces, et tous les t\u00e9moignages d&rsquo;explosion sont des faux ou ressortissent \u00e0 des hallucinations collectives.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"La_loi_James_Zadroga_et_la_polemique_des_pompiers_malades_du_11_septembre\"><\/span><span style=\"color: #000000;\"><strong>La loi James Zadroga et la pol\u00e9mique des pompiers malades du 11 septembre.<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Le vote de la loi James Zadroga en d\u00e9cembre 2010 fait de l&rsquo;affaire des secouristes canc\u00e9reux l&rsquo;aspect sans doute le plus <em>vivant<\/em> de la pol\u00e9mique qui s&rsquo;est d\u00e9velopp\u00e9e autour des attentats du 11 septembre. James Zadroga est un inspecteur de police qui a particip\u00e9 pendant 450 heures au d\u00e9blaiement des d\u00e9combres dans les semaines suivant l&rsquo;attentat. Au bout de deux mois, l&rsquo;homme commence \u00e0 ne pas se sentir tr\u00e8s bien\u00a0: il crache ses poumons, et est pris de vomissements. Tr\u00e8s inquiet, il se rend chez un m\u00e9decin qui lui diagnostique une silicose des poumons, malheureusement incurable. D&rsquo;ici 3 ans il sera aveugle, et dans 5 il mourra. Diagnostic correct puisque l&rsquo;homme d\u00e9c\u00e8de en 2006, \u00e0 l&rsquo;\u00e2ge tr\u00e8s vert de 34 ans. Persuad\u00e9e que ce d\u00e9c\u00e8s pr\u00e9matur\u00e9 est li\u00e9 au s\u00e9jour du secouriste sur le site, la famille fait proc\u00e9der \u00e0 une autopsie et m\u00e8ne une action pour requalifier ce d\u00e9c\u00e8s en maladie professionnelle directement li\u00e9e \u00e0 sa pr\u00e9sence prolong\u00e9e sur Ground Zero. Au terme de cette action, pour la premi\u00e8re fois, le d\u00e9c\u00e8s d&rsquo;un secouriste de Ground Zero est li\u00e9 \u00e0 sa pr\u00e9sence prolong\u00e9e sur le site. Cette action d\u00e9bouche sur le vote de la loi James Zadroga en d\u00e9cembre 2010, qui ouvre la possibilit\u00e9, dans l&rsquo;attente des r\u00e9sultats d&rsquo;une enqu\u00eate m\u00e9dicale men\u00e9e sur une vaste \u00e9chelle, de d\u00e9bloquer une enveloppe de 7,4 milliards de dollars pour les personnes comportant des s\u00e9quelles physiques d\u00e9coulant de leur implication directe dans les op\u00e9rations de d\u00e9blaiement sur le site de Ground Zero.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le cas de James Zadroga ne serait en effet pas isol\u00e9. Selon John Feal, secouriste qui a perdu un pied sur le site de Ground Zero et qui a cr\u00e9\u00e9 la <a style=\"color: #000000;\" href=\"http:\/\/www.fealgoodfoundation.com\/\" target=\"_blank\" rel=\"noopener\">Fondation Fealgood<\/a>, dont la mission est de \u00ab\u00a0f<em>aire prendre conscience et donner des \u00e9l\u00e9ments d&rsquo;informations au public sur les s\u00e9quelles catastrophiques dont souffrent les pompiers du 11 septembre<\/em>\u00a0\u00bb, 51 secouristes du 11 septembre seraient d\u00e9j\u00e0 morts des suites de cancers pr\u00e9matur\u00e9s, et uniquement des hommes jeunes n&rsquo;ayant pas d\u00e9pass\u00e9 40 ans. Certains documentaires de propagande r\u00e9cemment sortis semblent confirmer cette affreuse \u00e9ventualit\u00e9. L&rsquo;un d&rsquo;entre eux est particuli\u00e8rement saisissant. R\u00e9alis\u00e9 par deux de nos compatriotes, Xavier Deleu et Oriane Demeulin, <a style=\"color: #000000;\" href=\"http:\/\/www.dailymotion.com\/video\/xetmdd_docu-les-heros-sacrifies-du-11-sept_news\" target=\"_blank\" rel=\"noopener\">les h\u00e9ros sacrifi\u00e9s du 11 septembre<\/a> met en sc\u00e8ne un photographe pr\u00e9sent sur le site au moment des attentats, qui depuis a pris fait et cause pour les secouristes. L&rsquo;homme parcourt les \u00c9tats-Unis pour aller \u00e0 leur rencontre, les interviouver et les photographier. Deux cas sont particuli\u00e8rement impressionnants\u00a0: celui de Franck Silechia, ouvrier du b\u00e2timent qui a travaill\u00e9 10 mois sur le site. L&rsquo;homme marche avec difficult\u00e9, parle avec lenteur, et le regard tourn\u00e9 vers l&rsquo;int\u00e9rieur, comme s&rsquo;il n&rsquo;\u00e9tait d\u00e9j\u00e0 plus de ce monde\u00a0: \u00ab\u00a0<em>Avant je d\u00e9bordais d&rsquo;\u00e9nergie, j&rsquo;\u00e9tais fort comme un b\u0153uf. Maintenant c&rsquo;est termin\u00e9, je suis&#8230; je tombe en miettes, je me sens vide, je me sens inutile, pourquoi est-ce que j&rsquo;existe\u00a0? Mon traitement est cens\u00e9 m&rsquo;aider&#8230; je d\u00e9teste le fait que les gens oublient le 11 septembre. Moi je n&rsquo;oublierai jamais. Quant \u00e0 moi, quand je mange, quand je bois, quand je dors, du matin au soir je pense au 11 septembre. J&rsquo;ai sorti 47 personnes des d\u00e9combres, j&rsquo;y pense sans arr\u00eat. J&rsquo;ai des amis et des coll\u00e8gues qui souffrent des m\u00eames probl\u00e8mes que moi, et \u00e7a me ronge. On ne re\u00e7oit pratiquement aucune aide du gouvernement f\u00e9d\u00e9ral. L&rsquo;aide financi\u00e8re \u00e7a aussi \u00e7a me ronge&#8230; C&rsquo;est un cauchemar sans fin pour moi. 3000 personnes sont mortes ce jour-l\u00e0, et la liste continue de s&rsquo;allonger. J&rsquo;en ferai bient\u00f4t partie. C&rsquo;est juste une question de temps.\u00a0\u00bb <\/em>celui de John Mc Namara, pompier ayant \u0153uvr\u00e9 sur le site, aujourd&rsquo;hui d\u00e9c\u00e9d\u00e9\u00a0: \u00ab\u00a0<em>J&rsquo;aimerais que la ville reconnaisse&#8230; Ils nient encore que les cancers soient li\u00e9s au World Trade Center. Ils ont peur d&rsquo;admettre leur responsabilit\u00e9. Question d&rsquo;argent, j&rsquo;imagine\u00a0: ils ne veulent pas \u00eatre poursuivis. (\u2026) Sur le site je n&rsquo;ai pas trouv\u00e9 un seul ordinateur, un seul t\u00e9l\u00e9phone, une seule chaise, un seul bureau. Tout avait \u00e9t\u00e9 pulv\u00e9ris\u00e9, r\u00e9duit en poussi\u00e8re, \u00e0 n\u00e9ant. Quand on trouvait un fragment de corps, c&rsquo;\u00e9tait un jour faste. (\u2026) J&rsquo;ai commenc\u00e9 \u00e0 \u00eatre malade en juin 2006. J&rsquo;ai ressenti d&rsquo;affreuses douleurs abdominales, j&rsquo;ai \u00e9t\u00e9 voir mon m\u00e9decin. Il a remarqu\u00e9 des t\u00e2ches sur mon foie et il a pens\u00e9 au cancer du colon\u00a0; j&rsquo;ai donc pass\u00e9 une coloscopie. La tumeur \u00e9tait si grosse que le coloscope ne pouvait pas passer. Elle bouchait presque tout. Le m\u00e9decin a dit qu&rsquo;il avait rarement vu de tumeur aussi virulente au niveau du colon. Mon ami Shawn avait lui une tumeur qui adh\u00e9rait \u00e0 sa colonne vert\u00e9brale, et son docteur lui a dit qu&rsquo;il n&rsquo;avait jamais vu une tumeur aussi virulente. En tout j&rsquo;ai subi 4 op\u00e9rations. Je suis une exp\u00e9rience vivante. Ils m&rsquo;ont ouvert de part en part. On m&rsquo;a retir\u00e9 la moiti\u00e9 du foie, le c\u00f4lon, la v\u00e9sicule biliaire, un bout d&rsquo;estomac, et la moiti\u00e9 du poumon gauche. Puis ils m&rsquo;ont mis une pompe, tout \u00e7a en 10h30 d&rsquo;op\u00e9ration.\u00a0\u00bb<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><em>\u00a0<\/em>Les t\u00e9moignages en eux-m\u00eames sont peut-\u00eatre bouleversants mais il faut savoir garder la t\u00eate froide. Premi\u00e8re remarque d\u00e9j\u00e0, ces deux-l\u00e0 sont compl\u00e8tement contradictoires. l&rsquo;un dit avoir trouv\u00e9 47 corps, l&rsquo;autre dit qu&rsquo;il n&rsquo;a trouv\u00e9 que des bouts de corps. Enfin, peut-\u00eatre que Mc Namara n&rsquo;avait pas la chance de se trouver dans un bon coin\u2026 Allez, sur ce point je leur laisse le b\u00e9n\u00e9fice du doute\u2026<\/span><\/p>\n<p><span style=\"color: #000000;\">Fait beaucoup plus solide maintenant, la mise en sc\u00e8ne de l&rsquo;ensemble du documentaire\u00a0<a style=\"color: #000000;\" href=\"http:\/\/www.dailymotion.com\/video\/xetmdd_docu-les-heros-sacrifies-du-11-sept_news\" target=\"_blank\" rel=\"noopener\">les h\u00e9ros sacrifi\u00e9s du 11 septembre<\/a>, comme celle d&rsquo;<a style=\"color: #000000;\" href=\"http:\/\/video.google.fr\/videoplay?docid=-647042342894016035\" target=\"_blank\" rel=\"noopener\">une femme \u00e0 abattre<\/a>, que j&rsquo;ai d\u00e9bunqu\u00e9 <a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/10\/15\/jaccuse-6-12-richard-gage-et-sibel-edmonds\/\" target=\"_blank\" rel=\"noopener\">au chapitre pr\u00e9c\u00e9dent<\/a>, me semble des plus sujette \u00e0 caution. Dans le cas de Silechia, premier t\u00e9moignage, nous avons de toute \u00e9vidence affaire \u00e0 un f\u00e9tichiste, puisqu&rsquo;il a gard\u00e9 intact dans son jardin un 4*4 rempli de poussi\u00e8re de Ground Zero qu&rsquo;il n&rsquo;a pas lav\u00e9 depuis l&rsquo;\u00e9poque. On voit par ailleurs, qu&rsquo;en plus du cancer, il a \u00e9t\u00e9 atteint de plein fouet par la pand\u00e9mie conspirationniste puisqu&rsquo;il suspecte au d\u00e9tour d&rsquo;une phrase (bonjour le hors-sujet), le maire de New York d&rsquo;avoir vol\u00e9 219 millions de dollars sur le fonds d&rsquo;indemnisation d&rsquo;un milliard pr\u00e9vu pour les pompiers dans une loi pr\u00e9c\u00e9dente de 2010. Dans le cas McNamara, second t\u00e9moignage, que dire de l&rsquo;introduction dans laquelle on voit le photographe mitrailler l&rsquo;ancien \u00ab\u00a0h\u00e9ros\u00a0\u00bb sous tous les angles, avec le casque de pompier rutilant et le fiston en bonne place sur les clich\u00e9s\u00a0? Le plus choquant est peut-\u00eatre ces courtes sc\u00e8nes o\u00f9 il demande \u00e0 ses interlocuteurs moribonds, \u00e0 des fins de manipulation de l&rsquo;opinion, de poser \u00e0 c\u00f4t\u00e9 des dizaines de m\u00e9dicaments qui leur ont \u00e9t\u00e9 prescrits dispos\u00e9s en pyramides \u00e9vocatrices.<\/span><\/p>\n<p><span style=\"color: #000000;\">Ce genre de reportage permet d&rsquo;entrevoir cet aspect particuli\u00e8rement r\u00e9voltant de la psychologie des pompiers du 11 septembre\u00a0: la volont\u00e9 de se mettre en avant \u00e0 tout prix, de profiter du moindre rayon de soleil m\u00e9diatique pour faire jaillir hors de terre les d\u00e9l\u00e9t\u00e8res mauvaises herbes de la pand\u00e9mie conspirationniste.<\/span><\/p>\n<p><span style=\"color: #000000;\"><em>\u00a0<\/em>Je n&rsquo;imagine pas un instant que la repr\u00e9sentation \u00e9tasunienne puisse rester insensible \u00e0 la d\u00e9tresse humaine en g\u00e9n\u00e9ral, puisse laisser sur le bord de la touche des h\u00e9ros de leur patrie, comme les pompiers pr\u00e9tendent l&rsquo;\u00eatre avec la vanit\u00e9 qui les caract\u00e9rise. Or dans cette affaire, ils ne veulent rien l\u00e2cher, rien reconna\u00eetre. \u00ab\u00a0<em>Que ces pompiers d\u00e9voy\u00e9s aillent mourir en silence dans leur coin<\/em>\u00a0\u00bb semblent penser de nombreux d\u00e9put\u00e9s et s\u00e9nateurs, au vu de l&rsquo;intransigeance de leur refus face aux demandes r\u00e9p\u00e9t\u00e9es des plaignants. Le lecteur s&rsquo;en convaincra avec l&rsquo;\u00e9num\u00e9ration suivante. Les s\u00e9nateurs r\u00e9publicains <a style=\"color: #000000;\" href=\"http:\/\/www.redorbit.com\/news\/health\/1970767\/911_health_act_passes_senate\" target=\"_blank\" rel=\"noopener\">ont fait obstruction \u00e0 la loi Zadroga en d\u00e9cembre 2010<\/a>, parviennent \u00e0 ramener la somme de 7,4 milliards de dollars promise \u00e0 l&rsquo;origine aux secouristes \u00e0 4,3 milliards. En avril 2011, <a style=\"color: #000000;\" href=\"http:\/\/www.letelegramme.com\/ig\/generales\/france-monde\/monde\/11-septembre-les-heros-se-meurent-17-04-2011-1271552.php\" target=\"_blank\" rel=\"noopener\">selon Anne-Mary Bowmann<\/a>, vice pr\u00e9sidente de l&rsquo;association Fealgood, des experts m\u00e9dicaux viennent prendre le corps d&rsquo;un pompier d\u00e9c\u00e9d\u00e9 sous les yeux de sa famille pour de nouveaux examens, alors qu&rsquo;il allait \u00eatre inhum\u00e9. Le but \u00e9tait de prouver que sa maladie n&rsquo;\u00e9tait pas li\u00e9e \u00e0 son m\u00e9tier. Le m\u00eame mois, <a style=\"color: #000000;\" href=\"http:\/\/www.huffingtonpost.com\/2011\/04\/21\/911-responders-screened-for-terror-ties_n_852198.html\" target=\"_blank\" rel=\"noopener\">est adopt\u00e9 un amendement \u00e0 la loi Zadroga<\/a> qui autorise le FBI \u00e0 croiser les donn\u00e9es personnelles de dizaines de milliers de secouristes pr\u00e9tendant b\u00e9n\u00e9ficier de la loi Zadroga avec son fichier anti-terroriste, afin de s&rsquo;assurer qu&rsquo;aucun membre d&rsquo;Al Qaida ne se glisse dans cette clique de soupirants. Pour \u00eatre indemnis\u00e9s, ceux-ci devront imp\u00e9rativement communiquer ces informations \u00e0 l&rsquo;agence de renseignement. Enfin, dernier coup de th\u00e9\u00e2tre, <a style=\"color: #000000;\" href=\"http:\/\/www.nydailynews.com\/ny_local\/2011\/07\/27\/2011-07-27_its_absolutely_unacceptable.html#ixzz1TLoFEWoc\" target=\"_blank\" rel=\"noopener\">para\u00eet en juillet 2011<\/a> un rapport s&rsquo;appuyant sur plusieurs \u00e9tudes m\u00e9dicales \u00e9tablit que \u00ab\u00a0<em>\u00a0trop peu de preuves existent \u00e0 l&rsquo;heure actuelle pour que l&rsquo;on propose d&rsquo;ajouter le cancer, ou un certain type de cancer, \u00e0 la liste des probl\u00e8mes de sant\u00e9 li\u00e9s au World Trade Center.<\/em>\u00a0\u00bb, en cons\u00e9quence de quoi tous les secouristes ayant contract\u00e9 des cancers ne seront probablement jamais indemnis\u00e9s au titre de la loi Zadroga.<\/span><\/p>\n<p><span style=\"color: #000000;\">Il est toujours int\u00e9ressant dans une histoire d&rsquo;entendre tous les sons de cloche, et de ne pas c\u00e9der \u00e0 l&rsquo;\u00e9motion, qui oblit\u00e8re si facilement le jugement. En l&rsquo;occurrence, l&rsquo;attitude intransigeante de l&rsquo;establishment \u00e9tasuniens montre bien que l&rsquo;histoire des pompiers n&rsquo;est pas tr\u00e8s cr\u00e9dible. Dans le tas il doit bien y avoir un lot de vrais cancers, mais je fr\u00e9mis en imaginant la proportion d&rsquo;hypocondriaques, de mythomanes, et de voyous, sans compter les agents d&rsquo;al Qaida infiltr\u00e9s dans cette cour des miracles pour abuser de la g\u00e9n\u00e9rosit\u00e9 du gouvernement.<\/span><\/p>\n<p><span style=\"color: #000000;\">A la limite, la seule faute qui m&rsquo;appara\u00eet imputable \u00e0 l&rsquo;administration W. Bush, comme le montre un rapport rendu public en 2003 par l&rsquo;agence de protection de l&rsquo;environnement (EPA), c&rsquo;est d&rsquo;avoir express\u00e9ment demand\u00e9 \u00e0 sa directrice Christie Whitman, \u00ab\u00a0<em>d&rsquo;ajouter des d\u00e9clarations rassurantes, et de mettre en sourdine celles qui pouvaient \u00eatre alarmantes<\/em>\u00a0\u00bb quant \u00e0 la qualit\u00e9 de l&rsquo;air respir\u00e9 par les secouriste sur le site de Ground Zero. Ainsi voit-on cette derni\u00e8re <a style=\"color: #000000;\" href=\"http:\/\/www.youtube.com\/watch?v=BxdttHY59b4\" target=\"_blank\" rel=\"noopener\">affirmer<\/a>, quelques jours apr\u00e8s les \u00e9v\u00e9nements, que\u00a0: \u00ab\u00a0<em>Les concentrations (de produits toxiques), sont telles qu&rsquo;elles ne posent pas de probl\u00e8mes de sant\u00e9. Nous allons nous assurer que tout le monde soit en s\u00e9curit\u00e9<\/em>\u00a0\u00bb. Il est malheureusement possible que deux ou trois pompiers un peu trop curieux s&rsquo;\u00e9tant pench\u00e9s au-dessus d&rsquo;un trou particuli\u00e8rement toxique aient respir\u00e9 quelques effluves pas tr\u00e8s catholiques. Mais depuis la directrice de l&rsquo;agence n&rsquo;a-t-elle pas eu le courage, en 2003, de d\u00e9missionner de son propre chef,<a style=\"color: #000000;\" href=\"http:\/\/dir.salon.com\/story\/opinion\/feature\/2005\/01\/15\/muck_whitman\/index.html\" target=\"_blank\" rel=\"noopener\"> pour se consacrer \u00e0 sa famille<\/a>, et <a style=\"color: #000000;\" href=\"http:\/\/www.nytimes.com\/2003\/05\/22\/us\/often-isolated-whitman-quits-as-epa-chief.html\" target=\"_blank\" rel=\"noopener\">ne pas plomber la campagne de r\u00e9\u00e9lection de George W. Bush<\/a>\u00a0? Et la position responsable qu&rsquo;elle avait prise en 2001 n&rsquo;a-t-elle pas facilit\u00e9 <a style=\"color: #000000;\" href=\"http:\/\/boutique.ina.fr\/video\/1814650001\/edition-nationale-emission-du-17-septembre-2001.fr.html\" target=\"_blank\" rel=\"noopener\">la r\u00e9ouverture de la bourse de Wall Street<\/a>, situ\u00e9e \u00e0 deux pas du World Trade Center, six jours plus tard\u00a0? Je sais bien que certains tiqueront de ce que je privil\u00e9gie le mat\u00e9riel sur l&rsquo;humain, mais la crise des subprimes en 2007 nous a appris que les institutions financi\u00e8res \u00e9taient le c\u0153ur du syst\u00e8me, que c&rsquo;\u00e9tait l\u00e0 qu&rsquo;\u00e9tait le soleil v\u00e9ritable autour duquel toute la r\u00e9alit\u00e9 humaine gravitait, que la disparition de ce soleil entra\u00eenerait la mort du syst\u00e8me et le commencement d&rsquo;une errance sans fin pour les plan\u00e9to\u00efdes que nous sommes tous. Il est l\u00e0 le v\u00e9ritable <em>poumon<\/em> des \u00c9tats-Unis d&rsquo;Am\u00e9rique, et par ricochet du monde libre et d\u00e9mocratique\u00a0! Qui sait\u00a0? Peut-\u00eatre m\u00eame cette d\u00e9cision de Christie Whitman, en permettant de relancer dare-dare le moteur \u00e9conomique \u00e9tasunien, a-t-elle contribu\u00e9 \u00e0 sauvegarder des pr\u00e9cieux points de croissance et des millions vies irrempla\u00e7ables..<\/span><\/p>\n<p><span style=\"color: #000000;\">Une derni\u00e8re remarque l\u00e0-dessus\u00a0: pourquoi un pompier s&rsquo;\u00e9mouvrait-il de contracter un cancer\u00a0? A force d&rsquo;aller dans les incendies, de respirer des fum\u00e9es toxiques de toutes sortes, c&rsquo;est un noir compagnon que l&rsquo;on croise t\u00f4t ou tard sur son chemin. Partir d&rsquo;un cancer pour un pompier, c&rsquo;est comme la cirrhose pour les vignerons, ou la balle perdue pour les soldats, cela fait partie, tout bien pes\u00e9, de l&rsquo;ordre naturel. La charte des pompiers ne stipule-t-elle pas que la mort fait partie des risques du m\u00e9tier\u00a0?<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"_Conclusion\"><\/span><span style=\"color: #000000;\"><strong>\u00a0Conclusion<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Je veux finir cette accusation du comportement des pompiers en cette journ\u00e9e funeste du 11 septembre 2001 et dans la d\u00e9cennie qui a suivi, en rendant hommage au pr\u00e9sident George W. Bush, injustement brocard\u00e9 selon moi dans cette pol\u00e9mique naus\u00e9abonde. Les pompiers ont en effet un grief particulier envers le 43<sup>\u00e8me<\/sup> pr\u00e9sident des \u00c9tats-Unis d&rsquo;Am\u00e9rique\u00a0: l&rsquo;homme s&rsquo;est servi dans plusieurs de ses spots de campagne de 2004 de vid\u00e9os mettant en sc\u00e8ne des familles de victimes et des pompiers de Ground Zero. <a style=\"color: #000000;\" href=\"http:\/\/www.youtube.com\/watch?v=s67qaViGNBU\" target=\"_blank\" rel=\"noopener\">Celui intitul\u00e9 \u00ab\u00a0safer, stronger\u00a0\u00bb<\/a>, o\u00f9 l&rsquo;on voit un groupe de pompiers transportant le cercueil d&rsquo;un des leurs recouvert de la banni\u00e8re \u00e9toil\u00e9e, sur fond d&rsquo;images de la trag\u00e9die <a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/%20http:\/\/www.washingtonpost.com\/wp-dyn\/articles\/A31696-2004Mar4.html\" target=\"_blank\" rel=\"noopener\">a particuli\u00e8rement choqu\u00e9 les int\u00e9ress\u00e9s<\/a>. La\u00a0pol\u00e9mique populiste qu&rsquo;ils ont d\u00e9clench\u00e9e en r\u00e9ponse n&rsquo;a heureusement pas emp\u00eacher le pr\u00e9sident qui a d\u00fb faire face \u00e0 l&rsquo;impensable de gagner une seconde fois le c\u0153ur du peuple \u00e9tasunien.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le caract\u00e8re choquant de cette d\u00e9marche n&rsquo;est qu&rsquo;apparent. La s\u00e9paration des pouvoirs, contrairement \u00e0 des pays comme la France, n&rsquo;est pas un vain mot. Si le pr\u00e9sident George W. Bush avait \u00e9cout\u00e9 son c\u0153ur, il aurait certainement sign\u00e9 sans r\u00e9fl\u00e9chir n&rsquo;importe quel ch\u00e8que en blanc que leur aurait tendu les pompiers. Cependant une enqu\u00eate ind\u00e9pendante a \u00e9t\u00e9 men\u00e9e. Les s\u00e9nateurs, surtout dans le camp r\u00e9publicain, domptant le flot d&rsquo;\u00e9motions patriotiques qui les submergeaient, ont courageusement men\u00e9 leur enqu\u00eate pour voir de quoi il retournait vraiment. Il s&rsquo;est av\u00e9r\u00e9 au terme de cette enqu\u00eate dont les premi\u00e8res conclusions ont \u00e9t\u00e9 rendues en juillet 2011, que les pompiers avaient en quelque sorte \u00ab\u00a0vendu leur corps\u00a0\u00bb pour les besoins de ce que l&rsquo;on est oblig\u00e9 de consid\u00e9rer, tout bien pes\u00e9, comme une <em>arnaque \u00e0 l&rsquo;assurance<\/em>. Peut-\u00eatre avaient-ils \u00e9t\u00e9 mis en app\u00e9tit par les <a style=\"color: #000000;\" href=\"http:\/\/www.ny1.com\/content\/top_stories\/57821\/charges-of-greed-surface-following-breakdown-of-wtc-talks\">4,65 milliards de dollars r\u00e9cup\u00e9r\u00e9s<\/a> par le pauvre Larry Silverste\u00efn, l&rsquo;homme qui a sauv\u00e9 d&rsquo;innombrables vies de pompiers en les obligeant \u00e0 sortir de la tour 7 avant son effondrement (<a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2010\/10\/02\/jaccuse-5-12-leffondrement-de-la-tour-7\/\" target=\"_blank\" rel=\"noopener\">voir chapitre 3<\/a>). Larry Silverste\u00efn, un vrai h\u00e9ros pour le coup&#8230; aucun rapport avec ces pompiers mythomanes qui entendent des explosions \u00e0 chaque coin de rue, et fantasment un cancer derri\u00e8re chaque grain de beaut\u00e9. Tout ce monde-l\u00e0 \u00e0 l&rsquo;\u00e9vidence ne joue pas dans la m\u00eame division.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">Post Scriptum\u00a0: au moment o\u00f9 je rends public sur le World Wide Web ce chapitre sur les pompiers d\u00e9voy\u00e9s du 11 septembre, un reportage <a style=\"color: #000000;\" href=\"http:\/\/www.m6bonus.fr\/videos-emissions-4\/videos-enquete_exclusive-2460\/emission_du_04_09_2011\/video-special_11_09_10_ans_apres-84760.html\" target=\"_blank\" rel=\"noopener\">vient de passer sur M6<\/a> dont les personnages principaux sont les pompiers du 11 septembre. Les auteurs du reportage, qui disposent d&rsquo;autres moyens que moi, ont pu se rendre aux \u00c9tats-Unis pour mener leur enqu\u00eate dans des conditions autrement plus satisfaisantes. Ils sont parvenus \u00e0 deux conclusions que je suis oblig\u00e9 de discuter, eu \u00e9gard \u00e0 leur caract\u00e8re profond\u00e9ment novateur. Premier point\u00a0: Les auteurs ont d\u00e9couvert que les policiers pr\u00e9sents autour du site se sont rendus compte <em>avant les pompiers<\/em> que les tours jumelles allaient s&rsquo;effondrer et ont tent\u00e9 de les avertir. Ce nouveau fait renforce mon hypoth\u00e8se de la folie des pompiers\u00a0: si des gens ne connaissant rien aux incendies d&rsquo;immeubles peuvent avertir des professionnels d&rsquo;une \u00e9vidence faisant partie du B-A BA de leur instruction, nous tenons l\u00e0 la preuve indubitable de l&rsquo;\u00e9tat de d\u00e9mence des pompiers que j&rsquo;ai d\u00e9crit de fa\u00e7on convaincante \u00e0 travers deux exemples \u00e9difiants. Second point\u00a0: les policiers, l&rsquo;esprit foudroy\u00e9 par cette \u00e9vidence auraient tent\u00e9 d&rsquo;avertir leurs coll\u00e8gues en rouge \u00e0 l&rsquo;int\u00e9rieur des tours, mais en vain, en raison du fait qu&rsquo;ils n&rsquo;\u00e9taient pas inform\u00e9s de la fr\u00e9quence sur laquelle \u00e9tait cal\u00e9e les talkie-walkies des pompiers. L\u00e0 je suis oblig\u00e9 de m&rsquo;insurger. Autant la premi\u00e8re hypoth\u00e8se me semble traduire une belle trou\u00e9e dans le chemin vers la v\u00e9rit\u00e9, autant le second me semble propre \u00e0 jeter le discr\u00e9dit le plus profond sur le respectable et n\u00e9cessaire mouvement des debunkers. Comment imaginer une erreur aussi incroyable\u00a0? Il faut bien plut\u00f4t supposer que les pompiers ont entendu les avertissements des policiers, <em>mais qu&rsquo;ils n&rsquo;ont pas voulu les entendre<\/em>. Occup\u00e9s \u00e0 cisailler les poutres en acier au chalumeau oxy-\u00e9thyl\u00e8ne, rendus sourds \u00e0 toute parole humaine sens\u00e9e, la parole de leurs coll\u00e8gues en bleu comptaient \u00e0 ce moment l\u00e0 pour de la poussi\u00e8re. Cette interpr\u00e9tation des mauvaises communications me semble pour le coup vraiment tir\u00e9e par les cheveux, et sur ce coup-l\u00e0, je me dis que la petite cha\u00eene qui monte est tomb\u00e9e bien bas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Donald Forestier<\/span><\/p>\n<p><span style=\"color: #000000;\"><em>co-\u00e9crit avec Charles Aissani, sous le pseudonyme de Donald Forestier, publi\u00e9 sur le site <a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/tribune-libre\/article\/j-accuse-les-sauveteurs-du-11-09-102031\" target=\"_blank\" rel=\"noopener\">Agoravox<\/a> le\u00a0 10 octobre 2011. Le d\u00e9calage de parution d&rsquo;un an s&rsquo;explique par le retard irrattrapable pris l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente dans la r\u00e9daction de l&rsquo;ensemble des articles. Seules se trouvent dans cette situation les parties 7\/12 et 8\/12<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a un an j&rsquo;ai publi\u00e9 sur ce site mon livre \u00ab J&rsquo;accuse la pand\u00e9mie conspirationniste \u00bb au rythme d&rsquo;un chapitre par semaine. Les lecteurs attentifs auront peut-\u00eatre remarqu\u00e9 qu&rsquo;il en manquait deux dans la seconde section : celui sur les pompiers et les familles de victime remettant en cause la version officielle, et &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;J&rsquo;accuse (7\/12) : les pompiers du 11 septembre&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[13,23,22],"class_list":["post-71","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-donald-forestier","tag-11-septembre-2001","tag-jerome-quirant","tag-pompiers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>J&#039;accuse (7\/12) : les pompiers du 11 septembre - Fran\u00e7ois Belliot<\/title>\n<meta name=\"description\" content=\"Les pompiers du 11 septembre, des h\u00e9ros\u00a0? Donald d\u00e9montre, au contraire qu\u2019ils ont vendu leurs corps pour une arnaque \u00e0 l\u2019assurance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J&#039;accuse (7\/12) : les pompiers du 11 septembre - Fran\u00e7ois Belliot\" \/>\n<meta property=\"og:description\" content=\"Les pompiers du 11 septembre, des h\u00e9ros\u00a0? Donald d\u00e9montre, au contraire qu\u2019ils ont vendu leurs corps pour une arnaque \u00e0 l\u2019assurance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Fran\u00e7ois Belliot\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-10T12:19:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-13T16:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"266\" \/>\n\t<meta property=\"og:image:height\" content=\"190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francoisbelliot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"francoisbelliot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"29 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/\",\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/\",\"name\":\"J'accuse (7\/12) : les pompiers du 11 septembre - Fran\u00e7ois Belliot\",\"isPartOf\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg\",\"datePublished\":\"2011-10-10T12:19:55+00:00\",\"dateModified\":\"2018-08-13T16:17:48+00:00\",\"author\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\"},\"description\":\"Les pompiers du 11 septembre, des h\u00e9ros\u00a0? Donald d\u00e9montre, au contraire qu\u2019ils ont vendu leurs corps pour une arnaque \u00e0 l\u2019assurance.\",\"breadcrumb\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#primaryimage\",\"url\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg\",\"contentUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg\",\"width\":266,\"height\":190,\"caption\":\"A l'int\u00e9rieur des tours jumelles, puis par la suite sur le site de Ground Zero, les pompiers furent en premi\u00e8re ligne le 11 septembre 2001 \u00e0 New York\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/francoisbelliot.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"J&rsquo;accuse (7\/12) : les pompiers du 11 septembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/francoisbelliot.fr\/#website\",\"url\":\"https:\/\/francoisbelliot.fr\/\",\"name\":\"Fran\u00e7ois Belliot\",\"description\":\"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/francoisbelliot.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\",\"name\":\"francoisbelliot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"caption\":\"francoisbelliot\"},\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J'accuse (7\/12) : les pompiers du 11 septembre - Fran\u00e7ois Belliot","description":"Les pompiers du 11 septembre, des h\u00e9ros\u00a0? Donald d\u00e9montre, au contraire qu\u2019ils ont vendu leurs corps pour une arnaque \u00e0 l\u2019assurance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/","og_locale":"fr_FR","og_type":"article","og_title":"J'accuse (7\/12) : les pompiers du 11 septembre - Fran\u00e7ois Belliot","og_description":"Les pompiers du 11 septembre, des h\u00e9ros\u00a0? Donald d\u00e9montre, au contraire qu\u2019ils ont vendu leurs corps pour une arnaque \u00e0 l\u2019assurance.","og_url":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/","og_site_name":"Fran\u00e7ois Belliot","article_published_time":"2011-10-10T12:19:55+00:00","article_modified_time":"2018-08-13T16:17:48+00:00","og_image":[{"width":266,"height":190,"url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg","type":"image\/jpeg"}],"author":"francoisbelliot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"francoisbelliot","Dur\u00e9e de lecture estim\u00e9e":"29 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/","url":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/","name":"J'accuse (7\/12) : les pompiers du 11 septembre - Fran\u00e7ois Belliot","isPartOf":{"@id":"https:\/\/francoisbelliot.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#primaryimage"},"image":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#primaryimage"},"thumbnailUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg","datePublished":"2011-10-10T12:19:55+00:00","dateModified":"2018-08-13T16:17:48+00:00","author":{"@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9"},"description":"Les pompiers du 11 septembre, des h\u00e9ros\u00a0? Donald d\u00e9montre, au contraire qu\u2019ils ont vendu leurs corps pour une arnaque \u00e0 l\u2019assurance.","breadcrumb":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#primaryimage","url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg","contentUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2011\/10\/pompiers911.jpeg","width":266,"height":190,"caption":"A l'int\u00e9rieur des tours jumelles, puis par la suite sur le site de Ground Zero, les pompiers furent en premi\u00e8re ligne le 11 septembre 2001 \u00e0 New York"},{"@type":"BreadcrumbList","@id":"https:\/\/francoisbelliot.fr\/index.php\/2011\/10\/10\/jaccuse-7-12-les-sauveteurs-du-11-septembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francoisbelliot.fr\/"},{"@type":"ListItem","position":2,"name":"J&rsquo;accuse (7\/12) : les pompiers du 11 septembre"}]},{"@type":"WebSite","@id":"https:\/\/francoisbelliot.fr\/#website","url":"https:\/\/francoisbelliot.fr\/","name":"Fran\u00e7ois Belliot","description":"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francoisbelliot.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9","name":"francoisbelliot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","caption":"francoisbelliot"},"url":"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/"}]}},"_links":{"self":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/comments?post=71"}],"version-history":[{"count":0,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/71\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media\/361"}],"wp:attachment":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media?parent=71"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/categories?post=71"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/tags?post=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}