{"id":1640,"date":"2021-11-20T11:46:41","date_gmt":"2021-11-20T10:46:41","guid":{"rendered":"https:\/\/francoisbelliot.fr\/?p=1640"},"modified":"2024-06-20T17:59:18","modified_gmt":"2024-06-20T15:59:18","slug":"la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres","status":"publish","type":"post","link":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/","title":{"rendered":"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres"},"content":{"rendered":"\n<p>Alors qu\u2019il n\u2019existe aucun cas de haut fonctionnaire ayant eu \u00e0 rendre des comptes pour l\u2019anticipation et la gestion au mieux calamiteuse, au pire coupable, d\u2019\u00e9v\u00e9nements sanglants comme le massacre de la r\u00e9daction de <em>Charlie Hebdo<\/em> du 7 janvier 2015 ou les attentats du 13 novembre 2015 \u2013 la m\u00eame remarque pourrait \u00eatre faite pour la si mal nomm\u00e9e \u00ab\u00a0crise sanitaire\u00a0\u00bb dans laquelle nous nous enfon\u00e7ons inexorablement depuis pr\u00e8s de vingt mois comme dans des sables mouvants \u2013 le cas de Bernard Petit, l\u2019ancien patron du 36 quai des Orf\u00e8vres \u2013 la Police Judiciaire de la Pr\u00e9fecture de Police de Paris \u2013, nous donne l\u2019occasion de montrer par un exemple \u00e9clatant qu\u2019au besoin, les sanctions les plus lourdes peuvent \u00eatre prises contre un fonctionnaire tr\u00e8s haut plac\u00e9, pour un pr\u00e9texte dont le caract\u00e8re d\u00e9cisif est loin d\u2019\u00eatre \u00e9vident. Ce qu\u2019on appelle le deux poids\/deux mesures pour \u00e9voquer le gouffre qui s\u2019approfondit jour apr\u00e8s jour entre les \u00e9lites et les simples citoyens, les premi\u00e8res toujours \u00ab\u00a0responsables mais pas coupables\u00a0\u00bb, les seconds toujours \u00ab\u00a0pas responsables mais coupables\u00a0\u00bb, peut se constater \u00e9galement dans les hautes sph\u00e8res du pouvoir, d\u00e8s lors que l\u2019on d\u00e9range le dispositif ou grippe son fonctionnement, et il ne s\u2019agit pas d\u2019une question de comp\u00e9tence ou d\u2019incomp\u00e9tence. Le r\u00e9gime r\u00e9publicain privil\u00e9giera toujours l\u2019incomp\u00e9tent servile au comp\u00e9tent ind\u00e9pendant, couvrant le premier en toutes circonstances, quelles que soient ses casseroles, et d\u00e9truisant le second sans piti\u00e9, aussi irr\u00e9prochables soient ses \u00e9tats de service \u2013 la question de l\u2019int\u00e9r\u00eat sup\u00e9rieur des Fran\u00e7ais et de leur s\u00e9curit\u00e9, est-il besoin de le pr\u00e9ciser, n\u2019entrant <em>jamais<\/em> en ligne de compte. Nous avons rapport\u00e9 dans notre ouvrage <em><a href=\"https:\/\/www.leretourauxsources.com\/ingenierie-sociale\/165-massacre-de-charlie-hebdo-l-enquete-impossible.html\">Le massacre d<\/a><a href=\"https:\/\/www.leretourauxsources.com\/ingenierie-sociale\/165-massacre-de-charlie-hebdo-l-enquete-impossible.html\" target=\"_blank\" rel=\"noreferrer noopener\">e<\/a><a href=\"https:\/\/www.leretourauxsources.com\/ingenierie-sociale\/165-massacre-de-charlie-hebdo-l-enquete-impossible.html\"> Charlie Hebdo, l\u2019enqu\u00eate impossible<\/a><\/em>, le cas du patron du RAID Jean-Michel Fauvergue, limog\u00e9 en 2017 pour le plus captieux des pr\u00e9textes en plein \u00e9tat d\u2019urgence terroriste, voyons maintenant celui de Bernard Petit, qui en tant que patron de la PJ de Paris coordonnait les enqu\u00eates les attentats de janvier 2015, brutalement plac\u00e9 en garde-\u00e0-vue le 3 f\u00e9vrier 2015, aussit\u00f4t d\u00e9grad\u00e9, limog\u00e9, humili\u00e9, et toujours en attente de son proc\u00e8s six ans apr\u00e8s les faits.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Le pr\u00e9sent travail s&rsquo;int\u00e8gre dans la s\u00e9rie d&rsquo;articles connexes que nous avons publi\u00e9s depuis le mois d&rsquo;ao\u00fbt 2021, en accompagnement de la sortie du <a href=\"https:\/\/www.leretourauxsources.com\/ingenierie-sociale\/165-massacre-de-charlie-hebdo-l-enquete-impossible.html\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Massacre de Charlie Hebdo, l&rsquo;enqu\u00eate impossible<\/em>, dans l&rsquo;ordre&nbsp;<\/a>:<\/p>\n\n\n\n<p>1) <a href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/08\/03\/un-ouvrage-anticomplotiste-ac-sur-le-massacre-de-charlie-hebdo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Un ouvrage anticomplotiste (AC), sur le massacre de Charlie Hebdo<\/a><\/p>\n\n\n\n<p>2) <a href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/08\/13\/le-lynchage-republicain-de-thierry-casasnovas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Le lynchage r\u00e9publicain de Thierry Casasnovas<\/a><\/p>\n\n\n\n<p>3) <a href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/09\/02\/11-septembre-et-massacre-de-charlie-hebdo-ressemblance-ou-filiation\/\" target=\"_blank\" rel=\"noreferrer noopener\">11 septembre et massacre de Charlie Hebdo&nbsp;: ressemblance ou filiation&nbsp;?<\/a><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_71 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57aecd1a207\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57aecd1a207\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#Une_carriere_et_des_etats_de_service_exemplaires\" title=\"Une carri\u00e8re et des \u00e9tats de service exemplaires\">Une carri\u00e8re et des \u00e9tats de service exemplaires<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#3_fevrier_2015_La_chute\" title=\"3 f\u00e9vrier 2015 : La chute\">3 f\u00e9vrier 2015 : La chute<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#Un_exercice_perturbe_par_les_affaires_et_les_destabilisations\" title=\"Un exercice perturb\u00e9 par les affaires et les d\u00e9stabilisations\">Un exercice perturb\u00e9 par les affaires et les d\u00e9stabilisations<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#Deux_affaires_retentissantes_un_viol_et_un_vol_de_52_kg_de_cocaine_dans_les_locaux_de_la_PJ\" title=\"Deux affaires retentissantes&nbsp;: un viol et un vol de 52 kg de coca\u00efne dans les locaux de la PJ\">Deux affaires retentissantes&nbsp;: un viol et un vol de 52 kg de coca\u00efne dans les locaux de la PJ<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#Destabilisations\" title=\"D\u00e9stabilisations\">D\u00e9stabilisations<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#Mai_2021_le_proces_a_venir_de_Bernard_Petit\" title=\"Mai 2021 : le proc\u00e8s \u00e0 venir de Bernard Petit ?\">Mai 2021 : le proc\u00e8s \u00e0 venir de Bernard Petit ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#Conclusion\" title=\"Conclusion\">Conclusion<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#Addendum_le_point_de_vue_de_Bernard_Petit_sur_le_massacre_de_Charlie_Hebdo_et_le_mystere_des_freres_Kouachi\" title=\"Addendum&nbsp;: le point de vue de Bernard Petit sur le massacre de Charlie Hebdo et le myst\u00e8re des fr\u00e8res Kouachi\">Addendum&nbsp;: le point de vue de Bernard Petit sur le massacre de Charlie Hebdo et le myst\u00e8re des fr\u00e8res Kouachi<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Une_carriere_et_des_etats_de_service_exemplaires\"><\/span><strong>Une carri\u00e8re et des \u00e9tats de service exemplaires<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>N\u00e9 \u00e0 Sfax en Tunisie en 1956, Bernard Petit est entr\u00e9 dans la police en 1978, apr\u00e8s \u00eatre pass\u00e9 par l\u2019\u00e9cole des officiers de police \u00e0 Cannes l\u2019\u00c9cluse. D\u00e9butant en tant qu\u2019inspecteur puis inspecteur principal de l\u2019Office central pour la r\u00e9pression du trafic illicite de stup\u00e9fiants (OCTRIS) il passe en 1985-1986 par l\u2019\u00c9cole sup\u00e9rieure de la police nationale Saint-Cyr-au-Mont-d\u2019Or, dont il sort major de promotion, entrant dans la carri\u00e8re de commissaire. Il est affect\u00e9 pour commencer Adjoint au chef de l\u2019Office central pour la r\u00e9pression du banditisme (OCRB), jusqu\u2019en 1990 o\u00f9 il devient Conseiller technique \u00e0 la D\u00e9l\u00e9gation interminist\u00e9rielle \u00e0 la lutte contre la drogue et la toxicomanie (DGLDT). De 1994 \u00e0 1997, il est chef d\u2019\u00e9tat-major de la police judiciaire, puis de 1997 \u00e0 2001, attach\u00e9 de police en Afrique du Sud pour la Coop\u00e9ration technique et op\u00e9rationnelle. De 2001 \u00e0 2006 il dirige l\u2019OCRTIS, rattach\u00e9 \u00e0 la DCPJ. En 2006, il devient \u00ab<em>&nbsp;le patron de la Division des relations internationales (DRI) de la police nationale, la nouvelle d\u00e9nomination de la SCTIP, le Service de la coop\u00e9ration technique international de la police, une responsabilit\u00e9 traditionnellement attribu\u00e9e \u00e0 un franc-ma\u00e7on&nbsp;<\/em>\u00bb, rapporte Olivier Toscer dans le <a href=\"https:\/\/www.nouvelobs.com\/justice\/20150205.OBS1808\/pj-de-paris-bernard-petit-victime-des-freres-francs-macons.html\"><em>nouvelobs.com<\/em><\/a>. En 2010 il est nomm\u00e9 Sous-directeur de la police judiciaire en charge de la lutte contre le crime organis\u00e9 et la d\u00e9linquance financi\u00e8re. Il atteint la cons\u00e9cration en d\u00e9cembre 2013, quand il nomm\u00e9 par Manuel Valls \u00e0 la t\u00eate des services actifs de la pr\u00e9fecture de Paris, c\u2019est-\u00e0-dire patron du c\u00e9l\u00e8bre 36 quai des Orf\u00e8vres, en remplacement de Christian Flaesch, coupable de \u00ab&nbsp;faute d\u00e9ontologique&nbsp;\u00bb (( Bernard Petit r\u00e9sume ainsi l\u2019\u00e9viction de Christian Flaesch, p. 73&nbsp;:&nbsp;\u00ab&nbsp;<em>J\u2019avais ensuite [au moment de ma nomination] rencontr\u00e9 Fran\u00e7ois Molins. Prudent et courtois comme souvent, le procureur de la R\u00e9publique de Paris n\u2019\u00e9met aucun commentaire sur ma nomination. Simplement, il l\u00e2che entre deux phrases, au sujet de l\u2019affaire Flaesch&nbsp;: \u00ab\u00a0D\u00e8s lors que c\u2019\u00e9tait transcrit, c\u2019\u00e9tait pr\u00e9visible que \u00e7a sortirait&#8230;\u00a0\u00bb Une allusion \u00e0 la retranscription r\u00e9alis\u00e9e, \u00e0 la demande expresse du juge d\u2019instruction charg\u00e9 de l\u2019enqu\u00eate, par les fonctionnaires de l\u2019Office central de la lutte contre la corruption et les infractions financi\u00e8re et fiscales, de conversations au cours desquelles Christian Flaesch donnait des conseils \u00e0 Brice Hortefeux, ancien ministre de l\u2019Int\u00e9rieur, avant son audition par un juge d\u2019instruction. En fait, une fois ce document \u00e9tabli et transmis au juge mandant, celui-ci avait pris la d\u00e9cision de l\u2019adresser officiellement au parquet, ce qui devait aboutir \u00e0 une \u00ab&nbsp;mise en garde&nbsp;\u00bb du parquet g\u00e9n\u00e9ral. Malgr\u00e9 la volont\u00e9 de confidentialit\u00e9 qui entourait ces faits, le journal Le Monde finissait par les d\u00e9voiler. Comment les journalistes ont-ils \u00e9t\u00e9 inform\u00e9s de la convocation et de la mise en garde adress\u00e9e par le procureur g\u00e9n\u00e9ral au directeur de la PJ parisienne&nbsp;? Nul ne sait Le tout allait provoquer l\u2019ire du ministre de l\u2019Int\u00e9rieur et le limogeage de mon pr\u00e9d\u00e9cesseur.<\/em>&nbsp;\u00bb )), pour reprendre les propos publics du ministre. A ce poste \u00e9minent, Petit a activement particip\u00e9 \u00e0 l\u2019enqu\u00eate sur le massacre de Charlie Hebdo, dont il a vu de ses yeux le carnage dans les locaux du journal au 10 rue Nicolas Appert, et de la prise d\u2019otages de l\u2019Hyper Cacher. <a href=\"https:\/\/www.youtube.com\/watch?v=D3J1rza1YC8\" target=\"_blank\" rel=\"noreferrer noopener\">Interviouv\u00e9e sur <em>France Inter<\/em><\/a>, le 5 f\u00e9vrier, pour commenter la nouvelle de son placement compl\u00e8tement inattendu en garde-\u00e0-vue, Martine Monteil, ancienne cheffe de la direction centrale de la police de Paris, sous les ordres de laquelle Bernard Petit a travaill\u00e9, produit \u00e0 propos de la PJ parisienne, dont l\u2019image a \u00e9t\u00e9 \u00e9corn\u00e9e par les affaires en 2014 \u2013 nous y reviendrons \u2013 et de la carri\u00e8re de Bernard Petit, le commentaire suivant&nbsp;: \u00ab&nbsp;<em>C\u2019est quand m\u00eame une grosse partie de cette maison [le 36 quai des orf\u00e8vres] \u2013 il y a eu ceux qui \u00e9taient sur le terrain, comme la BRI \u2013 mais il y avait aussi tous ceux qui \u00e9taient derri\u00e8re \u00e0 la brigade criminelle, la section antiterroriste, qui ont merveilleusement travaill\u00e9 sur l\u2019affaire de ces actes autour de Charlie. (\u2026) C\u2019est un tr\u00e8s bon patron, il a gravi tous les \u00e9chelons des diff\u00e9rents services et de la hi\u00e9rarchie. (\u2026) C\u2019est un gar\u00e7on qui est intelligent, qui est tr\u00e8s r\u00e9fl\u00e9chi, et plut\u00f4t dans la r\u00e9serve et dans la prudence, ce qui me fait m\u2019\u00e9tonner. (\u2026) Je ne sais pas d\u2019ailleurs ce que donnera la fin de l\u2019enqu\u00eate, parce que moi j\u2019ai toujours une tr\u00e8s tr\u00e8s grande prudence, et j\u2019attends que les choses soient plus claires. Pour le moment, on en est au stade d\u2019une garde-\u00e0-vue. On verra bien.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p>Pour l\u2019homme, le coup de tonnerre du 3 f\u00e9vrier 2015 a \u00e9t\u00e9 une surprise totale et le traumatisme profond et encore aujourd\u2019hui incompris. \u00ab&nbsp;<em>On verra bien&nbsp;<\/em>\u00bb, commentait prudemment Martine Monteil \u00e0 l\u2019\u00e9poque. \u00ab&nbsp;<em>Qui vivra verra&nbsp;<\/em>\u00bb, serait-on tent\u00e9 aujourd\u2019hui d\u2019ajouter, alors que six ann\u00e9es se sont \u00e9coul\u00e9es et qu\u2019aucun proc\u00e8s n\u2019est venu \u00e9claircir cette histoire. La transcription de longs extraits de l\u2019autobiographie de Bernard Petit, <em>Secrets de flic<\/em>, publi\u00e9 en 2018 aux \u00e9ditions du Seuil, est ici incontournable.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"659\" src=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/bernard-petit-secrets-de-flic.jpg\" alt=\"\" class=\"wp-image-1645\" srcset=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/bernard-petit-secrets-de-flic.jpg 400w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/bernard-petit-secrets-de-flic-182x300.jpg 182w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_fevrier_2015_La_chute\"><\/span><strong>3 f\u00e9vrier 2015 : La chute<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u00ab&nbsp;C\u2019est un matin comme les autres. Je m\u2019arr\u00eate au Soleil d\u2019Or, la brasserie \u00e0 l\u2019angle du boulevard du Palais et du quai du March\u00e9-Neuf, tout pr\u00e8s du Quai des Orf\u00e8vres. Ignorant que ma fin est proche, je prends paisiblement mon caf\u00e9 du matin. Je prends le temps d\u2019engager une discussion avec mon voisin de bar. J\u2019ai toujours aim\u00e9 parler avec les gens crois\u00e9s par hasard. Anonyme parmi les anonymes. Je traverse le boulevard du Palais pour rejoindre le 36. Je salue le planton \u00e0 l\u2019entr\u00e9e.&nbsp;\u00bb (p. 51) (\u2026) \u00ab&nbsp;D\u00e9j\u00e0 9 heures, et c\u2019est la premi\u00e8re r\u00e9union de la journ\u00e9e&nbsp;: le directeur-adjoint, tous les sous-directeurs, le chef d\u2019\u00e9tat-major et le chef de cabinet sont l\u00e0 autour de la table pour faire un point sur l\u2019activit\u00e9 du moment. (\u2026) La r\u00e9union se d\u00e9roule ce jour-l\u00e0 comme d\u2019habitude, un peu r\u00e9p\u00e9titive, un rien monotone m\u00eame. (\u2026) Ce jour-l\u00e0, rien de sp\u00e9cial \u00e0 signaler. Me voil\u00e0 de retour quand le t\u00e9l\u00e9phone sonne. On m\u2019apprend qu\u2019un commissaire de la brigade criminelle vient de retrouver la moto de Coulibaly que nous n\u2019avons cess\u00e9 de chercher depuis l\u2019attentat de la porte de Vincennes. (\u2026) Je suis vraiment content que cette moto ait \u00e9t\u00e9 retrouv\u00e9e. Je t\u00e9l\u00e9phone aussit\u00f4t au procureur de Paris, Fran\u00e7ois Molins. Lorsqu\u2019il d\u00e9croche, je n\u2019ai pas le temps de placer un seul mot&nbsp;! Il semble encore moins disponible que d\u2019habitude, le ton est tr\u00e8s cassant&nbsp;: \u00ab\u00a0<em>Je suis tr\u00e8s occup\u00e9, je n\u2019ai pas le temps de vous parler\u00a0\u00bb<\/em>, et il raccroche. C\u2019est la premi\u00e8re fois qu\u2019il me rabroue ainsi. Je lui adresse aussit\u00f4t un SMS factuel&nbsp;: \u00ab\u00a0<em>Moto Coulibaly retrouv\u00e9e.\u00a0\u00bb<\/em> Un message rest\u00e9 sans r\u00e9ponse. J\u2019ai souvent repens\u00e9 \u00e0 l\u2019attitude du magistrat. S\u2019est-il m\u00e9pris sur l\u2019objet de mon appel&nbsp;? Craint-il que je ne sois en qu\u00eate de soutien&nbsp;? Ce qui est certain c\u2019est que Fran\u00e7ois Molins devait savoir, depuis plusieurs jours, que j\u2019allais \u00eatre interpell\u00e9 et poursuivi par la justice. A-t-il eu peur d\u2019\u00eatre \u00ab\u00a0sali\u00a0\u00bb par ce contact t\u00e9l\u00e9phonique avec moi&nbsp;? Lui seul peut le dire. Sur le moment je n\u2019ai pas compris. (\u2026) Je me pr\u00e9pare alors \u00e0 une nouvelle r\u00e9union. C\u2019est qu\u2019il est bient\u00f4t l\u2019heure du \u00ab\u00a0rapport\u00a0\u00bb chez le pr\u00e9fet de police, comme tous les lundi, mercredi et vendredi de chaque semaine. (..) Alors que je commence \u00e0 pr\u00e9parer mon dossier pour aller chez le pr\u00e9fet, j\u2019entends un brouhaha inhabituel au secr\u00e9tariat. Soudain, Christine entre dans mon bureau. Le visage livide, elle me dit&nbsp;: \u00ab\u00a0<em>Des juges et l\u2019IGPN, ils sont l\u00e0\u2026 pour vous\u2026\u00a0\u00bb<\/em> Je n\u2019ai pas le temps d\u2019ouvrir la bouche que des hommes surgissent derri\u00e8re elle. Je reconnais imm\u00e9diatement l\u2019un d\u2019entre eux&nbsp;: il est contr\u00f4leur g\u00e9n\u00e9ral de la police. En revanche, je n\u2019identifie pas les deux magistrats qui se pr\u00e9sentent \u00e0 moi. (\u2026) Ils m\u2019annoncent tout de go qu\u2019ils vont perquisitionner mon bureau dans le cadre d\u2019une enqu\u00eate pour \u00ab\u00a0violation du secret de l\u2019instruction\u00a0\u00bb. Je n\u2019en reviens pas, je ne comprends pas, je ne parviens m\u00eame pas \u00e0 r\u00e9aliser ce qui se passe. Ironie de notre \u00e9poque, la t\u00e9l\u00e9vision me ram\u00e8ne \u00e0 la r\u00e9alit\u00e9. Je vois en direct, simultan\u00e9ment \u00e0 ce que je suis en train de vivre, l\u2019annonce de la perquisition en cours dans mon bureau et des images de l\u2019entr\u00e9e du 36 (( Dans son interviou accord\u00e9e \u00e0 <em>Mediapart<\/em> le 20 juin 2018, Bernard Petit pr\u00e9cise qu\u2019il disposait d\u2019une t\u00e9l\u00e9 tr\u00e8s grand \u00e9cran dans son bureau et que son interpellation a forc\u00e9ment \u00e9t\u00e9 synchronis\u00e9e avec les M\u00e9dias qui ont pu la couvrir en direct. ))\u2026 Mon abattement est immense. Pourtant, \u00e0 ce moment-l\u00e0, je suis loin d\u2019imaginer toutes les cons\u00e9quences de cette \u00ab&nbsp;descente&nbsp;\u00bb. (\u2026) Durant la perquisition, j\u2019h\u00e9site \u00e0 faire appel \u00e0 un avocat. Un commandant de l\u2019IGPN l\u00e8ve ce doute et me glisse, discr\u00e8tement&nbsp;: \u00ab\u00a0<em>Oui, oui, appelez un avocat.<\/em> <em>\u00ab\u00a0<\/em> Je l\u2019interroge&nbsp;: \u00ab\u00a0<em>Mais c\u2019est grave \u00e0 ce point&nbsp;?<\/em> <em>\u00ab\u00a0<\/em> Son regard en dit long. Oui c\u2019est grave. (\u2026) [L\u2019avocate] ne tardera pas \u00e0 me rejoindre dans les locaux de l\u2019IGPN. C\u2019est l\u00e0-bas que je suis entendu. On m\u2019accorde un traitement moins humiliant que celui r\u00e9serv\u00e9 au commandant Richard Atlan, mon chef de cabinet et ami, dont j\u2019apprends qu\u2019il est lui aussi mis en cause pour les m\u00eames faits qui me sont reproch\u00e9s. A cet instant, je crois qu\u2019il est encore possible de s\u2019expliquer et je suis toujours loin d\u2019imaginer le sort qui va m\u2019\u00eatre r\u00e9serv\u00e9, tant sur le plan judiciaire qu\u2019administratif. (\u2026) Les questions pleuvent. Je suis, \u00e0 la fois, trop r\u00e9volt\u00e9 et abasourdi pour y r\u00e9pondre correctement. Et les auditions achoppent imm\u00e9diatement sur des points, qui avec le recul, me paraissent bien secondaires.&nbsp;\u00bb<\/p>\n\n\n\n<p>On lui apprend tout de m\u00eame le motif pr\u00e9cis de son placement en garde-\u00e0-vue&nbsp;: un certain Philippe Lema\u00eetre, lui aussi en garde-\u00e0-vue, l\u2019accuse de lui avoir r\u00e9v\u00e9l\u00e9 l\u2019existence d\u2019une enqu\u00eate judiciaire contre Christian Prouteau \u2013 que Petit assure ne pas conna\u00eetre \u2013 et d\u2019ainsi perturber le travail de la justice. Lors de la perquisition du bureau de Bernard Petit, les juges saisissent notamment sept pages manuscrites, qu\u2019il avait \u00e9crites la veille suite \u00e0 un \u00e9change de SMS avec la cheffe de l\u2019IGPN Marie-France Mon\u00e9ger, faisant le point sur \u00ab&nbsp;l\u2019affaire Prouteau&nbsp;\u00bb, du nom de l\u2019ancien officier de gendarmerie, devenu pr\u00e9fet, fondateur du GIGN et du GSPR, le groupe de s\u00e9curit\u00e9 du pr\u00e9sident de la R\u00e9publique. Avec d\u2019autres, Christian Prouteau est alors soup\u00e7onn\u00e9 d\u2019avoir tent\u00e9, contre paiement, de faire r\u00e9gulariser des situations administratives avec des titres de s\u00e9jour fragiles. Le nom de Philippe Lema\u00eetre, agent administratif du minist\u00e8re de l\u2019Int\u00e9rieur, que Petit conna\u00eet professionnellement depuis des ann\u00e9es, apparaissait dans cette instruction. Mme Mon\u00e9ger avait avis\u00e9 Bernard Petit par SMS le 2 f\u00e9vrier, la veille de son interpellation, que ses services avaient besoin de l\u2019entendre personnellement dans le cadre d\u2019une commission rogatoire, sans plus de pr\u00e9cisions. Devinant qu\u2019il ne pouvait s\u2019agir que de l\u2019affaire Prouteau, M. Petit avait aussit\u00f4t r\u00e9dig\u00e9 un m\u00e9mo tr\u00e8s d\u00e9taill\u00e9 pour tout expliquer, afin de limiter le nombre d\u2019auditions le ciblant.<\/p>\n\n\n\n<p>\u00ab&nbsp;Je passe la nuit en garde-\u00e0-vue. C\u2019est mauvais signe. Les enqu\u00eateurs m\u2019avisent que je serai pr\u00e9sent\u00e9 aux juges le lendemain. Je sais d\u00e8s lors qu\u2019on va me mettre en examen quoi qu\u2019il arrive. L\u2019\u00e9nergie de mon avocate ne changera rien \u00e0 mon destin. Comme pr\u00e9vu, je suis transf\u00e9r\u00e9 au palais de justice o\u00f9 l\u2019on me fait attendre longuement dans une cellule.(\u2026) Face aux magistrats, l\u2019interrogatoire de premi\u00e8re comparution se passe tr\u00e8s mal. J\u2019ai le sentiment que tout est d\u00e9j\u00e0 bien scell\u00e9, ficel\u00e9, et que rien ne modifiera leur point de vue. Mme Bilger se montre agressive, me semble-t-il, s\u2019emportant vite \u00e0 de nombreuses reprises. Nous nous heurtons sur la nature de ma relation avec Lema\u00eetre, et mon banal carnet de notes reste pour elle un agenda. Les magistrats reprennent l\u2019argumentaire de l\u2019IGPN. \u00ab\u00a0<em>M. Lema\u00eetre ne peut mentir puisqu\u2019il s\u2019accuse en m\u00eame temps, quel serait alors son mobile&nbsp;?<\/em> <em>\u00ab\u00a0<\/em> me demandent-ils. Je n\u2019ai pas \u00e0 r\u00e9pondre pour lui. Mais j\u2019imagine, sans rien en savoir, qu\u2019il tient peut-\u00eatre \u00e0 faire tomber d\u2019autres gens pour minimiser sa faute. Et moi quel serait mon mobile&nbsp;? Je ne le comprends qu\u2019\u00e0 travers des sous-entendus&nbsp;: ma pr\u00e9tendue ob\u00e9dience ma\u00e7onnique&nbsp;! Mais je n\u2019ai jamais \u00e9t\u00e9 franc-ma\u00e7on. Je ne sais pas encore aujourd\u2019hui comment on peut prouver, une bonne fois pour toutes, ne pas appartenir \u00e0 cette confr\u00e9rie. (\u2026) Je suis d\u2019autant plus furieux que l\u2019un des magistrats qui instruit mon dossier est r\u00e9put\u00e9 appartenir \u00e0 la Grande Loge Nationale de France. Il n\u2019en est pas pour autant coupable.&nbsp;\u00bb (p. 65)<\/p>\n\n\n\n<p>\u00ab&nbsp;Ma mise en examen acquise, une double sanction s\u2019abat sur moi. Imm\u00e9diatement et brutalement. Qui peut pr\u00e9tendre que la justice n\u2019est pas rapide&nbsp;? Quand je pense aux difficult\u00e9s multiples et vari\u00e9es que j\u2019ai souvent rencontr\u00e9es pour obtenir d\u2019un magistrat l\u2019autorisation d\u2019une \u00e9coute sur un malfaiteur notoire ou l\u2019incarc\u00e9ration d\u2019un trafiquant d\u2019armes ou de stups\u2026 Je suis plac\u00e9 sous contr\u00f4le judiciaire&nbsp;: je ne peux plus exercer d\u2019activit\u00e9 et tout contact avec des policiers m\u2019est formellement interdit. Lorsque je fais valoir aux juges qu\u2019ils me condamnent professionnellement, ils me r\u00e9pondent que l\u2019administration peut toujours m\u2019affecter dans d\u2019autres services&#8230; Ils sont bien les seuls \u00e0 y croire. Je ne suis \u00e9videmment pas dupe. Je suis mort. Ce qui va vite m\u2019\u00eatre confirm\u00e9, j\u2019apprends qu\u2019au sortir du conseil des ministres, le ministre Bernard Cazeneuve s\u2019est d\u00e9j\u00e0 exprim\u00e9 face aux cam\u00e9ras. Son intervention a tout du l\u00e2chage. \u00ab\u00a0<em>Si, au terme de ces gardes \u00e0 vue, il appara\u00eet que des manquements graves ont \u00e9t\u00e9 commis par des policiers ou d\u2019anciens policiers, je serai d\u2019une fermet\u00e9 absolue et je serai intraitable.\u00a0\u00bb<\/em> Promesse tenue. D\u00e8s ma sortie de chez les juges, tr\u00e8s tard dans la nuit, le ministre a d\u00e9j\u00e0 d\u00e9p\u00each\u00e9 ses deux \u00e9missaires&nbsp;: Jean-Louis Wiart, inspecteur g\u00e9n\u00e9ral, en charge des personnels de la pr\u00e9fecture de police, et Brigitte Lafourcade, contr\u00f4leur g\u00e9n\u00e9ral, en charge des ressources humaines \u00e0 la direction des ressources et des comp\u00e9tences de la police nationale. (\u2026) Avant qu\u2019ils ne scellent mon sort, j\u2019obtiens de pouvoir passer \u00e0 mon appartement de fonction pour prendre une douche et me changer. Je me sens sale, sale \u00e0 tous points de vue. (\u2026) Je dois maintenant quitter le miens. Je suis conduit \u00e0 \u00ab Lumi\u00e8re&nbsp;\u00bb, un immeuble moderne \u00e0 la fa\u00e7ade rouge, situ\u00e9 tout pr\u00e8s de la place de la Nation. C\u2019est l\u00e0 que se trouvent, entre autres, les locaux de la direction des ressources et des comp\u00e9tences de la police nationale. Je ne sais pas ce qui m\u2019attend. Il y a belle lurette qu\u2019il n\u2019y a personne dans les murs \u00e0 cette heure-l\u00e0&nbsp;! (\u2026) A mon arriv\u00e9e tout est ferm\u00e9 ou presque. (\u2026) [Lafourcade] est en mission. Elle me fait signer successivement trois documents&nbsp;: mon limogeage du poste de directeur, la fin de mon d\u00e9tachement comme contr\u00f4leur g\u00e9n\u00e9ral et, puisque je suis redevenu un simple commissaire divisionnaire, compte-tenu de mon \u00e2ge, ma mise \u00e0 la retraite imm\u00e9diate. En me pr\u00e9sentant ce dernier document, elle prend la peine d\u2019ajouter&nbsp;: \u00ab\u00a0<em>Et maintenant, voil\u00e0 le plus dur.\u00a0\u00bb<\/em> Puis elle me demande de restituer imm\u00e9diatement ma carte de police. Mon arme, quant \u00e0 elle a d\u00e9j\u00e0 \u00e9t\u00e9 saisie lors de la perquisition. La bo\u00eete de courrier \u00e9lectronique \u00e0 mon nom a \u00e9t\u00e9 instantan\u00e9ment ferm\u00e9e&nbsp;: je n\u2019aurai jamais l\u2019occasion de m\u2019adresser aux personnels du 36. Sans t\u00e9l\u00e9phone, sans ordinateur, le tout promptement saisi par la justice, je me sens comme nu. En quelques heures, je ne suis plus rien. (\u2026) Dans les jours et semaines qui suivent, mon seul contact avec la vie administrative est le pr\u00e9fet de police Bernard Boucaut (( \u0002 Bernard Boucault a \u00e9t\u00e9 pr\u00e9fet de Police de Paris du 31 mai 2012 au 9 juillet 2015, date \u00e0 laquelle il sera remplac\u00e9 par Michel Cadot. Le nom du pr\u00e9fet Boucault n\u2019appara\u00eet qu\u2019une seule fois dans le rapport de la commission d\u2019enqu\u00eate parlementaire sur les attentats de 2015, lors de l\u2019audition du patron du RAID Jean-Michel Fauvergue. \u00ab <strong>J-M Fauvergue&nbsp;:<\/strong>&nbsp;la FIPN a \u00e9t\u00e9 d\u00e9clench\u00e9e en janvier, ce qui m\u2019a sembl\u00e9 la meilleure des choses. Or, lors d\u2019une r\u00e9union de d\u00e9briefing organis\u00e9e avec le DGPN et le pr\u00e9fet de police quelques jours plus tard, ce dernier a d\u00e9clar\u00e9 n\u2019avoir pas compris pourquoi le RAID \u00e9tait venu sur l\u2019Hyper cacher, le besoin ne s\u2019en \u00e9tant pas fait ressentir. <strong>M. Pascal Popelin. <\/strong>Il s\u2019agit du pr\u00e9fet Boucault\u2026 <strong>M. Jean-Michel Fauvergue.<\/strong> Cela m\u2019a beaucoup vex\u00e9, mais il \u00e9tait pr\u00e9fet, et je n\u2019ai rien dit.&nbsp;\u00bb Bernard Boucault rejoint Bernard Petit dans la charrette d\u2019infamie en juillet 2015, <a href=\"https:\/\/www.lesalonbeige.fr\/bernard-boucault-dans-une-tourmente-judiciaire\/\">quand la presse annonce qu\u2019il est m\u00eal\u00e9 au m\u00eame trafic d\u2019influence<\/a>, l\u2019affaire Prouteau, dans laquelle Bernard Petit a \u00e9t\u00e9 m\u00eal\u00e9 \u00e0 la p\u00e9riph\u00e9rie \u2013 les deux m\u00eames juges \u00e9tant \u00e0 la baguette. Proche de Fran\u00e7ois Hollande, il aurait d\u00fb partir en retraite en 2013 mais avait b\u00e9n\u00e9fici\u00e9 d\u2019une d\u00e9rogation exceptionnelle. Ces r\u00e9v\u00e9lations entra\u00eenent sa d\u00e9mission et son remplacement par Michel Cadot. )). Il me propose de venir d\u00e9jeuner avec lui \u00e0 la pr\u00e9fecture, mais je d\u00e9cline. Je n\u2019arrive pas \u00e0 surmonter mon malaise lorsque je passe aux abords de ce lieu. Nous convenons de nous rencontrer plut\u00f4t dans un restaurant du XVII<sup>\u00e8me<\/sup> arrondissement, loin de l\u2019\u00eele de la Cit\u00e9. Le pr\u00e9fet me conseille de demander ma r\u00e9int\u00e9gration. Je suis abasourdi. Pourquoi en effet demander cela \u00e0 un ministre qui vous a ex\u00e9cut\u00e9 sur la place publique&nbsp;? Bernard Boucault de fait rassurant&nbsp;: il m\u2019assure que si je formule une telle demande, j\u2019obtiendrais une r\u00e9ponse positive. L\u2019administration me trouvera alors un poste \u00e0 l\u2019\u00e9tranger, m\u00eame si je dois affronter, pour cela, une commission de discipline. Toujours est-il que je ferai finalement cette demande, et comme annonc\u00e9 par le pr\u00e9fet, la r\u00e9ponse sera imm\u00e9diatement positive. C\u2019est irr\u00e9el. Me voil\u00e0 r\u00e9int\u00e9gr\u00e9, mais comme commissaire divisionnaire de 6\u00b0 \u00e9chelon. En clair&nbsp;: une dizaine d\u2019ann\u00e9es de travail ont \u00e9t\u00e9 effac\u00e9es. (\u2026) Ma vie professionnelle et sociale est d\u00e9truite. Je n\u2019ai plus de raison d\u2019\u00eatre. Cette sale petite musique m\u2019obs\u00e8de jour et nuit. J\u2019ai \u00e9t\u00e9 l\u00e2ch\u00e9 par tout le monde. D\u2019un c\u00f4t\u00e9 il y a Bernard Cazeneuve qui, \u00e0 l\u2019Int\u00e9rieur, est soucieux d\u2019\u00e9liminer ce qui rappelle Manuel Valls (( On peut relever dans les m\u00e9dias des indices d\u2019une distance entre les deux hommes, par ex <a href=\"https:\/\/www.lexpress.fr\/actualite\/politique\/elections\/remaniement-les-piques-meprisantes-de-valls-a-cazeneuve_1857700.html\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a>, <a href=\"https:\/\/www.liberation.fr\/france\/2016\/07\/17\/valls-cazeneuve-un-numero-de-duellistes_1466813\/\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a>, <a href=\"https:\/\/www.planet.fr\/politique-manuel-valls-letrange-surnom-quil-donnait-a-bernard-cazeneuve.1267348.29334.html\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a> )), et c\u2019est ce dernier qui m\u2019avait nomm\u00e9&nbsp;; de l\u2019autre, les cadors de la \u00ab\u00a0firme\u00a0\u00bb, les bras arm\u00e9s de Nicolas Sarkozy, qui ne m\u2019ont jamais pardonn\u00e9 d\u2019\u00eatre devenu patron du 36 en lieu et place d\u2019un des leurs. Il fallait absolument m\u2019\u00e9liminer. Comme dans une conjuration des contraires. Durant ces jours sombres, j\u2019ai subi un v\u00e9ritable lynchage m\u00e9diatique, aliment\u00e9 par les fuites, des violations flagrantes et r\u00e9p\u00e9t\u00e9es du secret de l\u2019instruction. Qui les a donc orchestr\u00e9es&nbsp;? Je m\u2019en plains verbalement aupr\u00e8s des magistrats. Il m\u2019est r\u00e9pondu que c\u2019est d\u00e9sormais le cas dans toutes les affaires. Et que les indiscr\u00e9tions peuvent venir de n\u2019importe o\u00f9 et de n\u2019importe qui&nbsp;: des magistrats du parquet, des policiers de l\u2019IGPN, et m\u00eame du cabinet du ministre\u2026 Une banalisation que j\u2019avoue avoir du mal \u00e0 comprendre et, plus encore, \u00e0 admettre&nbsp;: la violation du secret de l\u2019instruction, n\u2019est-ce pas ce que l\u2019on me reproche si injustement&nbsp;?&nbsp;\u00bb (p. 70)<\/p>\n\n\n\n<p>Bernard Petit ne manque pas dans son ouvrage de replacer cette \u00e9radication professionnelle dans le contexte de sa nomination \u00e0 la t\u00eate du 36 quai des Orf\u00e8vres en d\u00e9cembre 2013. Depuis plus d\u2019un an, en effet, les affaires d\u00e9stabilisantes hors-normes et les coups fourr\u00e9s en interne avaient \u00e9t\u00e9 nombreux, comme des augures de ce qui lui tombera sur la t\u00eate le 3 f\u00e9vrier 2015,.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Un_exercice_perturbe_par_les_affaires_et_les_destabilisations\"><\/span><strong>Un exercice perturb\u00e9 par les affaires et les d\u00e9stabilisations<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Deux_affaires_retentissantes_un_viol_et_un_vol_de_52_kg_de_cocaine_dans_les_locaux_de_la_PJ\"><\/span><strong>Deux affaires retentissantes&nbsp;: un viol et un vol de 52 kg de coca\u00efne dans les locaux de la PJ<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Premi\u00e8re affaire&nbsp;: en avril 2014, une touriste canadienne accuse des fonctionnaires de la BRI de l\u2019avoir viol\u00e9e dans les locaux de cette unit\u00e9. Avant m\u00eame son \u00e9lucidation, et alors que Bernard Petit lui-m\u00eame ne conna\u00eet rien du d\u00e9tail des faits, l\u2019affaire fait grand bruit dans la presse. Mis sous pression par le pr\u00e9fet de police Bernard Boucault, il parvient \u00e0 sauver la t\u00eate de Christophe Molmy, r\u00e9cemment nomm\u00e9 \u00e0 la t\u00eate de la BRI-PP, et de son adjoint George Salinas, et se rend sur <em>Europe 1<\/em> pour condamner publiquement ces agissements inacceptables. \u00ab&nbsp;Plus tard, conclut Petit, le pr\u00e9fet me l\u00e2chera&nbsp;:<em> \u00ab\u00a0il faut tenir vos hommes&nbsp;!\u00a0\u00bb <\/em>La remarque me blesse. Elle est particuli\u00e8rement injuste. J\u2019ai conscience que cette affaire m\u2019affaiblit.&nbsp;\u00bb (p. 83)<\/p>\n\n\n\n<p>Seconde affaire&nbsp;: beaucoup plus grave et terrible en terme d\u2019image, \u00ab&nbsp;<em>c\u2019est dans ce contexte qu\u2019intervient une seconde affaire, tout aussi d\u00e9sagr\u00e9able, rocambolesque et pr\u00e9judiciable. Dans la nuit du 24 au 25 juillet 2014, cinquante-deux kilos de coca\u00efne sont vol\u00e9s dans la salle [des scell\u00e9s] de la Brigade des stups.<\/em>&nbsp;\u00bb Le brigadier Jonathan Guyot, accus\u00e9 d\u2019\u00eatre \u00e0 l\u2019origine du vol, est rapidement confondu et arr\u00eat\u00e9 ((  2017 \u00e0 10 ans de prison, la peine maximale pour ce genre de d\u00e9lit. Les 50 kilos de coca\u00efne, d\u2019une valeur de deux millions d\u2019euros, n\u2019ont jamais \u00e9t\u00e9 retrouv\u00e9s. Il a \u00e9t\u00e9 reconnu sur les cam\u00e9ras de vid\u00e9osurveillance par les plantons et plusieurs membres de sa hi\u00e9rarchie, malgr\u00e9 sa casquette et son \u00e9pais blouson. Il aurait sorti la coca\u00efne en trois fois. )). Quoique Bernard Petit n\u2019y soit pour rien, le scandale est immense et rejaillit encore sur lui&nbsp;: \u00ab&nbsp;<em>ces affaires in\u00e9dites au 36 m\u2019ont incontestablement fragilis\u00e9. Je suis devenu une cible vuln\u00e9rable. Surtout pendant cette p\u00e9riode pr\u00e9-\u00e9lectorale.<\/em>&nbsp;\u00bb D\u2019autant que certains m\u00e9dias, manifestement en service command\u00e9, ne se privent pas d\u2019exploiter imm\u00e9diatement l\u2019affaire pour la lui mettre sur le dos&nbsp;: \u00ab&nbsp;<em>C\u2019est le moment que choisit Valeurs actuelles, qui soutient alors ouvertement Nicolas Sarkozy, pour m\u2019accuser de faire partie d\u2019un cabinet noir. (\u2026) L\u2019hebdomadaire, situ\u00e9 \u00e0 la droite de la droite, ne fait pas dans la dentelle et me d\u00e9signe comme \u00ab\u00a0le responsable police\u00a0\u00bb de cette cellule clandestine. Je suis scandalis\u00e9 et j\u2019en obtiendrai r\u00e9paration en justice.&nbsp;<\/em>\u00bb (p. 86)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Destabilisations\"><\/span><strong>D\u00e9stabilisations<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Les d\u00e9stabilisations ont commenc\u00e9 en fait d\u00e8s son installation \u00e0 la t\u00eate du 36 quai des Orf\u00e8vres. L\u2019origine est \u00e0 en chercher dans la fa\u00e7on dont il a \u00e9t\u00e9 nomm\u00e9 en remplacement de Christian Flaesch, brutalement d\u00e9barqu\u00e9 par Manuels Valls, ce qui l\u2019a fait soup\u00e7onner d\u2019avoir particip\u00e9 \u00e0 un complot ourdi par un camp politique ennemi des sarkozystes dont le 36 quai des Orf\u00e8vres \u00e9tait truff\u00e9, et fait aussit\u00f4t na\u00eetre l\u2019envie et sans doute les projets d\u2019avoir sa peau t\u00f4t ou tard. Bernard Petit raconte que le champagne a \u00e9t\u00e9 sabr\u00e9 le jour de sa disgr\u00e2ce au 36 quai des Orf\u00e8vres. Il donne dans son ouvrage plusieurs exemples de d\u00e9stabilisations.<\/p>\n\n\n\n<p>Premier exemple&nbsp;: dans les premiers jours de son installation il re\u00e7oit en rendez-vous l\u2019un des responsables de la gestion de la PJ pour \u00e9voquer avec lui sa future mutation dont il a fait la demande et que Bernard Petit peut lui confirmer quoiqu\u2019il n\u2019en soit pas responsable. \u00ab&nbsp;Au moment de sortir de mon bureau, il para\u00eet h\u00e9siter. Je l\u2019interroge&nbsp;:<\/p>\n\n\n\n<p>\u00ab<em>&nbsp;Vous avez chang\u00e9 d\u2019avis&nbsp;?<\/em><\/p>\n\n\n\n<p><em>&#8211; Non, pas du tout, monsieur le directeur\u2026<\/em><\/p>\n\n\n\n<p><em>&#8211; Vous avez oubli\u00e9 quelque chose&nbsp;?<\/em><\/p>\n\n\n\n<p><em>&#8211; Non, monsieur le directeur. Je voulais simplement vous pr\u00e9venir. Attention \u00e0 vos d\u00e9penses. A la pr\u00e9fecture, quelqu\u2019un suit de pr\u00e8s vos d\u00e9bits de carte bleue et les commente \u00e0 haute voix.<\/em><\/p>\n\n\n\n<p><em>&#8211; Mais qui, bon sang&nbsp;? Et Pourquoi&nbsp;?<\/em><\/p>\n\n\n\n<p><em>&#8211; Je ne peux pas vous dire. Simplement, faites attention&#8230;<\/em>&nbsp;\u00bb (p. 75)<\/p>\n\n\n\n<p>Second exemple, \u00e0 peine croyable&nbsp;: \u00ab<em>&nbsp;Quelques semaines plus tard, un nouvel avertissement m\u2019est adress\u00e9. Lors d\u2019une de nos multiples r\u00e9unions destin\u00e9es \u00e0 faire le point sur les enqu\u00eates en cours, le procureur de Paris m\u2019interroge sur le dossier Aristophil. Cette soci\u00e9t\u00e9, fond\u00e9e en 1990, est sp\u00e9cialis\u00e9e dans l\u2019expertise et le commerce de lettres autographes et de manuscrits originaux du patrimoine \u00e9crit. Elle vend notamment des parts dans la possession de ces documents. Son succ\u00e8s est tel qu\u2019elle ouvre des filiales en Belgique, en Suisse, en Autriche et m\u00eame \u00e0 Hong Kong. Parall\u00e8lement \u00e0 cette activit\u00e9, son fondateur, G\u00e9rard L\u2019h\u00e9ritier, cr\u00e9e en 2004, \u00e0 Paris, le Mus\u00e9e des lettres et des manuscrits. Six cents m\u00e8tres carr\u00e9s situ\u00e9s boulevard Saint-Germain, au c\u0153ur du Paris intellectuel. Les plus hautes autorit\u00e9s de l\u2019\u00c9tat visitent ce lieu, dont le parrain n\u2019est autre que Patrick Poivre d\u2019Arvor, et l\u2019un des principaux financiers, la Soci\u00e9t\u00e9 G\u00e9n\u00e9rale. Des milliers d\u2019\u00e9pargnants placent ainsi leur argent dans ce qui est pr\u00e9sent\u00e9 comme un bon investissement, en achetant en pleine propri\u00e9t\u00e9 ou en indivision des documents rares. Pourtant, courant 2014, une enqu\u00eate est ouverte sur les agissements de cette soci\u00e9t\u00e9. Elle est confi\u00e9e \u00e0 la brigade de la r\u00e9pression de la d\u00e9linquance \u00e9conomique de la police judiciaire. En m\u2019interrogeant, Fran\u00e7ois Molins veut savoir si cette enqu\u00eate s\u2019oriente vers une arnaque \u00e0 la Madoff, une sorte de \u00ab\u00a0pyramide de Ponzi\u00a0\u00bb des belles lettres. Autrement dit&nbsp;: \u00ab\u00a0les achats des uns servent-ils \u00e0 financer les int\u00e9r\u00eats et le remboursement des autres&nbsp;?\u00a0\u00bb Je lui r\u00e9ponds beno\u00eetement n\u2019en rien savoir. Les investigations sont en cours, perquisitions et autres saisies d\u2019\u00e9l\u00e9ments comptables pourront sans doute nous \u00e9clairer. Molins me presse alors d\u2019acc\u00e9l\u00e9rer l\u2019enqu\u00eate. Mon sous-directeur aux affaires \u00e9conomiques et financi\u00e8res en a la responsabilit\u00e9. Je laisse donc Gilles Aubry man\u0153uvrer. Un matin, il vient me trouver. D\u2019ordinaire souriant, il pr\u00e9sente un visage inhabituel&nbsp;:<\/em><\/p>\n\n\n\n<p><em>\u00ab&nbsp;Que se passe-t-il, Gilles&nbsp;?<\/em><\/p>\n\n\n\n<p><em>&#8211; Tu as d\u00e9j\u00e0 \u00e9t\u00e9 au mus\u00e9e du livre&nbsp;?<\/em><\/p>\n\n\n\n<p><em>&#8211; Non, je ne sais m\u00eame pas o\u00f9 c\u2019est. Pourquoi me demandes-tu \u00e7a&nbsp;?<\/em><\/p>\n\n\n\n<p><em>&#8211; Tu connais le patron d\u2019Aristophil&nbsp;?<\/em><\/p>\n\n\n\n<p><em>&#8211; Ni lui ni aucun de ses employ\u00e9s. O\u00f9 veux-tu en venir&nbsp;?&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><em>Embarrass\u00e9, Gilles m\u2019explique que, lors d\u2019une perquisition, ses hommes ont d\u00e9couvert un mot sign\u00e9 de ma main dans le livre d\u2019or de l\u2019\u00e9tablissement. Il fait peu de doute dans mon esprit qu\u2019il s\u2019agit d\u2019un acte malveillant. Je comprends aussi, que, s\u2019il en parle, c\u2019est que t\u00f4t ou tard cette information sera dans la proc\u00e9dure et peut-\u00eatre d\u2019ici peu dans la presse. J\u2019imagine d\u00e9j\u00e0 avec angoisse le titre de l\u2019article du Canard encha\u00een\u00e9&nbsp;!<\/em><\/p>\n\n\n\n<p><em>\u00ab&nbsp;Mais Gilles, dans ton mus\u00e9e, il y a bien des cam\u00e9ras de surveillance&nbsp;?&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p><em>Gilles Aubry est un pro, il a d\u00e9j\u00e0 fait bloquer les bandes enregistr\u00e9es. Dans les quarante-huit heures qui suivent, il m\u2019informe par t\u00e9l\u00e9phone qu\u2019on a trouv\u00e9 \u00ab&nbsp;le coupable&nbsp;\u00bb, un commandant de police de sa sous-direction. Celui-ci reconna\u00eet avoir \u00e9crit le mot sign\u00e9 sous mon nom. J\u2019exige aussit\u00f4t qu\u2019un rapport me soit adress\u00e9 par la voix hi\u00e9rarchique. Le document que je re\u00e7ois comprend plusieurs pages tr\u00e8s bien \u00e9crites. L\u2019essentiel est consacr\u00e9 \u00e0 d\u00e9crire la situation et l\u2019attitude d\u2019un repr\u00e9sentant du parquet venu sur place, lequel se serait montr\u00e9 bougon et peu enthousiaste quant \u00e0 sa participation \u00e0 l\u2019op\u00e9ration. Seul, le dernier feuillet de l\u2019article aborde l\u2019\u00e9criture en catimini et sous mon nom du fameux mot dans le livre d\u2019or. On croit comprendre que le commandant s\u2019est laiss\u00e9 aller \u00e0 \u00e9crire un mot suppos\u00e9 humoristique pour tromper le temps. Je n\u2019en reviens pas. Je veux rencontrer ce fonctionnaire qui s\u2019amuse \u00e0 \u00e9crire en mon nom. Quand il se pr\u00e9sente \u00e0 moi, accompagn\u00e9 de ses sup\u00e9rieurs, je constate que c\u2019est un vieux soldat, le regard fuyant, qui n\u2019arrive pas \u00e0 me donner une explication coh\u00e9rente. J\u2019en parle au procureur de Paris. Fran\u00e7ois Molins prend le temps de lire le rapport du fonctionnaire de police que je lui tends. Il s\u2019attarde sur les passages concernant l\u2019attitude de son collaborateur mais ne me semble pas pr\u00eater attention au feuillet me concernant\u2026 Affaire class\u00e9e.<\/em>&nbsp;\u00bb (p. 75 \u00e0 78)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mai_2021_le_proces_a_venir_de_Bernard_Petit\"><\/span><strong>Mai 2021 : le proc\u00e8s \u00e0 venir de Bernard Petit ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Dans <a href=\"https:\/\/www.youtube.com\/watch?v=IlRs2yEXw5Q\" target=\"_blank\" rel=\"noreferrer noopener\">l&rsquo;une des tr\u00e8s rares intervious de fond<\/a> que les m\u00e9dias lui ont consacr\u00e9 lors de la sortie de son livre, Bernard Petit explique face \u00e0 Edwy Plenel pour Mediapart (( Ceux qui auront la curiosit\u00e9 de regarder cette entretien se rendront assez vite compte que la motivation principale qui a pouss\u00e9 Edwy Plenel \u00e0 interviouver Bernard Petit, au-del\u00e0 du souci de r\u00e9tablir la v\u00e9rit\u00e9, est la charge indirecte de Bernard Petit dans son livre contre les r\u00e9seaux sarkozystes, cible obsessionnelle de M\u00e9diapart et d\u2019Edwy Plenel. )), le 20 juin 2018, qu&rsquo;\u00e0 cette date, il attendait toujours la tenue de son proc\u00e8s pour qu&rsquo;il puisse enfin se d\u00e9fendre dans un cadre a priori impartial. Ces trois ans et demi d&rsquo;attente sont bien \u00e9videmment \u00e0 mettre en regard des trois journ\u00e9es au cours desquelles il a tout perdu, ce qu&rsquo;il appelle, pour reprendre son expression \u00e9vocatrice, la \u00ab\u00a0bombe thermonucl\u00e9aire\u00a0\u00bb qui lui est tomb\u00e9e dessus. Il semble finalement, si l&rsquo;on en croit une s\u00e9rie d&rsquo;articles parus en mai 2021, que le parquet ait enfin jug\u00e9 opportun d\u2019approfondir cette affaire, pour \u00e9tablir si oui ou non, le traitement de choc r\u00e9serv\u00e9 \u00e0 Bernard Petit, et une douzaine d&rsquo;autres pr\u00e9venus parmi lesquels son directeur de cabinet Richard Atlan et du syndicaliste, pr\u00e9sident de l&rsquo;Anas, Joaquin Masanet, qui g\u00e8re les \u0153uvres sociales de la police, \u00e9tait m\u00e9rit\u00e9. Mieux vaut tard que jamais, dit le dicton. Six ans, ce n&rsquo;est apr\u00e8s tout qu&rsquo;une ann\u00e9e suppl\u00e9mentaire par rapport aux dix inculp\u00e9s du massacre de Charlie Hebdo et de la prise d&rsquo;otages de l&rsquo;Hyper Cacher, rest\u00e9s pour certains en d\u00e9tention provisoire pendant plus de cinq ans&nbsp;: ce que le syst\u00e8me judiciaire fran\u00e7ais si performant permet d\u00e8s lors qu&rsquo;il s&rsquo;agit d&rsquo;affaires traitant de faits de terrorisme.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"L\u2019ex-directeur de la PJ raconte ses \u00absecrets de flic\u00bb\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/IlRs2yEXw5Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.lefigaro.fr\/flash-actu\/fuites-au-quai-des-orfevres-le-parquet-reclame-de-nouveau-un-proces-pour-l-ex-patron-de-la-pj-20210527\" target=\"_blank\" rel=\"noreferrer noopener\">Dans une d\u00e9p\u00eache AFP du 27 mai 2021<\/a>, on apprend ainsi que \u00ab\u00a0<em>Le parquet de Paris demande \u00e0 nouveau le renvoi en correctionnelle de l&rsquo;ex-patron de la PJ parisienne et de 12 autres personnes dans l&rsquo;affaire des fuites au \u00ab36\u00bb qui avait \u00e9branl\u00e9 l&rsquo;institution polici\u00e8re en 2015, d&rsquo;apr\u00e8s une source proche du dossier, confirmant une information du Parisien.<\/em>\u00ab\u00a0<\/p>\n\n\n\n<p>Cette demande intervient trois ann\u00e9es apr\u00e8s que le minist\u00e8re public ait rendu, le 12 avril 2018, ses premi\u00e8res r\u00e9quisitions, qui r\u00e9clamaient notamment un proc\u00e8s en correctionnelle pour Petit et Masanet pour \u00ab\u00a0violation du secret de l&rsquo;instruction\u00a0\u00bb. Si l&rsquo;on se base sur le rythme auquel l&rsquo;affaire progresse depuis f\u00e9vrier 2015, avec un sas juridique franchi tous les trois ans, on peut estimer que le proc\u00e8s de Bernard Petit devrait se tenir \u00e0 l&rsquo;horizon du printemps 2024. Entre-temps, Bernard Petit \u2013 ce que laissait augurer les ind\u00e9niables qualit\u00e9s litt\u00e9raires de son autobiographie <em>Secrets de flic<\/em>, s&rsquo;est lanc\u00e9 avec succ\u00e8s dans le roman policier, avec un premier ouvrage du genre, <em>La traque<\/em>, publi\u00e9 aux \u00e9ditions Fleuve noir, plut\u00f4t bien re\u00e7u par la critique.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/la-traque-bernard-petit-683x1024.jpg\" alt=\"\" class=\"wp-image-1644\" width=\"499\" height=\"748\" srcset=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/la-traque-bernard-petit-683x1024.jpg 683w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/la-traque-bernard-petit-200x300.jpg 200w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/la-traque-bernard-petit-768x1152.jpg 768w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/la-traque-bernard-petit.jpg 800w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption><em>La traque<\/em> de Bernard Petit, publi\u00e9 en 2021 aux \u00e9ditions Fleuvenoir<\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span><strong>Conclusion<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Tant que des fonctionnaires coupables de d\u00e9cisions d\u00e9sastreuses, par incomp\u00e9tence ou duplicit\u00e9, seront sciemment couverts \u2013 comme dans le cas de l\u2019abaissement \u00e0 tous les niveaux de la s\u00e9curit\u00e9 de Charlie Hebdo les semaines et les mois pr\u00e9c\u00e9dant les attentats, ou de l\u2019ordre r\u00e9it\u00e9r\u00e9 de non intervention au Bataclan donn\u00e9 \u00e0 la BI \u2013 tant que les fonctionnaires les plus comp\u00e9tents et les plus exp\u00e9riment\u00e9s seront mut\u00e9s ou limog\u00e9s en plein milieu des temp\u00eates (Jean-Michel Fauvergue, Bernard Petit, Marc Tr\u00e9vidic (( Marc Tr\u00e9vidic a offici\u00e9 en tant que juge d&rsquo;instruction au p\u00f4le antiterrorisme du tribunal de grande instance de Paris de 2006 \u00e0 2015. Il doit quitter ce poste le 25 ao\u00fbt 2015, en raison de la limite impos\u00e9e de dix ann\u00e9es pour occuper un tel poste. Il n&rsquo;y aurait pas de pol\u00e9mique si en ao\u00fbt 2015, Marc Tr\u00e9vidic n&rsquo;avait re\u00e7u des informations tr\u00e8s cr\u00e9dibles faisant \u00e9tat d&rsquo;un prochain attentat dans une salle de concert parisienne&nbsp;: son remplacement pendant cette p\u00e9riode cruciale de la pr\u00e9paration des attentats du 13 novembre a forc\u00e9ment affaibli la vigilance et la r\u00e9activit\u00e9 du p\u00f4le antiterrorisme. Nous avons racont\u00e9 plus en d\u00e9tails cette pol\u00e9mique dans notre article <a href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/10\/28\/72x15-lequation-interdite-des-attentats-du-13-novembre-2-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">7+2+x=15&nbsp;: l&rsquo;\u00e9quation interdite des attentats du 13 novembre<\/a>. ))), pour des pr\u00e9textes captieux, le respect fanatique des proc\u00e9dures administratives, voire dans le cadre de missions de sabotage&nbsp;; tant que les medias unanimes dans toutes les circonstances de ce genre couvriront en complices ces scandales, tout en allumant des contrefeux pour inviter le b\u00e9tail d\u00e9mocratique \u00e0 regarder vers une autre direction de l\u2019enclos, toutes les lois antiterroristes du monde, d\u2019une s\u00e9v\u00e9rit\u00e9 croissante, ne pourront avoir aucune esp\u00e8ce d\u2019utilit\u00e9, les \u00ab&nbsp;d\u00e9mocraties&nbsp;\u00bb demeureront vuln\u00e9rables, et les \u00ab&nbsp;complotistes&nbsp;\u00bb auront raison de nourrir une m\u00e9fiance syst\u00e9matique envers les autorit\u00e9s, et de tenter d\u2019exposer sur la place publique par tous les moyens ces incuries o\u00f9 ces duplicit\u00e9s aux yeux de leurs concitoyens anesth\u00e9si\u00e9s par la propagande et l\u2019ing\u00e9nierie sociale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Addendum_le_point_de_vue_de_Bernard_Petit_sur_le_massacre_de_Charlie_Hebdo_et_le_mystere_des_freres_Kouachi\"><\/span><strong>Addendum&nbsp;: le point de vue de Bernard Petit sur le massacre de Charlie Hebdo et le myst\u00e8re des fr\u00e8res Kouachi<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Il nous semble utile, dans la perspective de notre ouvrage sur<a href=\"https:\/\/www.leretourauxsources.com\/ingenierie-sociale\/165-massacre-de-charlie-hebdo-l-enquete-impossible.html\" target=\"_blank\" rel=\"noreferrer noopener\"> <em>le massacre de Charlie Hebdo, l\u2019enqu\u00eate impossible<\/em><\/a>, de livrer le point de vue Bernard Petit sur l\u2019enqu\u00eate sur le massacre de Charlie Hebdo, point de vue d\u2019autant plus int\u00e9ressant qu\u2019avons-nous vu, il y a particip\u00e9 aux premi\u00e8res loges, et le moins que l\u2019on puisse dire, c\u2019est que l\u2019homme est dubitatif sur le caract\u00e8re \u00e9ternel de la version officielle de cet \u00e9v\u00e9nement. C\u2019est l\u2019ex patron de la PJ, en poste au moment de ces \u00e9v\u00e9nements, qui pose ces questions&nbsp;! toujours face \u00e0 Edwy Plenel, questions que d\u2019aucuns qualifieraient de \u00ab&nbsp;complotistes&nbsp;\u00bb, mais qui finalement ne sont pas tr\u00e8s diff\u00e9rentes de celles que se pose la veuve de l\u2019avocat du garde du corps de Charb, Ingrid Brinsolaro, la veuve de George Wolinski, Maryse Wolinski, et plus r\u00e9cemment encore, la m\u00e8re de Charb Denise Charbonnier dans son ouvrage <em>Lettre \u00e0 mon fils Charb, <\/em>publi\u00e9 en avril 2021 aux \u00e9ditions JC Latt\u00e8s.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/lettre-a-mon-fils-Charb-denise-charbonnier-636x1024.jpg\" alt=\"\" class=\"wp-image-1643\" width=\"511\" height=\"822\" srcset=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/lettre-a-mon-fils-Charb-denise-charbonnier-636x1024.jpg 636w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/lettre-a-mon-fils-Charb-denise-charbonnier-186x300.jpg 186w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/lettre-a-mon-fils-Charb-denise-charbonnier-768x1236.jpg 768w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/lettre-a-mon-fils-Charb-denise-charbonnier-954x1536.jpg 954w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/lettre-a-mon-fils-Charb-denise-charbonnier-1273x2048.jpg 1273w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/lettre-a-mon-fils-Charb-denise-charbonnier.jpg 1400w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/><figcaption>Dans \u00ab\u00a0lettre \u00e0 mon fls Charb\u00a0\u00bb, la m\u00e8re de St\u00e9phane Charbonnier, questionne ouvertement, de fa\u00e7on lancinante, l&rsquo;abaissement de la s\u00e9curit\u00e9 de <em>Charlie Hebdo <\/em>dans les semaines et les mois pr\u00e9c\u00e9dant le massacre, d\u00e9plorant n&rsquo;avoir jamais re\u00e7u le moindre \u00e9claircissement \u00e0 ce sujet (p. 27, 70 \u00e0 75, 77, 78, 121, 122, 127, 134, 155, 160, <\/figcaption><\/figure><\/div>\n\n\n\n<p>\u00ab Bernard Petit&nbsp;:&nbsp;<em>Vous savez, j\u2019ai enqu\u00eat\u00e9 sur l\u2019affaire Charlie Hebdo, Coulibaly, Kouachi, etc., \u00e7a m\u2019a beaucoup frapp\u00e9 de voir, une fois qu\u2019on a identifi\u00e9 les Kouachi, il nous est tomb\u00e9 des notes et des notes de renseignement sur eux. On savait tout d\u2019eux (\u2026) Ce qui est int\u00e9ressant c\u2019est de se dire&nbsp;: ils ont \u00e9t\u00e9 d\u00e9tect\u00e9s, comment c\u2019est possible qu\u2019il y ait personne derri\u00e8re eux (sourire incr\u00e9dule)&nbsp;? C\u2019est \u00e7a la vraie question&nbsp;! C\u2019est pas \u00ab&nbsp;Ah les fich\u00e9s S, le fichier pour la pr\u00e9vention du terrorisme, de la radicalit\u00e9&#8230;&nbsp;\u00bb. Non, la question, c\u2019est, une fois que vous avez le renseignement, et si vous \u00eates convaincus que vous ne faites pas du renseignement pour du renseignement, c\u2019est qui est derri\u00e8re&nbsp;? Et le hic il est l\u00e0 parce que l\u00e0 c\u2019est une question de moyens. [Plenel s\u2019\u00e9tonne et lui demande pourquoi il n\u2019y pas eu de d\u00e9briefing et pourquoi il n\u2019y a pas eu de commission parlementaire (sic!), pour comprendre\u2026 \u00ab&nbsp;Pourquoi est-ce qu\u2019on a mis tout de suite un couvercle&nbsp;?&nbsp;\u00bb] Parce qu\u2019on est tous dans des postures, et on a cette b\u00eatise de ne pas parler aux gens, aux citoyens, normalement. Il est \u00e9vident que si vous regardez l\u2019affaire des Kouachi, ces types-l\u00e0 se sont arm\u00e9s, ils se sont \u00e9quip\u00e9s, etc. Il y a bien quelqu\u2019un qui leur a apport\u00e9 les armes&nbsp;? Plenel&nbsp;: on a fait une enqu\u00eate l\u00e0-dessus, on a montr\u00e9 leur circuit\u2026 [NDA&nbsp;: c\u2019est faux, tout l\u2019arsenal de Coulibaly a pu \u00eatre retrac\u00e9, concernant celui des fr\u00e8res Kouachi le myst\u00e8re demeure total \u00e0 ce jour] Petit&nbsp;: que maintenant qu\u2019on sait comment \u00e7a a fonctionn\u00e9 [m\u00eame erreur de la part de M. Petit], \u00e7a montre qu\u2019il y a une importance avec le renseignement territorial qui doit se coupler avec le renseignement d\u2019un \u00e9chelon un peu sup\u00e9rieur qui est celui de la DGSI par exemple [NDA, allusion au <\/em><a href=\"https:\/\/www.franceinter.fr\/emissions\/le-zoom-de-la-redaction\/le-zoom-de-la-redaction-05-janvier-2016\" target=\"_blank\" rel=\"noreferrer noopener\"><em>changement de domicile de Sa\u00efd Kouachi<\/em><\/a><em> \u00e0 Reims qui avait entra\u00een\u00e9 l\u2019interruption des \u00e9coutes le concernant], et qu\u2019il y a des probl\u00e8mes de coordination, de tuilage, entre ces services de renseignement, mais c\u2019est tr\u00e8s important. Je crois effectivement qu\u2019on a besoin de tirer des le\u00e7ons. C\u2019est clair, mais \u00e0 condition de ne pas rester dans ces postures&nbsp;: \u00ab&nbsp;on travaille tr\u00e8s bien, on a emp\u00each\u00e9 tant d\u2019actions\u2026&nbsp;\u00bb Oui, bah, ni vous ni moi on peut v\u00e9rifier combien d\u2019actions, voil\u00e0, parce que c\u2019est secret. Et puis quand \u00e7a p\u00e8te, quand on tue un pr\u00eatre [NDA, le p\u00e8re Jacques Hamel, assassin\u00e9 par Adel Kermiche et Abd el Nabil Petit Jean le 26 juillet 2016, 12 jours apr\u00e8s l\u2019attentat de Nice. Nous avons r\u00e9sum\u00e9 ces affaires dans <a href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/07\/31\/tangos-fous-50-attentats-attribues-a-lei\/\" target=\"_blank\" rel=\"noreferrer noopener\">L&rsquo;activit\u00e9 de Daech en France&nbsp;: base de donn\u00e9es<\/a>], quand on tue toute l\u2019\u00e9quipe de Charlie Hebdo, apr\u00e8s quand m\u00eame on se pose des questions. Ces questions je me les pose dans le livre, et c\u2019est les questions que je me suis pos\u00e9es sur le moment, c\u2019est \u00ab&nbsp;comment ils ont pu rassembler ces kalachnikovs, ce mat\u00e9riel, comment on a pu voir ces gens aller et venir et puis ne pas \u00eatre derri\u00e8re eux\u2026&nbsp;\u00bb et une fois \u00e7a va, deux fois \u00e7a va, mais je crois, je dis \u00e7a, tant qu\u2019il n\u2019y aura pas ce d\u00e9briefing, cette clart\u00e9 dont on a besoin, on continuera de chuchoter dans les services, dans les salles de r\u00e9daction, dans la rue, ou autour d\u2019un caf\u00e9, pour se dire, mais qu\u2019est-ce qui se passe&nbsp;? Ils n\u2019ont pas vu. Comment&nbsp;? Pourquoi&nbsp;?<\/em>&nbsp;\u00bb<\/p>\n\n<form action=\"https:\/\/www.paypal.com\/donate\" method=\"post\" target=\"_top\">\n<input type=\"hidden\" name=\"hosted_button_id\" value=\"TJ3ZM8YMEYAKQ\" \/>\n<input type=\"image\" src=\"https:\/\/www.paypalobjects.com\/fr_FR\/FR\/i\/btn\/btn_donateCC_LG.gif\" border=\"0\" name=\"submit\" title=\"PayPal - The safer, easier way to pay online!\" alt=\"Bouton Faites un don avec PayPal\" \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"\" border=\"0\" src=\"https:\/\/www.paypal.com\/fr_FR\/i\/scr\/pixel.gif\" width=\"1\" height=\"1\" \/>\n<\/form>","protected":false},"excerpt":{"rendered":"<p>Le 36 quai des Orf\u00e8vres, si\u00e8ge de la Police Judiciaire de Paris, d\u00e9pendant de la pr\u00e9fecture de police de Paris<\/p>\n","protected":false},"author":1,"featured_media":1647,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[443,305],"tags":[497,280,501,61,494,282,493,348,127,496,500,495,498,473,57,481,499,53],"class_list":["post-1640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-charlie-hebdo","category-hyper-cacher","tag-36-quai-des-orfevres","tag-amedy-coulibaly","tag-aristophil","tag-attentats-du-13-novembre","tag-bernard-boucault","tag-bernard-cazeneuve","tag-bernard-petit","tag-charb","tag-charlie-hebdo","tag-christian-flaesch","tag-edwy-plenel","tag-francois-molins","tag-igpn","tag-jean-michel-fauvergue","tag-manuel-valls","tag-marc-trevidic","tag-mediapart","tag-nicolas-sarkozy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres - Fran\u00e7ois Belliot<\/title>\n<meta name=\"description\" content=\"L&#039;\u00e9difiante destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres, alors qu&#039;il enqu\u00eatait sur les attentats de janvier 2015.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres - Fran\u00e7ois Belliot\" \/>\n<meta property=\"og:description\" content=\"L&#039;\u00e9difiante destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres, alors qu&#039;il enqu\u00eatait sur les attentats de janvier 2015.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/\" \/>\n<meta property=\"og:site_name\" content=\"Fran\u00e7ois Belliot\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T10:46:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-20T15:59:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francoisbelliot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"francoisbelliot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"34 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/\",\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/\",\"name\":\"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres - Fran\u00e7ois Belliot\",\"isPartOf\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg\",\"datePublished\":\"2021-11-20T10:46:41+00:00\",\"dateModified\":\"2024-06-20T15:59:18+00:00\",\"author\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\"},\"description\":\"L'\u00e9difiante destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres, alors qu'il enqu\u00eatait sur les attentats de janvier 2015.\",\"breadcrumb\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#primaryimage\",\"url\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg\",\"contentUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg\",\"width\":1024,\"height\":575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/francoisbelliot.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/francoisbelliot.fr\/#website\",\"url\":\"https:\/\/francoisbelliot.fr\/\",\"name\":\"Fran\u00e7ois Belliot\",\"description\":\"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/francoisbelliot.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\",\"name\":\"francoisbelliot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"caption\":\"francoisbelliot\"},\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres - Fran\u00e7ois Belliot","description":"L'\u00e9difiante destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres, alors qu'il enqu\u00eatait sur les attentats de janvier 2015.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/","og_locale":"fr_FR","og_type":"article","og_title":"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres - Fran\u00e7ois Belliot","og_description":"L'\u00e9difiante destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres, alors qu'il enqu\u00eatait sur les attentats de janvier 2015.","og_url":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/","og_site_name":"Fran\u00e7ois Belliot","article_published_time":"2021-11-20T10:46:41+00:00","article_modified_time":"2024-06-20T15:59:18+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg","type":"image\/jpeg"}],"author":"francoisbelliot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"francoisbelliot","Dur\u00e9e de lecture estim\u00e9e":"34 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/","url":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/","name":"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres - Fran\u00e7ois Belliot","isPartOf":{"@id":"https:\/\/francoisbelliot.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#primaryimage"},"image":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#primaryimage"},"thumbnailUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg","datePublished":"2021-11-20T10:46:41+00:00","dateModified":"2024-06-20T15:59:18+00:00","author":{"@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9"},"description":"L'\u00e9difiante destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres, alors qu'il enqu\u00eatait sur les attentats de janvier 2015.","breadcrumb":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#primaryimage","url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg","contentUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2021\/11\/le-36-quai-des-orfevres.jpg","width":1024,"height":575},{"@type":"BreadcrumbList","@id":"https:\/\/francoisbelliot.fr\/index.php\/2021\/11\/20\/la-destruction-de-bernard-petit-patron-du-36-quai-des-orfevres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francoisbelliot.fr\/"},{"@type":"ListItem","position":2,"name":"La destruction de Bernard Petit, patron du 36 quai des Orf\u00e8vres"}]},{"@type":"WebSite","@id":"https:\/\/francoisbelliot.fr\/#website","url":"https:\/\/francoisbelliot.fr\/","name":"Fran\u00e7ois Belliot","description":"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francoisbelliot.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9","name":"francoisbelliot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","caption":"francoisbelliot"},"url":"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/"}]}},"_links":{"self":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/1640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1640"}],"version-history":[{"count":6,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/1640\/revisions"}],"predecessor-version":[{"id":2184,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/1640\/revisions\/2184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media\/1647"}],"wp:attachment":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}