{"id":151,"date":"2014-08-05T10:00:11","date_gmt":"2014-08-05T08:00:11","guid":{"rendered":"https:\/\/francoisbelliot.fr\/?p=151"},"modified":"2018-08-13T11:11:01","modified_gmt":"2018-08-13T09:11:01","slug":"lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3","status":"publish","type":"post","link":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/","title":{"rendered":"L&rsquo;attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3)"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong>Apr\u00e8s avoir expos\u00e9, dans la premi\u00e8re partie de cette \u00e9tude, le d\u00e9roulement de l\u2019attentat de la discoth\u00e8que La Belle survenu \u00e0 Berlin ouest en avril 1986, et le bombardement subs\u00e9quent de la Libye par les \u00c9tats-Unis lors de l\u2019op\u00e9ration El Dorado Canyon, nous en venons au r\u00e9cit du proc\u00e8s qui s\u2019ouvre en novembre 1997, et de ses zones d\u2019ombre.\u00a0Nous \u00e9voquons \u00e9galement le t\u00e9moignage de l&rsquo;ex-agent du Mossad Victor Ostrovski et la pol\u00e9mique qu&rsquo;il a engendr\u00e9.<\/strong><\/span><!--more--><\/p>\n<p><span style=\"color: #000000;\">Alors que 10 jours apr\u00e8s l&rsquo;attentat, Ronald Reagan annon\u00e7ait disposer de preuves \u201cirr\u00e9futables\u201d(<a style=\"color: #000000;\" href=\"http:\/\/observatoire-terrorisme.com\/lattentat-de-la-belle-en-avril-1986-1er-casus-belli-contre-la-libye-de-kadhafi\/\" rel=\"nofollow\">voir la premi\u00e8re partie<\/a>), il faut attendre 4 ans pour qu&rsquo;un ensemble d&rsquo;\u00e9l\u00e9ments nouveaux soient vers\u00e9s au dossier et permettent de d\u00e9marrer vraiment l&rsquo;enqu\u00eate. La chute du mur de Berlin en 1989, ouvre l&rsquo;acc\u00e8s aux archives de la Stasi, lesquelles fournissent des informations sur les individus qui depuis Berlin-est auraient mis en \u0153uvre l&rsquo;attentat \u00e0 l&rsquo;\u00e9poque. Selon l\u2019accusation, ces archives livrent en particulier cinq noms\u00a0: trois employ\u00e9s de l\u2019ambassade de Libye \u00e0 Berlin-est, Musbah Eter, Yasser Chra\u00efdi, et Ali Chanaa, et deux femmes, Verena, la femme d\u2019Ali, et Andrea Haeusler, la s\u0153ur de Verena.<\/span><\/p>\n<p><span style=\"color: #000000;\">Eter et quatre autres suspects sont arr\u00eat\u00e9s en 1996 au Liban, en<\/span><\/p>\n<figure id=\"attachment_119\" aria-describedby=\"caption-attachment-119\" style=\"width: 168px\" class=\"wp-caption alignright\"><a class=\"noborder\" style=\"color: #000000;\" href=\"http:\/\/observatoire-terrorisme.com\/wp-content\/uploads\/2012\/05\/Mehlis2.jpg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-119\" title=\"Mehlis2\" src=\"https:\/\/www.agoravox.fr\/local\/cache-vignettes\/L168xH168\/Mehlis2jpg-771f2-37e5f.jpg\" alt=\"\" width=\"168\" height=\"168\" \/><\/a><figcaption id=\"caption-attachment-119\" class=\"wp-caption-text\"><span style=\"color: #000000;\">le procureur Detlev Mehlis<\/span><\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">Italie, en Gr\u00e8ce, et \u00e0 Berlin. L\u2019enqu\u00eate peut enfin commencer. le proc\u00e8s s&rsquo;ouvre en novembre 1997, sous la direction du procureur Detlev Mehlis. Elle dure quatre longues ann\u00e9es au terme desquelles, en novembre 2001, Musbah Eter, qui n&rsquo;avait de cesse pendant le proc\u00e8s de charger les autres co-accus\u00e9s <a style=\"color: #000000;\" href=\"http:\/\/news.bbc.co.uk\/2\/hi\/europe\/1653848.stm\" target=\"_blank\" rel=\"nofollow noopener\">est condamn\u00e9 \u00e0 12 ans de prison<\/a> pour assistance aux pr\u00e9paratifs de l&rsquo;attentat. Yasser Shra\u00efdi et Ali Chanaa, \u00e9copent de 14 et 12 ans, le premier pour avoir \u00e9t\u00e9 le cerveau de l&rsquo;op\u00e9ration, le second pour participation \u00e0 sa mise en \u0153uvre. Verena Chanaa, la femme d&rsquo;Ali, est la seule \u00e0 \u00eatre condamn\u00e9e pour meurtre, puisque c&rsquo;est elle qui a plac\u00e9 la bombe dans la discoth\u00e8que\u00a0; elle \u00e9cope quant \u00e0 elle de 14 ans de prison. L&rsquo;enqu\u00eate d\u00e9termine que les trois hommes ont assembl\u00e9 la bombe dans l&rsquo;appartement des Chanaa. L&rsquo;explosif ayant servi \u00e0 l&rsquo;attentat a \u00e9t\u00e9 achemin\u00e9 depuis Berlin-Est dans une valise diplomatique libyenne. Verena Chanaa et sa s\u0153ur, Andrea Haeusler, ont pos\u00e9 la bombe dans la discoth\u00e8que et en sont sorties 5 minutes avant qu&rsquo;elle n&rsquo;explose. Mme\u00a0Haeusler a \u00e9t\u00e9 acquitt\u00e9e au motif qu&rsquo;elle ignorait tout de l&rsquo;affaire, notamment que le sac meurtrier contenait une bombe.<\/span><\/p>\n<p><span style=\"color: #000000;\">La cour \u00e9tablit pour mobile de l\u2019attentat le d\u00e9sir de la Libye de se venger des pertes mat\u00e9rielles et humaines subies lors des exercices militaires \u00e9tasuniens de vaste ampleur organis\u00e9s \u00e0 la limite du golfe de Sidra dix jours plus t\u00f4t par les \u00c9tasuniens (<a style=\"color: #000000;\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-belle-en-avril-1986-1er-casus-belli-contre-la-libye-de-kadhafi-1-3\/\" target=\"_blank\" rel=\"nofollow noopener\">voir la premi\u00e8re partie de cette \u00e9tude).<\/a>Dans le dossier chargeant les inculp\u00e9s, figurent les messages de pr\u00e9paration et de revendication envoy\u00e9s depuis Tripoli \u00e0 l&rsquo;ambassade de Berlin-Est, des \u00e9coutes t\u00e9l\u00e9phoniques d&rsquo;Eter et<\/span><\/p>\n<figure id=\"attachment_120\" aria-describedby=\"caption-attachment-120\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a class=\"noborder\" style=\"color: #000000;\" href=\"http:\/\/observatoire-terrorisme.com\/wp-content\/uploads\/2012\/05\/Eter2.jpg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-120\" title=\"Eter2\" src=\"https:\/\/www.agoravox.fr\/local\/cache-vignettes\/L150xH150\/Eter2-150x154bc5-46523.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-120\" class=\"wp-caption-text\"><span style=\"color: #000000;\">Musbah Eter<\/span><\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">Shra\u00efdi, des rapports sur les activit\u00e9s de l&rsquo;ambassade de Libye \u00e0 Berlin-est, et des documents attestant de versements d&rsquo;argent aux \u00e9poux Chanaa en r\u00e9compense de leur action. Le proc\u00e8s en revanche n&rsquo;a pu permettre d&rsquo;\u00e9tablir formellement la responsabilit\u00e9 de Kadhafi dans cette affaire, la cour regrettant sur ce point l&rsquo;extr\u00eame r\u00e9ticence des services de renseignements allemands et \u00e9tasuniens <a style=\"color: #000000;\" href=\"http:\/\/www.nytimes.com\/2001\/11\/14\/world\/4-guilty-in-fatal-1986-berlin-disco-bombing-linked-to-libya.html\" target=\"_blank\" rel=\"nofollow noopener\">\u00e0 partager leurs informations avec la cour<\/a>.<\/span><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_71 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04582870533\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04582870533\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#Les_zones_dombre_de_lenquete_revelations_ulterieures\" title=\"Les zones d&rsquo;ombre de l&rsquo;enqu\u00eate\u00a0: r\u00e9v\u00e9lations ult\u00e9rieures\">Les zones d&rsquo;ombre de l&rsquo;enqu\u00eate\u00a0: r\u00e9v\u00e9lations ult\u00e9rieures<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#Le_role_trouble_de_Detlev_Mehlis_dans_lassassinat_de_Rafik_Hariri\" title=\"Le r\u00f4le trouble de Detlev Mehlis dans l&rsquo;assassinat de Rafik Hariri\">Le r\u00f4le trouble de Detlev Mehlis dans l&rsquo;assassinat de Rafik Hariri<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#Le_temoignage_de_lex_agent_du_Mossad_Victor_Ostrovski\" title=\"Le t\u00e9moignage de l&rsquo;ex agent du Mossad Victor Ostrovski\">Le t\u00e9moignage de l&rsquo;ex agent du Mossad Victor Ostrovski<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#Credibilite_du_temoignage_dOstrovski\" title=\"Cr\u00e9dibilit\u00e9 du t\u00e9moignage d&rsquo;Ostrovski\">Cr\u00e9dibilit\u00e9 du t\u00e9moignage d&rsquo;Ostrovski<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Les_zones_dombre_de_lenquete_revelations_ulterieures\"><\/span><span style=\"color: #000000;\"><strong>Les zones d&rsquo;ombre de l&rsquo;enqu\u00eate\u00a0: r\u00e9v\u00e9lations ult\u00e9rieures <\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">En 1998, des journalistes allemands du magazine Frontal de la cha\u00eene publique ZDF, alert\u00e9s par ce qu&rsquo;ils croient reconna\u00eetre comme des <em>zones d&rsquo;ombre<\/em> de l&rsquo;enqu\u00eate, d\u00e9cident de mener <a style=\"color: #000000;\" href=\"http:\/\/100777.com\/node\/101\" target=\"_blank\" rel=\"nofollow noopener\">leur propre investigation<\/a>. Les faits qu&rsquo;ils mettent \u00e0 jour, et les conclusions auxquelles ils parviennent s&rsquo;\u00e9cartent \u00e0 l&rsquo;extr\u00eame de celles de M.\u00a0Mehlis, et ils en viennent \u00e0 exposer leurs doutes de fa\u00e7on circonstanci\u00e9e dans un documentaire qui passe \u00e0 la t\u00e9l\u00e9vision le 25 ao\u00fbt de cette ann\u00e9e. Les auteurs du documentaire allemand font un certain nombre de d\u00e9couvertes parmi lesquelles\u00a0: le principal inculp\u00e9 pr\u00e9sent, Yasser Shra\u00efdi est tr\u00e8s probablement innocent et a \u00e9t\u00e9 utilis\u00e9 comme bouc \u00e9missaire par les services de renseignements ouest-allemands (BND) et \u00e9tasuniens (CIA)\u00a0; au moins l&rsquo;un des inculp\u00e9s, Musbah Eter, a \u00e9t\u00e9 un agent de la CIA pendant de nombreuses ann\u00e9es\u00a0; au moins l&rsquo;un des suspects, Mohamed Amairi, serait un agent du Mossad. Quant \u00e0 Shra\u00efdi, \u00e9tabli par la suite au Liban, les autorit\u00e9s allemandes ont exerc\u00e9 de fortes pressions pour obtenir son extradition, comme l&rsquo;indiquent le procureur libanais Mounif Oueidat et son adjoint Mrad Azoury. Ce dernier a ainsi d\u00e9clar\u00e9 qu&rsquo;on ne lui avait donn\u00e9 aucune preuve de l&rsquo;implication de Shra\u00efdi dans l&rsquo;attentat (voir par ailleurs <a style=\"color: #000000;\" href=\"http:\/\/usa.mediamonitors.net\/content\/view\/full\/22038\" rel=\"nofollow\">cet article de Nafeez Mossadeq<\/a>). Il y avait tout au plus de vagues indices. Ces preuves \u00e9taient d&rsquo;ailleurs si minces, pr\u00e9cisent les journalistes de Frontal, qu&rsquo;un juge de Berlin li\u00e9 \u00e0 l&rsquo;affaire mena\u00e7a de rel\u00e2cher Shra\u00efdi si on ne lui fournissait pas quelque chose de plus solide (nous sommes le 9 septembre 1996).<\/span><\/p>\n<p><span style=\"color: #000000;\">Le m\u00eame jour o\u00f9 ce juge lan\u00e7ait cette menace, le procureur Mehlis, s&rsquo;envolait pour l&rsquo;\u00eele de Malte en compagnie de l&rsquo;inspecteur de police Uwe Wilhelms et un agent des services secrets allemands pour y rencontrer un homme avait jusque l\u00e0 \u00e9t\u00e9 ignor\u00e9 par l&rsquo;accusation\u00a0: Musbah Eter. L&rsquo;homme y dirigeait une entreprise de commerce international qui, selon Frontal, servait de couverture \u00e0 certaines activit\u00e9s secr\u00e8tes de la CIA. L&rsquo;accord \u00e9tait le suivant\u00a0: les poursuites contre Eter seraient arr\u00eat\u00e9es si ce celui-ci acceptait de t\u00e9moigner contre Shra\u00efdi. Ayant accept\u00e9 le march\u00e9, il va t\u00e9moigner le lendemain \u00e0 l&rsquo;ambassade d&rsquo;Allemagne\u00a0; le mandat d&rsquo;arr\u00eat le visant est lev\u00e9, et, pensant ne courir aucun risque, il s&rsquo;envole pour l&rsquo;Allemagne. Selon Frontal, qui s\u2019appuie sur des notes de services de renseignement est-allemands, lesquels surveillaient de pr\u00e8s Eter \u00e0 l&rsquo;\u00e9poque, l&rsquo;homme travaillait \u00e0 l&rsquo;ambassade libyenne de Berlin-est mais faisait de fr\u00e9quentes visites \u00e0 l&rsquo;ambassade des \u00c9tats-Unis. Beaucoup d&rsquo;autres \u00e9l\u00e9ments pointent une participation active d&rsquo;Eter dans la pr\u00e9paration de l&rsquo;attentat.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les journalistes de Frontal rel\u00e8vent par ailleurs que certains suspects cl\u00e9s n&rsquo;ont pas pu t\u00e9moigner devant la cour car ils sont prot\u00e9g\u00e9s par ces services de renseignement.\u00a0Il y avait apparemment un autre groupe impliqu\u00e9 dans l&rsquo;attentat, un groupe de terroristes professionnels, dirig\u00e9 par un certain \u201cMahmoud\u201d Abu Jaber, qui travaillait pour quiconque avait de quoi les payer. Les membres de ce groupe ont \u00e9t\u00e9 cit\u00e9s lors du proc\u00e8s, mais de fa\u00e7on extr\u00eamement superficielle et sans qu&rsquo;on fasse jamais peser la moindre charge sur eux. Ces hommes \u00e9taient pourtant pr\u00e9sents \u00e0 Berlin-est quelques mois avant l&rsquo;op\u00e9ration et avaient des contacts quotidiens avec les autres inculp\u00e9s. Plusieurs heures avant l&rsquo;attaque, ils sont pass\u00e9s \u00e0 Berlin-Ouest. Leurs d\u00e9placements ont \u00e9t\u00e9 relev\u00e9s par les services sovi\u00e9tiques et est-allemands qui sont parvenus \u00e0 la conclusion qu&rsquo;il s&rsquo;agissait d&rsquo;agents \u00e0 la solde de services occidentaux<a style=\"color: #000000;\" title=\"\" href=\"https:\/\/mail.google.com\/mail\/u\/0\/?ui=2&amp;view=bsp&amp;ver=ohhl4rw8mbn4#_ftn1\" rel=\"nofollow\">[1]<\/a>. Les journalistes de Frontal ont retrouv\u00e9 la trace en Norv\u00e8ge de Mohamed Amairi, le bras droit de Mahmoud Abu Jaber, et sont m\u00eame parvenus \u00e0 obtenir un entretien. Celui-ci a pris fin au moment o\u00f9 l&rsquo;homme a refus\u00e9 de dire pour quel service de renseignement il travaillait. Son avocat, plus loquace, conc\u00e9da ensuite qu&rsquo;il \u00e9tait \u201c<a style=\"color: #000000;\" href=\"http:\/\/www.williambowles.info\/syria_lebanon\/mehlis_berlin_disco.html\" target=\"_blank\" rel=\"nofollow noopener\">un agent du Mossad<\/a>\u201d.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les conclusions de Frontal sur l&rsquo;\u00e9valuation des responsabilit\u00e9s dans l&rsquo;attentat de la Belle sont tr\u00e8s diff\u00e9rentes de celles du procureur Mehlis, qui, apr\u00e8s s&rsquo;\u00eatre compl\u00e8tement d\u00e9sint\u00e9ress\u00e9 de ce personnage cl\u00e9 de l&rsquo;affaire qu\u2019est Mohamed Amairi, fut celui qui leva le mandat d&rsquo;arr\u00eat pesant sur lui, avant qu\u2019il n\u2019obtienne la nationalit\u00e9 norv\u00e9gienne dans des circonstances troubles. \u00ab\u00a0<em>Ces intrigues des services secrets rendent la t\u00e2che de la cour de Berlin pratiquement insoluble, mais une chose est certaine, concluent les journalistes de Frontal, la version \u00e9tasunienne pr\u00e9sentant l&rsquo;\u00e9tat libyen comme un \u00e9tat terroriste ne peut plus \u00eatre maintenue plus longtemps.\u00a0<\/em>\u00a0\u00bb<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Le_role_trouble_de_Detlev_Mehlis_dans_lassassinat_de_Rafik_Hariri\"><\/span><span style=\"color: #000000;\"><strong>Le r\u00f4le trouble de Detlev Mehlis dans l&rsquo;assassinat de Rafik Hariri<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">Au vu de la gravit\u00e9 des irr\u00e9gularit\u00e9s dont le juge Mehlis s&rsquo;est apparemment rendu coupable lors du proc\u00e8s de La Belle, on aurait pu au moins s&rsquo;attendre \u00e0 ce qu&rsquo;une contre enqu\u00eate soit men\u00e9e pour obtenir certaines r\u00e9ponses de sa part. Rien de tout cela n&rsquo;est arriv\u00e9. Au contraire\u00a0: c&rsquo;est \u00e0 cet homme qu&rsquo;a \u00e9chu la redoutable responsabilit\u00e9 de pr\u00e9sider la commission d&rsquo;enqu\u00eate sur l&rsquo;assassinat du premier ministre libanais Rafik Hariri. Comme l&rsquo;exposent ces deux articles <a style=\"color: #000000;\" href=\"http:\/\/www.mondialisation.ca\/index.php?context=va&amp;aid=1450\" target=\"_blank\" rel=\"nofollow noopener\">de Talaat Ramih<\/a> et <a style=\"color: #000000;\" href=\"http:\/\/www.voltairenet.org\/Affaire-Hariri-apres-la-Syrie-le\" target=\"_blank\" rel=\"nofollow noopener\">de Thierry Meyssan<\/a>, M.\u00a0Mehlis dans l&rsquo;affaire Hariri semble \u00eatre all\u00e9 encore plus loin.<\/span><\/p>\n<p><span style=\"color: #000000;\">Parmi les innombrables irr\u00e9gularit\u00e9s de cette commission d&rsquo;enqu\u00eate, Ramih et Meyssan rel\u00e8vent que 1) l&rsquo;analyse de la sc\u00e8ne du crime n&rsquo;a pas \u00e9t\u00e9 faite dans le d\u00e9tail. 2) le profond crat\u00e8re constat\u00e9 apr\u00e8s l&rsquo;explosion ne correspond pas \u00e0 l&rsquo;effet qu&rsquo;aurait caus\u00e9 une camionnette pi\u00e9g\u00e9e. 3) La reconstitution a eu lieu en France, \u00e0 huis clos, et <a style=\"color: #000000;\" href=\"http:\/\/www.lefigaro.fr\/international\/2010\/10\/19\/01003-20101019ARTFIG00560-l-assassinat-d-hariri-reconstitue-en-secret.php\" target=\"_blank\" rel=\"nofollow noopener\">ses r\u00e9sultats n&rsquo;ont pas \u00e9t\u00e9 communiqu\u00e9s<\/a>. 4) Comme les enqu\u00eateurs voulaient v\u00e9rifier l&rsquo;hypoth\u00e8se d&rsquo;un missile tir\u00e9 depuis un drone (plusieurs t\u00e9moins ayant entendu un a\u00e9ronef au moment de l&rsquo;attentat), ils ont demand\u00e9 des photos satellites de la zone au moment des faits aux Isra\u00e9liens et aux \u00c9tasuniens qui <a style=\"color: #000000;\" href=\"http:\/\/www.legrandsoir.info\/Liban-L-assassinat-de-Rafic-Hariri-une-nouvelle-version-qui-derange.html\" target=\"_blank\" rel=\"nofollow noopener\">se sont d\u00e9clar\u00e9s incapables d&rsquo;acc\u00e9der \u00e0 cette requ\u00eate<\/a>, en raison de pannes techniques conjointes de leurs satellites. 5) Un passager de la voiture blind\u00e9e de Hariri a surv\u00e9cu. De fa\u00e7on inattendue on a retrouv\u00e9 dans son corps des traces d&rsquo;uranium appauvri, ce qui aurait d\u00fb amener les enqu\u00eateurs \u00e0 explorer la piste du missile \u00e0 l&rsquo;uranium appauvri, technologie inaccessible aux Syriens et aux combattants du Hezbollah, en premi\u00e8re ligne aux rangs des accus\u00e9s dans cette affaire. 6) La place de procureur n&rsquo;aurait jamais d\u00fb \u00eatre confi\u00e9e \u00e0 M Mehlis, pour des raisons de conflits d&rsquo;int\u00e9r\u00eats. Meyssan remarque\u00a0: \u201c<em>Au d\u00e9but des ann\u00e9es 2000, M.\u00a0Mehlis a \u00e9t\u00e9 grassement r\u00e9mun\u00e9r\u00e9 comme chercheur par le Washington Institute for Near East Policy WINEP (le think-tank du lobby pro-isra\u00e9lien AIPAC) et par la Rand Corporation (le think-tank du complexe militaro-industriel \u00e9tats-unien). Autant d\u2019\u00e9l\u00e9ments qui jettent un doute sur son impartialit\u00e9 dans l\u2019affaire Hariri et auraient d\u00fb le faire r\u00e9cuser.<\/em>\u201d 7) Mehlis \u00e9tait assist\u00e9 du commissaire Gerhard Lehmann, peut-\u00eatre agent des<\/span><\/p>\n<figure id=\"attachment_122\" aria-describedby=\"caption-attachment-122\" style=\"width: 150px\" class=\"wp-caption alignright\"><a class=\"noborder\" style=\"color: #000000;\" href=\"http:\/\/observatoire-terrorisme.com\/wp-content\/uploads\/2012\/05\/gerhard-lehmann2.jpg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-122\" title=\"gerhard-lehmann2\" src=\"https:\/\/www.agoravox.fr\/local\/cache-vignettes\/L150xH150\/gerhard-lehmb15a-95563.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-122\" class=\"wp-caption-text\"><span style=\"color: #000000;\">Gerhard Lehmann<\/span><\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">services secrets allemands et \u00e9tasuniens, reconnu formellement par un t\u00e9moin comme participant au programme d\u2019enl\u00e8vements, de s\u00e9questrations et de tortures, mis en place en Europe par l\u2019administration Bush (<a style=\"color: #000000;\" href=\"http:\/\/assembly.coe.int\/mainf.asp?link=\/committeedocs\/2006\/20060606_fjdoc162006partii-final.htm\" target=\"_blank\" rel=\"nofollow noopener\">voir le paragraphe 99 du rapport de Dick Marty du 12 juin 2006 pour le Conseil de l&rsquo;Europe<\/a>). 8) sur les trois \u00e9chantillons de terre pr\u00e9lev\u00e9s sur la sc\u00e8ne du crime, r\u00e9partis ensuite en trois bocaux qui ont \u00e9t\u00e9 envoy\u00e9s \u00e0 trois laboratoires diff\u00e9rents, deux analyses n\u2019ont montr\u00e9 aucune trace d\u2019explosif. Le troisi\u00e8me bocal, pris par Mehlis et Lehmann, et envoy\u00e9 par leur soin au troisi\u00e8me laboratoire, est le seul \u00e0 avoir r\u00e9v\u00e9l\u00e9 les traces d\u2019explosifs recherch\u00e9s. Or en principe, si l\u2019on d\u00e9cide de recourir \u00e0 trois experts judiciaires, c\u2019est qu\u2019en cas de d\u00e9saccord entre eux, on se reporte \u00e0 l\u2019avis majoritaire. 9) Pour mener son enqu\u00eate, l&rsquo;homme a conc\u00e9d\u00e9 s&rsquo;\u00eatre appuy\u00e9 sur l&rsquo;expertise des services de renseignement isra\u00e9liens, alors qu\u2019Isra\u00ebl pouvait \u00eatre suspect\u00e9 d\u2019\u00eatre partie prenante de l\u2019assassinat (Ramih et Meyssan). 10) Le procureur n&rsquo;a pas h\u00e9sit\u00e9 \u00e0 s&rsquo;appuyer sur des faux t\u00e9moignages, pour porter le soup\u00e7on sur les pr\u00e9sident Bashar el Assad et Emile Lahoud. \u201c<em>Sur la base de ces faux t\u00e9moignages, <\/em>dit Meyssan, <em>Detlev Mehlis arr\u00eata, au nom de la Communaut\u00e9 internationale, quatre g\u00e9n\u00e9raux libanais et les fit incarc\u00e9rer durant quatre ans. P\u00e9n\u00e9trant avec ses cow-boys au domicile de chacun, sans mandat de la justice libanaise, il interpella \u00e9galement les membres de leur entourage. Avec ses assistants \u2014qui s\u2019expriment entre eux en h\u00e9breu\u2014 il tenta de manipuler les familles.<\/em>\u201d En outre, d\u00e9tail qui rappelle furieusement la rencontre entre Mehlis et Eter \u00e0 Malte en 1990, \u201c<em>Lehmann proposa \u00e0 un des quatre g\u00e9n\u00e9raux incarc\u00e9r\u00e9s de le lib\u00e9rer s\u2019il acceptait de porter un faux t\u00e9moignage contre un dirigeant syrien.<\/em>\u201d Meyssan conclut\u00a0: \u201c<em>L\u2019enqu\u00eate de Detlev Mehlis a sombr\u00e9 non seulement dans le ridicule des faux t\u00e9moins, mais dans l\u2019ill\u00e9galit\u00e9 de l\u2019arrestation des quatre g\u00e9n\u00e9raux. <\/em><a style=\"color: #000000;\" href=\"http:\/\/www.a-ipi.net\/article154760.html\" rel=\"nofollow\"><em>Au point que le Groupe de travail sur les d\u00e9tentions arbitraire du Conseil des droits de l\u2019homme de l\u2019ONU est intervenu pour condamner fermement cet exc\u00e8s de pouvoir<\/em><\/a><em>.<\/em>\u201d<\/span><\/p>\n<p><span style=\"color: #000000;\"><em>Actualisation (2018) : eus \u00e9gard aux articles que j&rsquo;ai fait para\u00eetre \u00e0 l&rsquo;\u00e9t\u00e9 2018 sur les tr\u00e8s graves fraudes dont est entach\u00e9 le livre de Meyssan <span style=\"text-decoration: underline;\">Sous nos yeux<\/span>, en particulier son imposture libyenne, je pourrais supprimer ces r\u00e9f\u00e9rences, mais comme je l&rsquo;ai pr\u00e9cis\u00e9, Meyssan ne peut avoir tort sur tout sinon il ne serait pas cr\u00e9dible pour un sou. Et ici, de fait, il n&rsquo;a pas tort&#8230; Je pourrais supprimer ce vestige mais je le laisse pour t\u00e9moigner qu&rsquo;en tant que chercheur on peut \u00eatre amen\u00e9 \u00e0 r\u00e9viser et affiner ses positions avec le temps.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">Devant <a style=\"color: #000000;\" href=\"http:\/\/breve.fr\/2010\/10\/16\/assassinat-de-rafic-hariri-la-justice-syrienne-poursuit-l%E2%80%99enqueteur-onusien-et-son-adjoint\/\" rel=\"nofollow\">l&rsquo;ampleur du scandale<\/a>, l&rsquo;homme, <a style=\"color: #000000;\" href=\"http:\/\/www.voltairenet.org\/La-commission-Mehlis-discreditee\" rel=\"nofollow\">press\u00e9 par son gouvernement<\/a>, se retire de la commission d&rsquo;enqu\u00eate avant qu&rsquo;elle parvienne \u00e0 son terme.<\/span><\/p>\n<p><span style=\"color: #000000;\">Cet ensemble d&rsquo;irr\u00e9gularit\u00e9s et de manipulations accablantes pour Detlev Mehlis ne sont \u00e9videmment pas de nature \u00e0 diminuer la m\u00e9fiance que son action pendant le proc\u00e8s de la Belle pourrait inspirer. Bien au contraire, les pratiques auxquelles l&rsquo;homme s&rsquo;est abondamment livr\u00e9 en tant que directeur de deux enqu\u00eates extr\u00eamement sensibles dessinent en creux le profil d&rsquo;un juge ripou dont la fonction serait \u00e0 l&rsquo;occasion de dissimuler des affaires de <em>mensonges d&rsquo;\u00e9tat.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">La contre-enqu\u00eate du magazine Frontal, en r\u00e9v\u00e9lant les manipulations du juge Mehlis, et les liens de certains terroristes avec le Mossad, la CIA, ou le BND, ont permis de porter un regard diff\u00e9rent sur la planification et le d\u00e9roulement de l&rsquo;attentat.<\/span><\/p>\n<p><span style=\"color: #000000;\">Un autre myst\u00e8re est encore \u00e0 \u00e9claircir\u00a0: pourquoi des messages de revendication ont-ils \u00e9t\u00e9 \u00e9mis, ce qu&rsquo;aucun pays n&rsquo;a contest\u00e9, depuis Tripoli, dans les jours pr\u00e9c\u00e9dant et suivant l&rsquo;attentat\u00a0? Un ex agent du Mossad a peut-\u00eatre donn\u00e9 la r\u00e9ponse \u00e0 cette question.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Le_temoignage_de_lex_agent_du_Mossad_Victor_Ostrovski\"><\/span><span style=\"color: #000000;\"><strong>Le t\u00e9moignage de l&rsquo;ex agent du Mossad Victor Ostrovski<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_123\" aria-describedby=\"caption-attachment-123\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a class=\"noborder\" style=\"color: #000000;\" href=\"http:\/\/observatoire-terrorisme.com\/wp-content\/uploads\/2012\/05\/ostrovsky.jpg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-123\" title=\"ostrovsky\" src=\"https:\/\/www.agoravox.fr\/local\/cache-vignettes\/L150xH150\/ostrovsky-152cae-80e25.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-123\" class=\"wp-caption-text\"><span style=\"color: #000000;\">Victor Ostrovsky<\/span><\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">Victor Ostrovski est un ancien agent op\u00e9rationnel du Mossad qui a travaill\u00e9 pour l&rsquo;agence de renseignement isra\u00e9lienne de 1982 \u00e0 1986. Anim\u00e9 au d\u00e9part par l&rsquo;id\u00e9al nationaliste et persuad\u00e9 de la conduite irr\u00e9prochable de l&rsquo;\u00e9tat d&rsquo;Isra\u00ebl, peu \u00e0 peu il d\u00e9chante et est scandalis\u00e9 par \u00ab\u00a0<em>la corruption des id\u00e9aux, le pragmatisme qui se regarde le nombril, coupl\u00e9s \u00e0 (&#8230;) la convoitise, et un manque de respect total pour la vie humaine\u00a0<\/em>\u00a0\u00bb, il d\u00e9missionne et ressent le devoir de r\u00e9v\u00e9ler les dessous de quelques unes des op\u00e9rations les plus impressionnantes du Mossad. Cela donne deux livres aux contenu explosif\u00a0: <a style=\"color: #000000;\" href=\"http:\/\/www.whale.to\/c\/OSTROVbywayofdecep.pdf\" target=\"_blank\" rel=\"nofollow noopener\">By Way of Deception en 1990<\/a>, et <a style=\"color: #000000;\" href=\"http:\/\/thepiratebay.se\/torrent\/4750406\/The_Other_Side_of_Deception_-_Victor_Ostrovsky\" target=\"_blank\" rel=\"nofollow noopener\">Other Side of Deception<\/a>, en 1995.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dans le second de ces deux livres, Ostrovski consacre un long d\u00e9veloppement \u00e0 une op\u00e9ration particuli\u00e8rement os\u00e9e men\u00e9e par le Mossad sur le sol Libyen au d\u00e9but de l&rsquo;ann\u00e9e 1986.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les quatre paragraphes suivants sont une traduction ramass\u00e9e <a style=\"color: #000000;\" href=\"https:\/\/www.agoravox.fr\/aldeilis.net%201986%20Ostrovski\" target=\"_blank\" rel=\"nofollow noopener\">du r\u00e9cit d&rsquo;Ostrovski.<\/a><\/span><\/p>\n<p><span style=\"color: #000000;\">\u00ab\u00a0D\u00e9but 1986, le Mossad, toujours en qu\u00eate d&rsquo;id\u00e9es nouvelles et audacieuses pour mettre en difficult\u00e9 ceux qu&rsquo;il consid\u00e8re comme les ennemis d&rsquo;Isra\u00ebl les plus dangereux, imagine d&rsquo;implanter un \u00e9metteur en plein c\u0153ur de Tripoli par le biais duquel de fausses informations compromettantes pourraient \u00eatre envoy\u00e9es. Ces \u00e9missions seraient cod\u00e9es et emprunteraient une fr\u00e9quence gouvernementale libyenne. Intercept\u00e9es et d\u00e9chiffr\u00e9s par les stations d&rsquo;\u00e9coute occidentales, elles seraient interpr\u00e9t\u00e9es comme des preuves de la responsabilit\u00e9 de Kadhafi, en cas d&rsquo;attentat terroriste<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00ab\u00a0Shimon\u00a0\u00bb (Peres\u00a0?) donne son feu vert \u00e0 l&rsquo;op\u00e9ration qui est d\u00e9clench\u00e9e le 17 f\u00e9vrier. En pleine nuit, deux navires de guerre isra\u00e9liens se dirigent vers l&rsquo;ouest, en longeant au plus pr\u00e8s la limite des eaux territoriales libyennes. Parvenus au niveau de Tripoli ils ralentissent et mettent \u00e0 l&rsquo;eau un commando de 12 hommes. Install\u00e9s dans deux vedettes basses tr\u00e8s rapides, ils cinglent vers la c\u00f4te. Parvenus \u00e0 deux miles, une partie du commando se met \u00e0 l&rsquo;eau dans de petits sous-marins, l&rsquo;autre reste au large pour fixer le point de rendez-vous. Parvenus pr\u00e8s du rivage, deux hommes restent pour garder les sous-marins, et les 4 autres d\u00e9barquent l&rsquo;\u00e9metteur qui est log\u00e9 dans un cylindre de six pieds de long et 6 pouces de large. Ils se dirigent alors vers la route c\u00f4ti\u00e8re toute proche et tombent sur un homme en train de r\u00e9parer une roue crev\u00e9e. C&rsquo;est en fait un combattant du Mossad qui les attend. Quand il les aper\u00e7oit, il cesse son mime et leur ouvre les portes arri\u00e8res de la camionnette. Aussit\u00f4t les hommes font route vers le centre de Tripoli. Pour que le signal de l&rsquo;\u00e9metteur soit confondu, il faut qu&rsquo;il soit situ\u00e9 au plus pr\u00e8s des sources d&rsquo;o\u00f9 sont ordinairement \u00e9mis les messages gouvernementaux libyens. Pour ce faire, le combattant du Mossad a lou\u00e9 depuis quelques mois un appartement situ\u00e9 sur la rue de Al Jamhuriyh, \u00e0 trois p\u00e2t\u00e9s de maison des baraquements de Bab al Azizia qui h\u00e9bergeaient le quartier g\u00e9n\u00e9ral et le lieu de r\u00e9sidence de Kadhafi. La camionnette p\u00e9n\u00e8tre dans l&rsquo;immeuble et les hommes du Mossad, chang\u00e9s en civils, montent au dernier \u00e9tage le Troyen qu&rsquo;ils ont pris soin d&rsquo;enrober dans un tapis.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00ab\u00a0Rapidement ils installent le dispositif, puis font le voyage aller en sens inverse. Au petit matin les 12 hommes du commando sont au large, sans avoir \u00e9t\u00e9 rep\u00e9r\u00e9s. Le combattant du Mossad demeure sur place pour surveiller le Troyen. Celui-ci est cens\u00e9 exploser violemment en cas d&rsquo;intrusion. Quelques jours plus tard, le Troyen commence \u00e0 \u00e9mettre des messages \u00ab\u00a0officiels\u00a0\u00bb libyens tous plus inqui\u00e9tants les uns que les autres concernant des projets d&rsquo;actions terroristes. Tous ces messages sont volontairement chiffr\u00e9s par le Mossad pour leur donner plus de cr\u00e9dibilit\u00e9.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00ab\u00a0Plusieurs de ces messages, envoy\u00e9s dans les jours pr\u00e9c\u00e9dant et suivant l&rsquo;attentat de la discoth\u00e8que la Belle, qui survient deux mois plus tard, \u00e9voquent l&rsquo;attentat. Ceux-ci sont intercept\u00e9s par les \u00c9tasuniens, qui, comme l&rsquo;esp\u00e9raient les Isra\u00e9liens, sont parvenus \u00e0 en briser le chiffre.\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Victor Ostrovski fait le bilan de l&rsquo;op\u00e9ration\u00a0: \u00ab\u00a0<em>\u00a0L&rsquo;op\u00e9ration Troyen fut l&rsquo;un des succ\u00e8s les plus \u00e9clatants du Mossad. Il entra\u00eena le bombardement a\u00e9rien de la Libye, bombardement qui eut trois cons\u00e9quences importantes\u00a0: Un, il fit capoter l&rsquo;accord sur la lib\u00e9ration des otages \u00e9tasuniens au Liban, conservant au Hezbollah son statut d&rsquo;ennemi num\u00e9ro un de l&rsquo;Occident\u00a0; deux, ce fut un message envoy\u00e9 \u00e0 tout le monde arabe, les convaincant de la v\u00e9ritable position des \u00c9tats-Unis d&rsquo;Am\u00e9rique dans le conflit isra\u00e9lo-arabe\u00a0; trois, cela am\u00e9liora brillamment l&rsquo;image du Mossad en interne, puisque c&rsquo;\u00e9tait eux, gr\u00e2ce \u00e0 une op\u00e9ration ing\u00e9nieuse, qui avaient pouss\u00e9 les USA \u00e0 faire ce qu&rsquo;il fallait faire<\/em>\u00a0\u00bb<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Credibilite_du_temoignage_dOstrovski\"><\/span><span style=\"color: #000000;\"><strong>Cr\u00e9dibilit\u00e9 du t\u00e9moignage d&rsquo;Ostrovski<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"color: #000000;\">La question de la cr\u00e9dibilit\u00e9 d&rsquo;un tel t\u00e9moignage se pose \u00e9videmment. En consid\u00e9ration de la nature de la source, c&rsquo;est \u00e0 dire un ex agent du Mossad, ce n&rsquo;est pas le genre de t\u00e9moignage qui se croise ais\u00e9ment.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nombre d&rsquo;arguments penchent n\u00e9anmoins en la faveur de la cr\u00e9dibilit\u00e9 de l&rsquo;homme. D&rsquo;abord, la r\u00e9action d&rsquo;une extr\u00eame vigueur du gouvernement isra\u00e9lien. Lorsque l&rsquo;agent du MI5 Peter Wright fit para\u00eetre un livre de r\u00e9v\u00e9lations sur les agissements des services de renseignements de l&rsquo;Angleterre, <a style=\"color: #000000;\" href=\"http:\/\/blockyourid.com\/%7Egbpprorg\/mil\/cavity\/Spycatcher.pdf\" target=\"_blank\" rel=\"nofollow noopener\">Spycatcher<\/a>, le gouvernement britannique r\u00e9agit vigoureusement, montrant ainsi indirectement que les informations d\u00e9voil\u00e9es pas cet agent avaient du poids. Une publicit\u00e9 \u00e9norme fut donn\u00e9e au livre qui devint un best seller dont aucune des r\u00e9v\u00e9lations n&rsquo;ont \u00e9t\u00e9 d\u00e9menties depuis. Le gouvernement isra\u00e9lien commit la m\u00eame erreur. Plut\u00f4t que de l&rsquo;ignorer, inquiet et piqu\u00e9, il tenta tous les recours pour en emp\u00eacher la parution. Isser Harel et Meir Amit, deux anciens dirigeants du Mossad, donn\u00e8rent du cr\u00e9dit \u00e0 Ostrovski en le pr\u00e9sentant comme une menace pour la s\u00e9curit\u00e9 nationale.<\/span><\/p>\n<figure id=\"attachment_125\" aria-describedby=\"caption-attachment-125\" style=\"width: 133px\" class=\"wp-caption alignleft\"><a class=\"noborder\" style=\"color: #000000;\" href=\"http:\/\/observatoire-terrorisme.com\/wp-content\/uploads\/2012\/05\/GordonThomas.jpg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-125\" title=\"GordonThomas\" src=\"https:\/\/www.agoravox.fr\/local\/cache-vignettes\/L133xH200\/GordonThomasdb55-94da5.jpg\" alt=\"\" width=\"133\" height=\"200\" \/><\/a><figcaption id=\"caption-attachment-125\" class=\"wp-caption-text\"><span style=\"color: #000000;\">l&rsquo;historien Gordon Thomas<\/span><\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">Gordon Thomas, auteur de <a style=\"color: #000000;\" href=\"http:\/\/metreya.blog.lemonde.fr\/2008\/11\/29\/histoire-secrete-du-mossad-de-gordon-thomas\/\" target=\"_blank\" rel=\"nofollow noopener\">l&rsquo;Histoire Secr\u00e8te du Mossad<\/a>, rapporte ainsi l&rsquo;histoire de la parution du livre d&rsquo;Ostrovski\u00a0: \u00ab\u00a0<em>(Ses deux livres) ont lev\u00e9 un important coin du voile sur le fonctionnement interne du Mossad. On y d\u00e9crivait les m\u00e9thodes op\u00e9rationnelles du service et nommait de nombreux agents encore en activit\u00e9\u00a0; il est possible qu&rsquo;il ait compromis certains au fil de ses r\u00e9v\u00e9lations vengeresses, persuad\u00e9 qu&rsquo;il \u00e9tait d&rsquo;avoir \u00e9t\u00e9 plus qu&rsquo;injustement trait\u00e9 lors de son \u00e9viction du Mossad.\u00a0<\/em>\u00a0\u00bb (Thomas, histoire secr\u00e8te du Mossad, p 281) Les r\u00e9actions furent vives en Isra\u00ebl et dans les rangs du Mossad\u00a0: \u00ab\u00a0<em>Ostrovski fut la cible d&rsquo;une importante campagne de d\u00e9nigrement dans le groupe Mirror, et aussi dans Maariv, le grand journal du soir de Tel Aviv rachet\u00e9 par Maxwell, o\u00f9 il fut abondamment trait\u00e9 de mythomane, de calomniateur et de faux ami d&rsquo;Isra\u00ebl. Or, pour avoir \u00e9pluch\u00e9 ces deux livres, les membres les plus haut plac\u00e9s des services secrets isra\u00e9liens savaient que l&rsquo;essentiel de ces informations \u00e9taient v\u00e9ridiques.<\/em>\u00a0\u00bb (Thomas, p 283)<\/span><\/p>\n<figure id=\"attachment_127\" aria-describedby=\"caption-attachment-127\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a class=\"noborder\" style=\"color: #000000;\" href=\"http:\/\/observatoire-terrorisme.com\/wp-content\/uploads\/2012\/05\/Gilad-Atzmon2.jpg\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-127\" title=\"Gilad-Atzmon2\" src=\"https:\/\/www.agoravox.fr\/local\/cache-vignettes\/L150xH150\/Gilad-Atzmon438b-00253.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-127\" class=\"wp-caption-text\"><span style=\"color: #000000;\">l&rsquo;essayiste Gilad Atzmon<\/span><\/figcaption><\/figure>\n<p><span style=\"color: #000000;\">Sur l&rsquo;affaire Ostrovski on peut aussi citer Gilad Atzmon, dans <a style=\"color: #000000;\" href=\"http:\/\/www.silviacattori.net\/article3060.html\" rel=\"nofollow\">La Parabole d&rsquo;Esther,<\/a> r\u00e9cemment paru aux \u00e9ditions Demi Lune \u00ab\u00a0<em>Je consid\u00e8re comme cr\u00e9dible le t\u00e9moignage d&rsquo;Ostrovski. Comme nous le savons, le gouvernement isra\u00e9lien a recouru \u00e0 tous les moyens possibles et imaginables pour emp\u00eacher la publication de ses livres.\u00a0\u00bb <\/em>A l&rsquo;appui de cette assertion Atzmon rappelle <a style=\"color: #000000;\" href=\"http:\/\/web.archive.org\/web\/20100420011727\/http:\/\/www.washington-report.org\/backissues\/0195\/9501017.htm\" target=\"_blank\" rel=\"nofollow noopener\">cette r\u00e9action d&rsquo;un \u00e9ditorialiste isra\u00e9lien de renom, Joseph Lapid<\/a>, qui devait devenir par la suite ministre de la justice du gouvernement d&rsquo;Ariel Sharon<em>\u00a0: \u00ab\u00a0Ostrovski est le Juif le plus f\u00e9lon de toute l&rsquo;histoire juive moderne. Il n&rsquo;a pas le droit \u00e0 la vie, sauf s&rsquo;il est pr\u00eat \u00e0 rentrer en Isra\u00ebl et \u00e0 y affronter la justice. (\u2026) je dis les choses exactement comme je les pense. Malheureusement le Mossad ne peut pas s&rsquo;en charger, parce que nous ne pouvons pas mettre nos relations avec le Canada en danger. Mais j&rsquo;esp\u00e8re qu&rsquo;il y a un Juif honn\u00eate, au Canada, qui le fera pour nous. (\u2026) Cela ne serait que justice pour un homme qui a fait la chose la plus horrible \u00e0 laquelle un Juif puisse penser, \u00e0 savoir vendre l\u2019\u00c9tat juif et le peuple juif \u00e0 nos ennemis, pour de l&rsquo;argent. Il n&rsquo;y a rien de pire qu&rsquo;un \u00eatre humain puisse faire, si tant est qu&rsquo;Ostrovski puisse \u00eatre qualifi\u00e9 de la sorte.\u00a0\u00bb <\/em>Et Atzmon d&rsquo;appuyer\u00a0:<em> \u00ab\u00a0Un journaliste isra\u00e9lien, futur ministre de la Justice isra\u00e9lien, exprime ici les opinions les plus scandaleuses. Il encourage un coreligionnaire juif \u00e0 perp\u00e9trer un assassinat au nom de la fraternit\u00e9 juive. En bref, non seulement Lapid confirme les r\u00e9v\u00e9lations d&rsquo;Ostrovski sur le monde invisible des sayyanim, mais il confirme l&rsquo;opinion de Weizmann, selon qui, d&rsquo;un point de vue sioniste, il n&rsquo;existe pas de Canadiens juifs, mais uniquement des Juifs r\u00e9sidant au Canada. Toutefois Lapid affirme aussi qu&rsquo;un juif vivant au Canada devrait se comporter en assassin, au service de ce qu&rsquo;il consid\u00e8re comme la cause juive.<\/em>\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/raknagar.blogspot.fr\/2007\/10\/tmoignages-de-victor-ostrovsky-sur-le.html\" target=\"_blank\" rel=\"nofollow noopener\">La campagne de d\u00e9nigrement m\u00e9diatique<\/a> dont fut l&rsquo;objet Ostrovski au Canada et aux \u00c9tats-Unis \u00e0 l&rsquo;occasion de la parution de son livre est encore un autre indice de sa cr\u00e9dibilit\u00e9. Si Ostrovski fut invit\u00e9 \u00e0 de nombreuses \u00e9missions de radio ou de t\u00e9l\u00e9vision (en raison du scandale et du succ\u00e8s de son livre), il \u00e9tait presque toujours confront\u00e9 \u00e0 un \u00ab\u00a0intellectuel\u00a0\u00bb visiblement tr\u00e8s soucieux de la r\u00e9putation d&rsquo;Isra\u00ebl, qui lui \u00e9tait hostile, et qui souvent n&rsquo;avait pas lu son livre. Le format court des \u00e9missions l&#8217;emp\u00eachait de d\u00e9velopper suffisamment son propos. Ce traitement m\u00e9diatique n&rsquo;a rien exceptionnel aux Etats-Unis ou le lobby pro-isra\u00e9lien (voir le livre de Mearsheimer et Walt, qui en donne un compte-rendu \u00e9difiant), exerce une influence consid\u00e9rable sur toute une partie du volet proche et moyen-oriental de la politique \u00e9trang\u00e8re \u00e9tasunienne, veille au grain pour chasser toutes les sorci\u00e8res qui se hasardent \u00e0 critiquer la politique d\u2019Isra\u00ebl.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><em>Ici prend fin la seconde partie de l&rsquo;\u00e9tude de l&rsquo;ODME sur l&rsquo;attentat de La Belle. La semaine prochaine, nous \u00e9voquerons l&rsquo;indemnisation par la Libye des victimes de la Belle en 2004, et nous essaierons de r\u00e9\u00e9valuer les responsabilit\u00e9s des diff\u00e9rents \u00e9tats \u00e9voqu\u00e9s dans la planification et la mise en \u0153uvre de cet attentat.<\/em><\/strong><\/span><\/p>\n<div><span style=\"color: #000000;\">\u00a0<em>Fran\u00e7ois Belliot, pour l&rsquo;Observatoire Des Mensonges d&rsquo;\u00c9tat<\/em><\/span><\/div>\n<div><\/div>\n<p><span style=\"color: #000000;\"><strong>Notes<\/strong><\/span><\/p>\n<div>\n<p><span style=\"color: #000000;\"><a style=\"color: #000000;\" title=\"\" href=\"https:\/\/mail.google.com\/mail\/u\/0\/?ui=2&amp;view=bsp&amp;ver=ohhl4rw8mbn4#_ftnref\" rel=\"nofollow\">[1]<\/a> John Goetz, dans le num\u00e9ro de Covert Action de printemps 1996 \u00e9tait d\u00e9j\u00e0 arriv\u00e9 \u00e0 la conclusion, en \u00e9tudiant des archives du KGB, qu&rsquo;Abu Jaber \u00e9tait un informateur de la CIA et qu&rsquo;il s&rsquo;\u00e9tait entretenu avec son agent correspondant deux jours avant l&rsquo;attentat pour y fixer le prix de l&rsquo;op\u00e9ration \u00e0 30000 dollars.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir expos\u00e9, dans la premi\u00e8re partie de cette \u00e9tude, le d\u00e9roulement de l\u2019attentat de la discoth\u00e8que La Belle survenu \u00e0 Berlin ouest en avril 1986, et le bombardement subs\u00e9quent de la Libye par les \u00c9tats-Unis lors de l\u2019op\u00e9ration El Dorado Canyon, nous en venons au r\u00e9cit du proc\u00e8s qui s\u2019ouvre en novembre 1997, et &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;L&rsquo;attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3)&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86],"tags":[103,101,107,105,68,104,67,102,83,106],"class_list":["post-151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-operations-sou-faux-drapeau","tag-detlev-mehlis","tag-gilad-atzmon","tag-gordon-thomas","tag-hariri","tag-kadhafi","tag-liban","tag-libye","tag-mossad","tag-sayanim","tag-victor-ostrovski"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3) - Fran\u00e7ois Belliot<\/title>\n<meta name=\"description\" content=\"Dans la seconde partie de cette \u00e9tude nous nous int\u00e9ressons \u00e0 l\u2019\u00e9lucidation de l\u2019affaire dans son ensemble, qui devient possible \u00e0 partir de 1997.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3) - Fran\u00e7ois Belliot\" \/>\n<meta property=\"og:description\" content=\"Dans la seconde partie de cette \u00e9tude nous nous int\u00e9ressons \u00e0 l\u2019\u00e9lucidation de l\u2019affaire dans son ensemble, qui devient possible \u00e0 partir de 1997.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Fran\u00e7ois Belliot\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-05T08:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-13T09:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francoisbelliot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"francoisbelliot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/\",\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/\",\"name\":\"L'attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3) - Fran\u00e7ois Belliot\",\"isPartOf\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg\",\"datePublished\":\"2014-08-05T08:00:11+00:00\",\"dateModified\":\"2018-08-13T09:11:01+00:00\",\"author\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\"},\"description\":\"Dans la seconde partie de cette \u00e9tude nous nous int\u00e9ressons \u00e0 l\u2019\u00e9lucidation de l\u2019affaire dans son ensemble, qui devient possible \u00e0 partir de 1997.\",\"breadcrumb\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#primaryimage\",\"url\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg\",\"contentUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg\",\"width\":620,\"height\":465,\"caption\":\"Kadhafi a \u00e9t\u00e9 du premier au dernier de ses jours de pouvoir dans la ligne de mire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/francoisbelliot.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/francoisbelliot.fr\/#website\",\"url\":\"https:\/\/francoisbelliot.fr\/\",\"name\":\"Fran\u00e7ois Belliot\",\"description\":\"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/francoisbelliot.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\",\"name\":\"francoisbelliot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"caption\":\"francoisbelliot\"},\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3) - Fran\u00e7ois Belliot","description":"Dans la seconde partie de cette \u00e9tude nous nous int\u00e9ressons \u00e0 l\u2019\u00e9lucidation de l\u2019affaire dans son ensemble, qui devient possible \u00e0 partir de 1997.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/","og_locale":"fr_FR","og_type":"article","og_title":"L'attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3) - Fran\u00e7ois Belliot","og_description":"Dans la seconde partie de cette \u00e9tude nous nous int\u00e9ressons \u00e0 l\u2019\u00e9lucidation de l\u2019affaire dans son ensemble, qui devient possible \u00e0 partir de 1997.","og_url":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/","og_site_name":"Fran\u00e7ois Belliot","article_published_time":"2014-08-05T08:00:11+00:00","article_modified_time":"2018-08-13T09:11:01+00:00","og_image":[{"width":620,"height":465,"url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg","type":"image\/jpeg"}],"author":"francoisbelliot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"francoisbelliot","Dur\u00e9e de lecture estim\u00e9e":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/","url":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/","name":"L'attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3) - Fran\u00e7ois Belliot","isPartOf":{"@id":"https:\/\/francoisbelliot.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#primaryimage"},"image":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#primaryimage"},"thumbnailUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg","datePublished":"2014-08-05T08:00:11+00:00","dateModified":"2018-08-13T09:11:01+00:00","author":{"@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9"},"description":"Dans la seconde partie de cette \u00e9tude nous nous int\u00e9ressons \u00e0 l\u2019\u00e9lucidation de l\u2019affaire dans son ensemble, qui devient possible \u00e0 partir de 1997.","breadcrumb":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#primaryimage","url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg","contentUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2014\/08\/labelle2.jpg","width":620,"height":465,"caption":"Kadhafi a \u00e9t\u00e9 du premier au dernier de ses jours de pouvoir dans la ligne de mire"},{"@type":"BreadcrumbList","@id":"https:\/\/francoisbelliot.fr\/index.php\/2014\/08\/05\/lattentat-de-la-discotheque-la-belle-en-avril-1986-premier-casus-belli-contre-la-libye-de-kadhafi-2-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francoisbelliot.fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;attentat de la discoth\u00e8que La Belle en avril 1986, premier casus belli contre la Libye de Kadhafi (2\/3)"}]},{"@type":"WebSite","@id":"https:\/\/francoisbelliot.fr\/#website","url":"https:\/\/francoisbelliot.fr\/","name":"Fran\u00e7ois Belliot","description":"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francoisbelliot.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9","name":"francoisbelliot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","caption":"francoisbelliot"},"url":"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/"}]}},"_links":{"self":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":0,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media\/336"}],"wp:attachment":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}