{"id":1135,"date":"2020-11-30T17:57:10","date_gmt":"2020-11-30T16:57:10","guid":{"rendered":"https:\/\/francoisbelliot.fr\/?p=1135"},"modified":"2024-06-20T18:13:39","modified_gmt":"2024-06-20T16:13:39","slug":"la-covid-19-au-prisme-de-moliere-1-3","status":"publish","type":"post","link":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/","title":{"rendered":"La Covid-19 au prisme de Moli\u00e8re (1\/3)"},"content":{"rendered":"\n<figure class=\"wp-block-pullquote\"><blockquote><p>\u00ab&nbsp;<em>Il y a de certains esprits qu\u2019il ne faut prendre qu\u2019en biaisant&nbsp;<\/em>\u00bb<\/p><cite>Val\u00e8re, dans <em>L\u2019avare ou l\u2019\u00e9cole du mensonge<\/em>, acte I, sc\u00e8ne 8<\/cite><\/blockquote><\/figure>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_71 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a57aed99f033\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a57aed99f033\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#Introduction\" title=\"Introduction\">Introduction<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#Premiere_partie_Moliere_dans_le_texte\" title=\"Premi\u00e8re partie: Moli\u00e8re dans le texte\">Premi\u00e8re partie: Moli\u00e8re dans le texte<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#M_Jourdain_le_bourgeois_qui_veut_devenir_gentilhomme\" title=\"M. Jourdain, le bourgeois qui veut devenir gentilhomme\">M. Jourdain, le bourgeois qui veut devenir gentilhomme<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#Argan_le_malade_imaginaire\" title=\"Argan, le malade imaginaire\">Argan, le malade imaginaire<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#Orgon_lobsede_du_salut_de_son_ame\" title=\"Orgon, l\u2019obs\u00e9d\u00e9 du salut de son \u00e2me\">Orgon, l\u2019obs\u00e9d\u00e9 du salut de son \u00e2me<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#Philaminte_la_femme_savante\" title=\"Philaminte, la femme savante\">Philaminte, la femme savante<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Introduction\"><\/span><strong>Introduction<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Si d\u2019aventure cette \u00e9tude se r\u00e9v\u00e9lait de quelque utilit\u00e9 pour arracher au moins quelques esprits pris au pi\u00e8ge dans la toile du discours sanitaire anti Covid martel\u00e9 quotidiennement depuis pr\u00e8s de neuf fois par les m\u00e9dias et les politiques des d\u00e9mocraties occidentales, je m\u2019estimerais pay\u00e9 au centuple des efforts qu\u2019elle m\u2019a co\u00fbt\u00e9 en imagination, relectures, et composition. Qui sait si, forts de leur exp\u00e9rience de prisonniers de la caverne tout frais sortis \u00e0 l\u2019air libre et pur du dehors, ils se sentiront une ardeur vierge et puissante pour venir grossir les rangs des \u00e9carteurs de paupi\u00e8res et arracheurs de cha\u00eenes, qui doivent encore endurer sans pouvoir r\u00e9pliquer haut et fort les calomnies et diffamations publiques continuelles des marionnettistes qui maintiennent sous hypnose les esprits depuis les \u00e9crans de t\u00e9l\u00e9vision, les baffles des radios, les pages des quotidiens et magazines, et les autels des minist\u00e8res, avec leur jeu perp\u00e9tuel d&rsquo;ombres trompeuses projet\u00e9es <a rel=\"noreferrer noopener\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2014\/06\/16\/lallegorie-de-la-caverne-au-xxieme-siecle\/\" target=\"_blank\">sur le fond du salon<\/a>.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p><\/p>\n\n\n\n<p>Si seulement nous disposions d\u2019un peu de temps et de s\u00e9r\u00e9nit\u00e9, s\u2019il \u00e9tait possible de forcer tous nos compagnons d\u2019infortune \u00e0 faire retraite pendant plusieurs semaines en quelque endroit paisible et sacr\u00e9, pour qu\u2019ils oublient le tintamarre absurde et ali\u00e9nant dont ils sont en permanence \u00e9tourdis&nbsp;! H\u00e9las, le temps de cerveau disponible est ce qui le plus cruellement nous manque&nbsp;: Covid, Covid, Covid, Black Lives Matter, Covid, Covid, Charlie Hebdo, Covid, Charlie Hebdo, Covid, Trump, Covid, Trump, Covid, Covid, Covid\u2026 les marionnettistes sollicitent contin\u00fbment les m\u00e9ninges collectives, ne laissant pas une seconde de r\u00e9pit, m\u00eame dans les r\u00eaves, aux ombres d\u2019esprits libres que tant d\u2019entre nous sommes devenus&nbsp;! Le recul est impossible, d\u00e8s que la t\u00eate du clou se rel\u00e8ve un peu, un coup de marteau plus fort revient la maintenir au ras du cr\u00e2ne.<\/p>\n\n\n\n<p>Je veux ici pousser le lecteur \u00e0 prendre un recul de 350 ann\u00e9es. Peut-\u00eatre que plac\u00e9 d\u2019un coup \u00e0 cette distance, le son assourdi de la propagande pour un moment d\u00e9cisif lui appara\u00eetra pour ce qu\u2019il est, c\u2019est-\u00e0-dire absurde, cacophonique, \u00e9touffant, tout entier p\u00e9tri de mensonges et gonfl\u00e9 par le levain des intentions les plus noires.<\/p>\n\n\n\n<p>Replongeons-nous dans quelques unes des plus c\u00e9l\u00e8bres com\u00e9dies de Moli\u00e8re, dans l\u2019ordre le <em>Bourgeois Gentilhomme<\/em>, le <em>Malade imaginaire<\/em>, <em>Tartuffe<\/em>, et <em>les Femmes savantes.<\/em> Nous allons commencer, dans cette premi\u00e8re partie, par les r\u00e9sumer en nous concentrant sur les extraits et d\u00e9tails utiles au traitement que je propose d\u2019administrer &#8211; une sorte de th\u00e9rapie \u00e0 base d\u2019antiviral litt\u00e9raire -, et en restituant les r\u00e9pliques o\u00f9 les marionnettes que sont les personnages principaux passent soudain de l\u2019obscurit\u00e9 \u00e0 la lumi\u00e8re, de la maladie \u00e0 la gu\u00e9rison, de l\u2019\u00e9garement \u00e0 la raison. Je sugg\u00e8re d\u2019embl\u00e9e au patient, pour accro\u00eetre l\u2019efficace du traitement, en guise d&rsquo;antibiotique, de remplacer spontan\u00e9ment les \u00ab\u00a0m\u00e9decins\u00a0\u00bb, \u00ab\u00a0d\u00e9vots\u00a0\u00bb et \u00ab\u00a0bel esprit\u00a0\u00bb, par \u00ab\u00a0journalistes\u00a0\u00bb, \u00ab\u00a0experts\u00a0\u00bb, et \u00ab\u00a0politiques\u00a0\u00bb ; les dupes par \u00ab\u00a0opinion publique\u00a0\u00bb, \u00ab\u00a0population\u00a0\u00bb ou \u00ab\u00a0t\u00e9l\u00e9spectateurs\u00a0\u00bb ; les membres de leur entourage qui s&rsquo;efforcent de les d\u00e9senvo\u00fbter, par \u00ab\u00a0lanceurs d\u2019alerte\u00a0\u00bb, \u00ab\u00a0sonneurs de tocsin\u00a0\u00bb, \u00ab\u00a0bons samaritains\u00a0\u00bb, \u00ab\u00a0sauveteurs en mer\u00a0\u00bb, \u00ab\u00a0pompiers volontaires\u00a0\u00bb. Je pourrais ici donner des noms mais je m\u2019en garderai bien, de crainte de faire fuir d\u00e8s l\u2019or\u00e9e de la for\u00eat la foule des malades en craintif troupeau, que le chien de berger m\u00e9diatique terrorise et regroupe encore avec ses harcelants \u00ab Waf&nbsp;! Waf&nbsp;!&nbsp;\u00bb.<\/p>\n\n\n\n<p>De cette pelote ensuite nous t\u00e2cherons de tirer, dans le volet suivant, quelques fils analogiques vers l\u2019actualit\u00e9 de ces neuf derniers mois surdos\u00e9e de Covid-19.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Premiere_partie_Moliere_dans_le_texte\"><\/span><strong>Premi\u00e8re partie: Moli\u00e8re dans le texte<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Parmi les personnages de Moli\u00e8re, ceux dont le ressort comique est le plus puissant, ceux qui donc pr\u00eatent le plus \u00e0 rire, sont les riches barbons que domine enti\u00e8rement une obsessionnelle lubie. D\u2019une pi\u00e8ce \u00e0 l\u2019autre, le type est \u00e0 peu apr\u00e8s invariable&nbsp;: p\u00e8re de famille, il r\u00e8gne en tyran, \u00e9chafaudant pour lui-m\u00eame ou ses enfants des plans de mariage o\u00f9 il ne consid\u00e8re que son int\u00e9r\u00eat propre. But\u00e9 au dernier degr\u00e9, n\u2019\u00e9coutant que lui-m\u00eame et comptant pour rien l\u2019opinion de ses proches, il a en outre l\u2019infortune d\u2019\u00eatre sous l\u2019empire invincible d\u2019une lubie, phobie, obsession, id\u00e9e fixe, qui en fait le pigeon par excellence pour les escrocs, charlatans, et parasites en tous genres suffisamment habiles pour \u00e9pouser sa pente. Il est la ris\u00e9e et le sujet d\u2019indignation de presque toute la maisonn\u00e9e, jusqu\u2019\u00e0 sa servante qui l\u2019emporte \u00e0 tout coup du point de vue du bon sens en le faisant plaisamment tourner en bourrique.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"M_Jourdain_le_bourgeois_qui_veut_devenir_gentilhomme\"><\/span><strong>M. Jourdain, le bourgeois qui veut devenir gentilhomme<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Dans le <em>Bourgeois Gentilhomme<\/em>, M. Jourdain est, comme le sugg\u00e8re le titre de la pi\u00e8ce, un riche parvenu dont l\u2019ambition maladive est de devenir un membre reconnu de la noblesse. Il devient ainsi la cible de toutes sortes de \u00ab&nbsp;ma\u00eetres&nbsp;\u00bb v\u00e9reux et int\u00e9ress\u00e9s, qui de musique, qui de danse, qui d\u2019armes, qui de philosophie, qu\u2019il paie \u00e0 prix d\u2019or pour apprendre les usages des \u00ab&nbsp;gens de qualit\u00e9&nbsp;\u00bb. Alors que tout le monde dans la maisonn\u00e9e, sa femme et sa servante Nicole au premier chef, est douloureusement conscient qu\u2019il est la dupe de tous ces flatteurs attir\u00e9s par son argent, qui chacun l\u2019\u00e9blouissent avec le jargon propre \u00e0 leur art, ne parvenant avec leurs le\u00e7ons qu\u2019au r\u00e9sultat le plus gauche et le plus ridicule, M. Jourdain finit par se laisser convaincre, dans la pens\u00e9e d\u2019atteindre tout de bon le dernier \u00e9tage de l\u2019ascenseur social, d\u2019accorder la main de sa fille Lucie au fils du grand Turc, qui le sollicite avec force flatteries \u00e0 cet effet&nbsp;; cela lui permettra en m\u00eame temps de devenir <em>Mamamouchi<\/em>, acc\u00e9dant ainsi \u00e0 une dignit\u00e9 qui dans son fol et influen\u00e7able esprit surpasse la plus haute noblesse fran\u00e7aise. Or il s\u2019agit d\u2019une ruse mise en \u0153uvre par l\u2019amant de sa fille, Cl\u00e9onte, jeune homme plein de m\u00e9rite mais qui n\u2019a pas l\u2019heur d\u2019\u00eatre gentilhomme. Sous l\u2019habit de fils du Grand Turc, c\u2019est Cl\u00e9onte qui finalement parvient \u00e0 \u00e9pouser celle qu\u2019il aime d\u2019un amour r\u00e9ciproque. La b\u00eatise de M. Jourdain est si crasse et son obsession si obnubilante, qu\u2019ils sont parvenus \u00e0 le circonvenir en usant de cet improbable stratag\u00e8me.<\/p>\n\n\n\n<p>Mme Jourdain explose de col\u00e8re en apprenant la nouvelle\u00a0:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">MADAME JOURDAIN.- Comment donc, qu\u2019est-ce que c\u2019est que ceci\u00a0? \nOn dit que vous voulez donner votre fille\nen mariage \u00e0 un car\u00eame-prenant.\nMONSIEUR JOURDAIN.- Voulez-vous vous taire, impertinente\u00a0? \nVous venez toujours m\u00ealer vos extravagances \u00e0 toutes choses, \net il n\u2019y a pas moyen de vous apprendre \u00e0 \u00eatre raisonnable.\nMADAME JOURDAIN.- <u>C\u2019est vous qu\u2019il n\u2019y a pas moyen de rendre sage,<\/u>\n<u>et vous allez de folie en folie.<\/u> \nQuel est votre dessein, et que voulez-vous faire\navec cet assemblage\u00a0?<\/pre>\n<\/div><\/div>\n\n\n\n<p>S\u2019ensuit alors une violente dispute qui cesse soudain quand Covielle, le valet de Cl\u00e9onte qui a eu l\u2019id\u00e9e du stratag\u00e8me, parvient enfin \u00e0 mettre Mme Jourdain dans la confidence&nbsp;: \u00ab&nbsp;<em>Il y a une heure, Madame, que nous vous faisons signe. Ne voyez-vous pas bien que <\/em><em><u>tout ceci n\u2019est fait que pour nous ajuster aux visions de votre mari<\/u><\/em><em>, que nous l\u2019abusons sous ce d\u00e9guisement, et que c\u2019est Cl\u00e9onte lui-m\u00eame qui est le fils du Grand Turc&nbsp;?<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p>A la diff\u00e9rence d\u2019Argon et d\u2019Argan dont nous allons parler, M. Jourdain n\u2019a pas le privil\u00e8ge d\u2019une r\u00e9v\u00e9lation finale propre \u00e0 lui remettre l\u2019esprit \u00e0 l\u2019endroit. Juste avant que l\u2019ubuesque c\u00e9r\u00e9monie commence, c\u2019est Covielle qui prononce la derni\u00e8re r\u00e9plique de la pi\u00e8ce&nbsp;: \u00ab&nbsp;<em>Si l\u2019on en peut voir un plus fou, je l\u2019irai dire \u00e0 Rome.&nbsp;<\/em>\u00bb<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Argan_le_malade_imaginaire\"><\/span><strong>Argan, le malade imaginaire<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Argan, le personnage central du <em>Malade imaginaire<\/em>, est une caricature d\u2019hypocondriaque. Persuad\u00e9 d\u2019\u00eatre un fini val\u00e9tudinaire, vivant dans la hantise continuelle de la mort, il passe ses journ\u00e9es \u00e0 prendre tous les traitements possibles et imaginables, \u00e0 la composition souvent abracadabrante, d\u00e9pensant des fortunes en consultations de m\u00e9decins et en ordonnances de m\u00e9decines. Trois charlatans ont bien compris cette faille psychologique et tout le profit qu\u2019ils pouvaient en tirer&nbsp;: un apothicaire, Monsieur Fleurant, et deux m\u00e9decins&nbsp;: Monsieur Purgon et Monsieur Diafoirus qui lui font des visites continuelles, en ayant soin de le conforter dans sa phobie, au besoin en le terrorisant, afin que jamais le filon ne se tarisse. Ceux-ci ont fini par acqu\u00e9rir aux yeux d\u2019Argan une valeur sup\u00e9rieure \u00e0 celle de son entourage proche, sa femme \u00e9pous\u00e9e en secondes noces B\u00e9line except\u00e9e, celle-ci l\u2019ayant su s\u00e9duire en caressant complaisamment son temp\u00e9rament maladif dans le sens du poil, dans l\u2019espoir, \u00e0 sa mort qu\u2019elle esp\u00e8re prochaine, de frustrer de leur h\u00e9ritage les deux filles issues de son premier mariage, Ang\u00e9lique et Louison. Afin d\u2019\u00e9teindre une bonne fois pour toutes, croit-il, l\u2019id\u00e9e fixe qui lui ronge la cervelle, Argan finit par arr\u00eater la d\u00e9cision de marier sa fille a\u00een\u00e9e Ang\u00e9lique au fils de Monsieur Diafoirus, Thomas Diafoirus, qui vient d\u2019\u00eatre re\u00e7u m\u00e9decin \u00e0 la facult\u00e9&nbsp;; au grand d\u00e9sespoir de celle-ci qui est amoureuse du jeune Cl\u00e9ante avec qui elle projetait de se marier.<\/p>\n\n\n\n<p>Le fr\u00e8re d\u2019Argan, B\u00e9ralde, qui dans la pi\u00e8ce incarne le bon sens et la mesure, d\u00e9ploie des tr\u00e9sors de rh\u00e9torique pour le faire revenir \u00e0 la raison, d\u2019autant qu\u2019il a vu clair dans le jeu des m\u00e9decins et de B\u00e9line. Cela donne lieu, dans la sc\u00e8ne 3 de l\u2019acte III, \u00e0 l\u2019\u00e9change suivant\u00a0:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">ARGAN.\u2014 Mais raisonnons un peu, mon fr\u00e8re. \n<u>Vous ne croyez donc point \u00e0 la m\u00e9decine?<\/u>\nB\u00c9RALDE.\u2014 Non, mon fr\u00e8re, et je ne vois pas \nque pour son salut, il soit n\u00e9cessaire d'y croire.\nARGAN.\u2014 <u>Quoi vous ne tenez pas v\u00e9ritable une chose \u00e9tablie <\/u>\n<u>par tout le monde, et que tous les si\u00e8cles ont r\u00e9v\u00e9r\u00e9e?<\/u>\nB\u00c9RALDE.\u2014 Bien loin de la tenir v\u00e9ritable, \nje la trouve entre nous, une des plus grandes folies \nqui soit parmi les hommes\u00a0; et \u00e0 regarder \nles choses en philosophe, je ne vois point \nde plus plaisante momerie; je ne vois rien de plus ridicule, \nqu'un homme qui se veut m\u00ealer d'en gu\u00e9rir un autre.\nB\u00c9RALDE.\u2014 Par la raison, mon fr\u00e8re, que les ressorts \nde notre machine sont des myst\u00e8res jusques ici, \no\u00f9 les hommes ne voient goutte; \net que la nature nous a mis au-devant des yeux\n des voiles trop \u00e9pais pour y conna\u00eetre quelque chose.\nARGAN.\u2014 <u>Les m\u00e9decins ne savent donc rien, \u00e0 votre compte?<\/u>\nB\u00c9RALDE.\u2014 <u>Si fait<\/u>, mon fr\u00e8re. <u>Ils<\/u> savent la plupart \nde fort belles humanit\u00e9s; <u>savent parler en beau latin, <\/u>\n<u>savent nommer en grec toutes les maladies, les d\u00e9finir, <\/u>\n<u>et les diviser; mais pour ce qui est de les gu\u00e9rir, <\/u>\n<u>c'est ce qu'ils ne savent point du tout.<\/u>\nARGAN.\u2014 Mais toujours faut-il demeurer d'accord, \nque sur cette mati\u00e8re les m\u00e9decins \nen savent plus que les autres.\nB\u00c9RALDE.\u2014 Ils savent, mon fr\u00e8re, ce que je vous ai dit, \nqui ne gu\u00e9rit pas de grand-chose, \net<u> toute l'excellence de leur art <\/u>\n<u>consiste en un pompeux galimatias, <\/u>\n<u>en un sp\u00e9cieux babil, qui vous donne des mots pour des raisons, <\/u>\n<u>et des promesses pour des effets.<\/u>\nARGAN.\u2014 Mais enfin, mon fr\u00e8re, il y a des gens aussi sages \net aussi habiles que vous; et nous voyons \nque dans la maladie tout le monde a recours aux m\u00e9decins.\nB\u00c9RALDE.\u2014 C'est une marque de la faiblesse humaine, \net non pas de la v\u00e9rit\u00e9 de leur art.\nARGAN.\u2014 Mais il faut bien que les m\u00e9decins croient \nleur art v\u00e9ritable, puisqu'ils s'en servent pour eux-m\u00eames.\nB\u00c9RALDE.\u2014 <u>C'est qu'il y en a parmi eux, qui sont eux-m\u00eames <\/u>\n<u>dans l'erreur populaire, dont ils profitent, <\/u>\n<u>et d'autres qui en profitent sans y \u00eatre.<\/u>(...)<\/pre>\n<\/div><\/div>\n\n\n\n<p>A la sc\u00e8ne 16 de l\u2019acte III, B\u00e9ralde tente de lui ouvrir les yeux sur la fausset\u00e9 de B\u00e9line \u00e0 qui, se croyant parvenu \u00e0 la derni\u00e8re extr\u00e9mit\u00e9, il a confi\u00e9 une tr\u00e8s forte somme d\u2019argent, prise sur l\u2019h\u00e9ritage du \u00e0 ses deux filles&nbsp;:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">B\u00c9RALDE<em>.\u2014 <\/em>H\u00e9 bien oui, mon fr\u00e8re, \npuisqu'il faut parler \u00e0 c\u0153ur ouvert, \nc'est votre femme que je veux dire\u00a0; \net non plus que l'ent\u00eatement de la m\u00e9decine, \nje ne puis souffrir l'ent\u00eatement o\u00f9 vous \u00eates pour elle, \net voir que vous donniez t\u00eate baiss\u00e9e \ndans tous les pi\u00e8ges qu'elle vous tend.<\/pre>\n<\/div><\/div>\n\n\n\n<p>C\u2019est finalement sa servante Toinette qui va trouver le moyen d\u2019enfin lui faire ouvrir les yeux sur ces rapaces qui lui tournent autour, sa femme en particulier. Il se refuse \u00e0 entendre aucun discours raisonnable\u00a0? alors qu\u2019il entende, \u00e9nonc\u00e9es \u00e0 coeur ouvert, les v\u00e9ritables pens\u00e9es de B\u00e9line. Et pour obtenir ce d\u00e9voilement, quel meilleur stratag\u00e8me que d\u2019annoncer faussement sa mort, et d\u2019observer en cadavre attentif la r\u00e9action des uns et des autres\u00a0? Sur ce survient B\u00e9line. Comme Toinette faussement \u00e9plor\u00e9e lui apprend l\u2019affreuse nouvelle, en prenant soin de pr\u00e9ciser qu\u2019elle est la premi\u00e8re \u00e0 en prendre connaissance, loin de fondre en larmes elle exulte\u00a0:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">B\u00c9LINE.\u2014 Le Ciel en soit lou\u00e9. \nMe voil\u00e0 d\u00e9livr\u00e9e d\u2019un grand fardeau. \nQue tu es sotte, Toinette, de t\u2019affliger de cette mort\u00a0!\nTOINETTE.\u2014 Je pensais, Madame, qu\u2019il fall\u00fbt pleurer.\nB\u00c9LINE.\u2014 Va, va, cela n\u2019en vaut pas la peine. \nQuelle perte est-ce que la sienne, \net de quoi servait-il sur la terre\u00a0? \nUn homme incommode \u00e0 tout le monde, malpropre, d\u00e9go\u00fbtant, \nsans cesse un lavement, ou une m\u00e9decine dans le ventre, \nmouchant, toussant, crachant toujours, sans esprit, \nennuyeux, de mauvaise humeur, \nfatiguant sans cesse les gens, \net grondant jour et nuit servantes, et valets.\nTOINETTE.\u2014 Voil\u00e0 une belle oraison fun\u00e8bre.\nB\u00c9LINE.\u2014 Il faut, Toinette, \nque tu m\u2019aides \u00e0 ex\u00e9cuter mon dessein,\net tu peux croire qu\u2019en me servant ta r\u00e9compense est s\u00fbre. \nPuisque par un bonheur personne \nn\u2019est encore averti de la chose, \nportons-le dans son lit, et tenons cette mort cach\u00e9e, \njusqu\u2019\u00e0 ce que j\u2019aie fait mon affaire. Il y a des papiers, \nil y a de l\u2019argent, dont je me veux saisir, \net il n\u2019est pas juste que j\u2019aie pass\u00e9 sans fruit \naupr\u00e8s de lui mes plus belles ann\u00e9es. \nViens, Toinette, prenons auparavant toutes ses clefs.<\/pre>\n<\/div><\/div>\n\n\n\n<p>Les yeux dessill\u00e9s d\u2019un coup d\u2019un seul, Argan ressuscite et explose d\u2019indignation, provoquant la fuite de B\u00e9line.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">ARGAN, \u00e0 B\u00e9line qui sort.\u2014 Je suis bien aise \nde voir votre amiti\u00e9, et d\u2019avoir entendu \nle beau pan\u00e9gyrique que vous avez fait de moi. \n<u>Voil\u00e0 un avis au lecteur, qui me rendra sage \u00e0 l\u2019avenir,<\/u>\n<u>et qui m\u2019emp\u00eachera de faire bien des choses.<\/u>\nL\u2019exp\u00e9rience n\u2019est toutefois pas termin\u00e9e. \nToinette sugg\u00e8re \u00e0 son ma\u00eetre de la reproduire \navec sa fille Ang\u00e9lique, afin de bien lui montrer, \npar contraste, de quel c\u00f4t\u00e9 doit pencher \nsa tendresse et sa sollicitude, ce qui donne\u00a0:\nANG\u00c9LIQUE.\u2014 \u00d4 Ciel\u00a0! quelle infortune\u00a0! \nquelle atteinte cruelle\u00a0! H\u00e9las\u00a0! \nfaut-il que je perde mon p\u00e8re, \nla seule chose qui me restait au monde\u00a0; \net qu\u2019encore pour un surcro\u00eet de d\u00e9sespoir, \nje le perde dans un moment o\u00f9 il \u00e9tait irrit\u00e9 contre moi\u00a0? \nQue deviendrai-je, malheureuse, \net quelle consolation trouver apr\u00e8s une si grande perte\u00a0?<\/pre>\n<\/div><\/div>\n\n\n\n<p>Cette mise en sc\u00e8ne permet \u00e9galement \u00e0 Val\u00e8re, qui arrive opportun\u00e9ment sur ces entrefaites, de montrer son bon naturel:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre id=\"block-07716447-c252-4686-b5de-fdb3e78aff46\" class=\"wp-block-preformatted\">VALERE.\u2014 \u00d4 Ciel\u00a0! quel accident\u00a0! quel coup inopin\u00e9\u00a0! \nh\u00e9las\u00a0! apr\u00e8s la demande que j\u2019avais conjur\u00e9 \nvotre oncle de lui faire pour moi, \nje venais me pr\u00e9senter \u00e0 lui, \net t\u00e2cher par mes respects et par mes pri\u00e8res, \nde disposer son c\u0153ur \u00e0 vous accorder \u00e0 mes v\u0153ux.<\/pre>\n<\/div><\/div>\n\n\n\n<p>L\u2019esprit presque remis \u00e0 l\u2019endroit par ce traitement de choc, Argan accepte de bon gr\u00e9 de donner la main d\u2019Ang\u00e9lique \u00e0 Val\u00e8re \u00e0 la condition que ce dernier se fasse m\u00e9decin, puis finit par se laisser convaincre tout aussi facilement qu\u2019il peut tout aussi bien lui-m\u00eame devenir m\u00e9decin:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre id=\"block-07716447-c252-4686-b5de-fdb3e78aff46\" class=\"wp-block-preformatted\">ARGAN.\u2014 Je pense, mon fr\u00e8re, que vous vous moquez de moi. \nEst-ce que je suis en \u00e2ge d\u2019\u00e9tudier\u00a0?\nB\u00c9RALDE.\u2014Bon, \u00e9tudier. Vous \u00eates assez savant\u00a0; \net il y en a beaucoup parmi eux, \nqui ne sont pas plus habiles que vous.\nARGAN.\u2014 Mais il faut savoir bien parler latin, \nconna\u00eetre les maladies, et les rem\u00e8des qu\u2019il y faut faire.\nB\u00c9RALDE.\u2014 En recevant la robe et le bonnet de m\u00e9decin, \nvous apprendrez tout cela, \net vous serez apr\u00e8s plus habile que vous ne voudrez.\nARGAN.\u2014 Quoi\u00a0? l\u2019on sait discourir \nsur les maladies quand on a cet habit-l\u00e0\u00a0?\nB\u00c9RALDE.\u2014 Oui. L\u2019on n\u2019a qu\u2019\u00e0 parler\u00a0; \navec une robe, et un bonnet, tout galimatias \ndevient savant, et toute sottise devient raison.\nTOINETTE.\u2014 Tenez, Monsieur, \nquand il n\u2019y aurait que votre barbe, \nc\u2019est d\u00e9j\u00e0 beaucoup, et la barbe \nfait plus de la moiti\u00e9 d\u2019un m\u00e9decin.<\/pre>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Orgon_lobsede_du_salut_de_son_ame\"><\/span><strong>Orgon, l\u2019obs\u00e9d\u00e9 du salut de son \u00e2me<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Orgon, l\u2019\u00e9quivalent de M. Jourdain et Argan dans la plus c\u00e9l\u00e8bre pi\u00e8ce de Moli\u00e8re, le <em>Tartuffe ou l\u2019imposteur<\/em>, est un chef de famille fortun\u00e9. P\u00e8re d\u2019un fils, Damis, et d\u2019une fille, Marianne, issus d\u2019un premier mariage, il a \u00e9pous\u00e9 en secondes noces la belle Elmire, qui contrairement \u00e0 B\u00e9line, l\u2019aime d\u2019amour sinc\u00e8re. Angoiss\u00e9 jusqu\u2019aux tr\u00e9fonds de son \u00e2me pour son salut, et la vie \u00e9ternelle qui va avec, Orgon re\u00e7oit tous les jours chez lui depuis plusieurs mois Tartuffe, d\u00e9vote personne d\u00e9pourvue de tout bien, qui passe son existence en \u0153uvres pies et mortifications ostensibles, pr\u00f4ne l\u2019aust\u00e9rit\u00e9 absolue dans les occupations terrestres, et se pr\u00e9tend tout entier tourn\u00e9 vers les f\u00e9licit\u00e9s c\u00e9lestes dont il fait miroiter l\u2019obtention \u00e0 Orgon. De la sorte Tartuffe a acquis dans la maison une influence croissante et finalement d\u00e9mesur\u00e9e, au point de prendre aux yeux d&rsquo;Orgon plus de valeur que les membres de la maisonn\u00e9e, auxquels il se permet de faire d\u2019audacieuses remontrances. La m\u00e8re d\u2019Orgon, Mme Pernelle, fieff\u00e9e bigote, est aussi entich\u00e9e de Tartuffe que son fils&nbsp;: elle n\u2019a pas de mots assez durs contre les membres de la maisonn\u00e9e, qu\u2019elle accuse de d\u00e9pravation, et ne tarit pas de louanges au contraire envers Tartuffe, au point de le proclamer un Saint Homme, repr\u00e9sentant sur Terre des vertus divines. Or tout cela n\u2019est que du cin\u00e9ma, Tartuffe en r\u00e9alit\u00e9 est un escroc, un imposteur, un sc\u00e9l\u00e9rat, qui ne joue ce r\u00f4le que pour tirer tout ce qu\u2019il peut de la bourse sans fond d\u2019Orgon, dont il a compris \u00e0 merveille la b\u00e9ante faille psychologique, qui ne demande qu\u2019a \u00eatre combl\u00e9e. Il a m\u00eame pouss\u00e9 son emprise si loin qu\u2019il est parvenu \u00e0 d\u00e9cider son bienfaiteur \u00e0 lui accorder la main de sa fille, afin de l\u2019avoir aupr\u00e8s de lui \u00e0 tout instant. La cuirasse du tra\u00eetre ne comporte qu\u2019un seul d\u00e9faut&nbsp;: il est tomb\u00e9 amoureux d\u2019Elmire. Mais si loin va la c\u00e9cit\u00e9 d\u2019Orgon que lorsque son fils Damis pense pouvoir se d\u00e9barrasser du faussaire en r\u00e9v\u00e9lant \u00e0 son p\u00e8re une d\u00e9claration d\u2019amour que celui-ci \u00e0 faite \u00e0 Elmire et qu\u2019il a surprise, plut\u00f4t que de l\u2019en remercier le p\u00e8re ne veut rien entendre, et explose en impr\u00e9cations contre son fils. Il d\u00e9fend Tartuffe envers et contre tout, et loin de prendre la d\u00e9cision de le chasser, intime \u00e0 ce dernier de rester dans sa maison&nbsp;: \u00ab<em>&nbsp;Non, vous demeurerez&nbsp;; il y va de ma vie&nbsp;!&nbsp;<\/em>\u00bb. Emport\u00e9 par son aveugle rage, il prend en sus la d\u00e9cision de d\u00e9sh\u00e9riter son fils \u00e0 son profit, ce qu\u2019il fait sur l\u2019heure&nbsp;!<\/p>\n\n\n\n<p>La question lancinante que se posent toutes les personnes de l\u2019entourage d\u2019Orgon, comme dans les deux autres pi\u00e8ces est la suivante&nbsp;: comment diable allons-nous enfin parvenir \u00e0 ouvrir les yeux \u00e0 cet \u00eatre litt\u00e9ralement envo\u00fbt\u00e9, qui dans un aveuglement complet et de plus en plus obstin\u00e9 achemine pas \u00e0 pas sa famille \u00e0 la ruine&nbsp;? Comment, nom d\u2019un homme, allons-nous parvenir \u00e0 lui faire comprendre que Tartuffe est en tout <em>l\u2019antith\u00e8se exacte<\/em> de ce qu\u2019il pr\u00e9tend \u00eatre, \u00e0 savoir un menteur, un voleur, un imposteur, un manipulateur, disciple et membre de la secte la plus inf\u00e2me dont l\u2019humanit\u00e9 ait \u00e0 d\u00e9plorer et subir l\u2019existence&nbsp;?Ni Damis (par la col\u00e8re), ni la servante Dorine (par la raillerie), ni son fr\u00e8re l\u2019avis\u00e9 Cl\u00e9ante (par la raison), ni sa fille Marianne (par la compassion) ne parviennent \u00e0 lib\u00e9rer Orgon du sort que Tartuffe lui a jet\u00e9. De surcro\u00eet ce dernier est parvenu \u00e0 isoler compl\u00e8tement la famille en faisant fuir tous les visiteurs. Comme dans les deux autres pi\u00e8ces, la t\u00e2che a d\u2019abord l\u2019air impossible\u2026 La faille psychologique d\u2019Orgon est trop profonde, Tartuffe est parvenu \u00e0 la combler avec une habilet\u00e9 diabolique, et Orgon est depuis trop longtemps persuad\u00e9 de la saintet\u00e9 de Tartuffe pour pouvoir changer facilement et du tout au tout d\u2019opinion \u00e0 son \u00e9gard. Il en est venu \u00e0 nourrir une relation de <em>d\u00e9pendance<\/em> \u00e0 l\u2019\u00e9gard de Tartuffe, qui de simplement rassurant au d\u00e9part a fini par devenir indispensable. Le bon sens d\u2019Orgon \u00e9t\u00e9 r\u00e9duit \u00e0 n\u00e9ant. Un et un peuvent faire trois. Il peut faire jour quand il fait nuit. L\u2019\u00e9tranger peut \u00eatre pr\u00e9f\u00e9r\u00e9 au prochain. Tartuffe pourrait facilement le convaincre qu\u2019en se mettant un masque en tissu b\u00e9ni sur la bouche, il pourrait se prot\u00e9ger des propos et pens\u00e9es impurs dont les miasmes flottent dangereusement dans la maison sous la forme d\u2019\u00e9charpes contagieuses d\u2019une fum\u00e9e impie, m\u00eame si chacun sait qu\u2019un masque en tissu, aussi serr\u00e9es en soient les mailles, ne sauraient prot\u00e9ger d\u2019une mati\u00e8re aussi insaisissable que la parole et la pens\u00e9e.<\/p>\n\n\n\n<p>Finalement, le destin de la famille est en train les mains d\u2019Elmire, qui heureusement n\u2019est pas une B\u00e9line&nbsp;! Elle met son mari au d\u00e9fi&nbsp;:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">ELMIRE.\u2014 J'admire, encore un coup, cette faiblesse \u00e9trange.    \nMais que me r\u00e9pondrait votre incr\u00e9dulit\u00e9,\n<span style=\"text-decoration: underline;\">Si je vous faisais voir qu'on vous dit v\u00e9rit\u00e9?<\/span>\nORGON.\u2014 <span style=\"text-decoration: underline;\">Voir?<\/span>\nELMIRE.\u2014 Oui.\nORGON.\u2014 Chansons.\nELMIRE.\u2014 Mais quoi! <span style=\"text-decoration: underline;\">si je trouvais mani\u00e8re\nDe vous le faire voir avec pleine lumi\u00e8re?<\/span>\nORGON.\u2014 Contes en l'air.\nELMIRE.\u2014 Quel homme! Au moins r\u00e9pondez-moi.\n<u>Je ne vous parle pas de nous ajouter foi:<\/u>\n<u>Mais supposons ici, que d'un lieu qu'on peut prendre,<\/u>\n<u>On vous f\u00eet clairement tout voir, et tout entendre,<\/u>\n<u>Que diriez-vous alors de votre homme de bien?<\/u>\nORGON.\u2014 En ce cas, je dirais que... Je ne dirais rien,\nCar cela ne se peut.\nELMIRE.\u2014 L'erreur trop longtemps dure,\nEt c'est trop condamner ma bouche d'imposture.\n<u>Il faut que par plaisir, et sans aller plus loin,<\/u>\n<u>De tout ce qu'on vous dit, je vous fasse t\u00e9moin.<\/u>\nORGON.\u2014 Soit je vous prends au mot. Nous verrons votre adresse\nEt comment vous pourrez remplir cette promesse.<\/pre>\n<\/div><\/div>\n\n\n\n<p>Cela dit elle demande \u00e0 son mari de se cacher sous la table, et fait venir Tartuffe. Lui expliquant pourquoi elle n\u2019a pas voulu d\u2019abord r\u00e9pondre positivement \u00e0 sa d\u00e9claration d\u2019amour, elle s\u2019avoue finalement toute \u00e0 lui. D\u2019abord m\u00e9fiant face \u00e0 ce revirement qui le ravit, Tartuffe trop amoureux peu \u00e0 peu abaisse ses d\u00e9fenses, et renouvelant sa d\u00e9claration d\u2019amour, la presse d\u2019en avoir sur le champ la preuve charnelle. Face \u00e0 tant d\u2019empressement Elmire lui pr\u00e9sente ce scrupule\u00a0:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">Mais comment consentir \u00e0 ce que vous voulez,\nSans offenser le Ciel dont toujours parlez\u00a0?<\/pre>\n<\/div><\/div>\n\n\n\n<p>Tartuffe d\u00e9voile alors toute la noirceur de son \u00e2me.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">Si ce n'est que le Ciel qu'\u00e0 mes v\u0153ux on oppose,\nLever un tel obstacle, est \u00e0 moi peu de chose,\nEt cela ne doit pas retenir votre c\u0153ur.\n(\u2026)\nJe puis vous dissiper ces craintes ridicules,\nMadame, et je sais l'art de lever les scrupules.\nLe Ciel d\u00e9fend, de vrai, certains contentements;\nMais on trouve avec lui des accommodements.\n(\u2026)\nContentez mon d\u00e9sir, et n'ayez point d'effroi,\nJe vous r\u00e9ponds de tout, et prends le mal sur moi.\n(\u2026)\nEnfin votre scrupule est facile \u00e0 d\u00e9truire,\nVous \u00eates assur\u00e9e ici d'un plein secret,\nEt le mal n'est jamais que dans l'\u00e9clat qu'on fait.\nLe scandale du monde, est ce qui fait l'offense;\nEt ce n'est pas p\u00e9cher, que p\u00e9cher en silence.<\/pre>\n<\/div><\/div>\n\n\n\n<p>Enfin, pour faire tomber les derni\u00e8res d\u00e9fenses d\u2019Elmire, Tartuffe l\u00e2che ces phrases terribles\u00a0:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">Qu'est-il besoin pour lui, du soin que vous prenez?\n<u>C'est un homme, entre nous, \u00e0 mener par le nez.<\/u>\nDe tous nos entretiens, il est pour faire gloire,\n<u>Et je l'ai mis au point de voir tout, sans rien croire.<\/u><\/pre>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"1024\" src=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Ogon-suprend-Tartuffe-675x1024.jpg\" alt=\"\" class=\"wp-image-1141\" srcset=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Ogon-suprend-Tartuffe-675x1024.jpg 675w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Ogon-suprend-Tartuffe-198x300.jpg 198w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Ogon-suprend-Tartuffe-768x1165.jpg 768w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Ogon-suprend-Tartuffe-1013x1536.jpg 1013w, https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Ogon-suprend-Tartuffe.jpg 1255w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><figcaption>Quel biais a-t-il fallu trouver pour enfin amener Orgon \u00e0 reconna\u00eetre l&rsquo;abominable duplicit\u00e9 de Tartuffe !<\/figcaption><\/figure>\n\n\n\n<p>Cette fois, enfin, Orgon est convaincu, et plus que convaincu&nbsp;: sa rage est \u00e0 la mesure de l\u2019aveuglement dans lequel il a si longtemps \u00e9t\u00e9 englu\u00e9. Malheureusement, comme il s\u2019empresse, apr\u00e8s avoir jailli de sa cachette, de chasser avec fracas Tartuffe de chez lui, ce dernier, se d\u00e9voilant pour de bon, lui rappelle qu\u2019il lui a remis par \u00e9crit tout son bien, et que c\u2019est \u00e0 lui de vider les lieux dont il est le nouveau propri\u00e9taire l\u00e9gitime.<\/p>\n\n\n\n<p>Pour l\u2019analogie que nous allons d\u00e9velopper ensuite, ce d\u00e9nouement \u00e0 d\u2019autres suites instructives\u00a0: alors qu\u2019Orgon se r\u00e9concilie avec tous ses proches, qui lui pardonnent volontiers, et qu\u2019ils cherchent ensemble un moyen de s\u2019extirper de cet horrible pi\u00e8ge, survient Mme Pernelle qui continue de ne rien vouloir croire. C\u2019est \u00e0 pr\u00e9sent au tour d\u2019Orgon d\u2019affronter en clairvoyant les rationalisations stupides de sa radicalis\u00e9e de m\u00e8re :<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">MADAME PERNELLE .\u2014 <u>Mon fils, je ne puis du tout croire<\/u>\n<u>Qu'il ait voulu commettre une action si noire.<\/u>\nORGON .\u2014 Comment?\nMADAME PERNELLE .\u2014 Les gens de bien sont envi\u00e9s toujours.\nORGON .\u2014 Que voulez-vous donc dire avec votre discours,\nMa m\u00e8re?\nMADAME PERNELLE .\u2014 Que chez vous on vit d'\u00e9trange sorte,\nEt qu'on ne sait que trop la haine qu'on lui porte.\nORGON .\u2014 Qu'a cette haine \u00e0 faire avec ce qu'on vous dit?\nMADAME PERNELLE .\u2014 Je vous l'ai dit cent fois, quand vous \u00e9tiez petit.\nLa vertu, dans le monde, est toujours poursuivie;\nLes envieux mourront, mais non jamais l'envie.\nORGON.\u2014 Mais que fait ce discours aux choses d'aujourd'hui?\nMADAME PERNELLE .\u2014 On vous aura forg\u00e9 cent sots contes de lui.\nORGON.\u2014 Je vous ai dit d\u00e9j\u00e0, que j'ai vu tout moi-m\u00eame.\nMADAME PERNELLE .\u2014 Des esprits m\u00e9disants, la malice est extr\u00eame.\nORGON .\u2014 Vous me feriez damner, ma m\u00e8re. <u>Je vous di,<\/u>\n<u>Que j'ai vu de mes yeux, un crime si hardi<\/u>.\nMADAME PERNELLE .\u2014 Les langues ont toujours du venin \u00e0 r\u00e9pandre;\nEt rien n'est, ici-bas, qui s'en puisse d\u00e9fendre.\nORGON .\u2014 C'est tenir un propos de sens bien d\u00e9pourvu !\n<u>Je l'ai vu, dis-je, vu, de mes propres yeux vu,<\/u>\n<u>Ce qu'on appelle vu: faut-il vous le rebattre<\/u>\n<u>Aux oreilles cent fois, et crier comme quatre?<\/u>\nMADAME PERNELLE .\u2014 <u>Mon Dieu, le plus souvent, l'apparence d\u00e9\u00e7oit.<\/u>\n<u>Il ne faut pas toujours juger sur ce qu'on voit.<\/u>\nORGON .\u2014 J'enrage.\nMADAME PERNELLE.\u2014 Aux faux soup\u00e7ons la nature est sujette;\nEt c'est souvent \u00e0 mal, que le bien s'interpr\u00e8te.\nORGON.\u2014 Je dois interpr\u00e9ter \u00e0 charitable soin,\nLe d\u00e9sir d'embrasser ma femme?\nMADAME PERNELLE.\u2014 Il est besoin,\nPour accuser les gens, d'avoir de justes causes,\nEt vous deviez attendre \u00e0 vous voir s\u00fbr des choses.\nORGON.\u2014H\u00e9, diantre, le moyen de m'en assurer mieux?\nJe devais donc, ma m\u00e8re, attendre qu'\u00e0 mes yeux\nIl e\u00fbt... Vous me feriez dire quelque sottise.\nMADAME PERNELLE .\u2014 Enfin d'un trop pur z\u00e8le on voit son \u00e2me \u00e9prise,\nEt je ne puis du tout me mettre dans l'esprit,\nQu'il ait voulu tenter les choses que l'on dit.\nORGON.\u2014 Allez. Je ne sais pas, si vous n'\u00e9tiez ma m\u00e8re,\nCe que je vous dirais, tant je suis en col\u00e8re.<\/pre>\n<\/div><\/div>\n\n\n\n<p>Dialogue de sourds, que Dorine conclut malicieusement par cette morale :<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre id=\"block-0d5b3afa-b13c-4a8c-96d6-1be3ac8a76f7\" class=\"wp-block-preformatted\"><span style=\"text-decoration: underline;\"><u>Juste retour, Monsieur, des choses d'ici-bas.<\/u>\n<u>Vous ne vouliez point croire, et l'on ne vous croit pas<\/u><\/span>.<\/pre>\n<\/div><\/div>\n\n\n\n<p>Pour faire changer d\u2019avis Madame Pernelle, il faut que Tartuffe paraisse devant eux avec son vrai visage, les sommant imp\u00e9rieusement de vider les lieux dans les 24 heures. Alors seulement elle accepte de se ranger \u00e0 l\u2019opinion de tous\u00a0: \u00ab\u00a0<em>Je suis tout \u00e9baudie, et je tombe des nues.\u00a0\u00bb <\/em>Comme son fils, il fallait qu\u2019elle <em>voie de ses propres ses yeux<\/em>.<\/p>\n\n\n\n<p>Heureusement, comme toujours chez Moli\u00e8re, tout est bien qui finit bien. Accompagn\u00e9 de l\u2019exempt du Prince, qui est cens\u00e9 ex\u00e9cuter l\u2019arr\u00eat d\u2019expulsion en sa pr\u00e9sence, Tartuffe d\u00e9voile \u00e0 nouveau sans fard son hideux vrai visage, ce qui signe sa perte. C\u2019est \u00e0 ce dernier, et non \u00e0 Orgon, que l\u2019Exempt intime de le suivre, et pour l\u2019emmener en prison. Il tient alors ce discours au ma\u00eetre de maison\u00a0:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Philaminte_la_femme_savante\"><\/span><strong>Philaminte, la femme savante<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\">Remettez-vous, Monsieur, d'une alarme si chaude.\n<span style=\"text-decoration: underline;\">Nous vivons sous un Prince ennemi de la fraude,<\/span>\n<u>Un Prince dont les yeux se font jour dans les c\u0153urs,<\/u>\n<u>Et que ne peut tromper tout l'art des imposteurs.<\/u>\n<u>D'un fin discernement, sa grande \u00e2me pourvue,<\/u>\n<u>Sur les choses toujours jette une droite vue<\/u>,\nChez elle jamais rien ne surprend trop d'acc\u00e8s,\nEt sa ferme raison ne tombe en nul exc\u00e8s.\n<u>Il donne aux gens de bien une gloire immortelle<\/u>,\nMais sans aveuglement il fait briller ce z\u00e8le,\nEt l'amour pour les vrais, ne ferme point son c\u0153ur\n\u00c0 tout ce que les faux doivent donner d'horreur.\nCelui-ci n'\u00e9tait pas pour le pouvoir surprendre,\nEt de pi\u00e8ges plus fins on le voit se d\u00e9fendre.\n<u>D'abord il a perc\u00e9, par ses vives clart\u00e9s,<\/u>\n<u>Des replis de son c\u0153ur, toutes les l\u00e2chet\u00e9s.<\/u>\nVenant vous accuser, il s'est trahi lui-m\u00eame,\nEt par un juste trait de l'\u00e9quit\u00e9 supr\u00eame,\nS'est d\u00e9couvert au Prince un fourbe renomm\u00e9,\nDont sous un autre nom il \u00e9tait inform\u00e9;\nEt c'est un long d\u00e9tail d'actions toutes noires,\nDont on pourrait former des volumes d'histoires.\nCe monarque, en un mot, a vers vous d\u00e9test\u00e9\nSa l\u00e2che ingratitude, et sa d\u00e9loyaut\u00e9;\n\u00c0 ses autres horreurs, il a joint cette suite,\nEt ne m'a, jusqu'ici, soumis \u00e0 sa conduite,\nQue pour voir l'impudence aller jusques au bout,\nEt vous faire, par lui, faire raison de tout.\nOui, de tous vos papiers, dont il se dit le ma\u00eetre,\nIl veut qu'entre vos mains, je d\u00e9pouille le tra\u00eetre.<\/pre>\n<\/div><\/div>\n\n\n\n<p>On trouve le pendant f\u00e9minin de ces trois barbons envo\u00fbt\u00e9s et tyranniques chez Philaminte, dans <em>L\u2019\u00e9cole des femmes&nbsp;<\/em>: Philaminte, \u00e9pouse de Chrysale, que dans le couple elle a subjugu\u00e9, s\u2019est prise d\u2019une passion immod\u00e9r\u00e9e, de concert avec sa belle-s\u0153ur B\u00e9line et sa fille a\u00een\u00e9e Armande, du \u00ab&nbsp;bel esprit&nbsp;\u00bb et homme d\u2019\u00e2ge m\u00fbr Trissotin. Il vient tous les jours dans la maison o\u00f9 il \u00e9blouit son public f\u00e9minin fascin\u00e9 par un langage plein de pompe, d\u2019appr\u00eats, de figures, de r\u00e9f\u00e9rences p\u00e9dantes aux auteurs et philosophes grecs et latins, et aux grammairiens c\u00e9l\u00e8bres. A l\u2019instar de ses alter ego masculins, Philaminte se met en t\u00eate de forcer sa fille cadette, Henriette, jeune fille de bon sens insensible au verbiage de l\u2019escroc \u00e8s us du bien-dire, \u00e0 prendre Trissotin pour \u00e9poux, mariage auquel ce dernier n\u2019est pas hostile, non par amour pour Henriette, mais par ambition de devenir ainsi riche gr\u00e2ce \u00e0 la dot consid\u00e9rable qu\u2019elle lui apportera. Le faible mari, la cadette victime et la servante Martine au langage ch\u00e2ti\u00e9 tentent tour \u00e0 tour, chacun tentant avec ses mots \u00e0 lui de frayer un chemin dans le labyrinthe o\u00f9 le bon sens de Philaminte s\u2019est perdu, afin de la faire descendre de son Olympe de pacotille. Mais c\u2019est en pure perte&nbsp;; quand elle re\u00e7oit, d\u2019un jaloux et concurrent de Trissotin sur ce march\u00e9, une lettre r\u00e9v\u00e9lant les plagiats de ce dernier dans les po\u00e8mes qu\u2019il leur a pr\u00e9sent\u00e9s pour siens, jointe \u00e0 un colis des ouvrages marqu\u00e9s aux pages pill\u00e9es, elle refuse de les ouvrir pour v\u00e9rifier par elle-m\u00eame, refuse m\u00eame d\u2019en lire les titres, d\u2019en regarder m\u00eame les couvertures&nbsp;!&#8230; imputant la d\u00e9marche \u00e0 pure volont\u00e9 jalouse de nuire au saint homme de lettres qui dans son \u00e2me ensorcel\u00e9e a pris l\u2019importance du soleil dans le ciel. Comme Argan et Orgon, il faut litt\u00e9ralement lui <em>mettre le nez dedans<\/em> pour qu\u2019elle s\u2019\u00e9veille enfin de l\u2019enchantement. Le stratag\u00e8me est mis en \u0153uvre par Ariste, le fr\u00e8re de Chrysale&nbsp;: alors que le mariage est pr\u00e8s de se conclure en pr\u00e9sence du notaire, celui-ci d\u00e9boule in extremis porteur de deux lettres adress\u00e9es, l\u2019une \u00e0 son fr\u00e8re, l\u2019autre \u00e0 son \u00e9pouse Philaminte&nbsp;: la premi\u00e8re lui annonce sa compl\u00e8te banqueroute, la seconde qu\u2019elle vient d\u2019\u00eatre ruin\u00e9e dans un proc\u00e8s&nbsp;; ce qu\u2019apprenant, Trissotin se d\u00e9gage brusquement de son engagement, n\u2019y voyant plus aucun int\u00e9r\u00eat mat\u00e9riel. Alors Philaminte reconna\u00eet&nbsp;:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse\"><u>Je vois, je vois de vous, non pas pour votre gloire,<\/u>\n<u>Ce que jusques ici j\u2019ai refus\u00e9 de croire.<\/u><\/pre>\n<\/div><\/div>\n\n\n\n<p>Puis\u00a0:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"wp-block-verse has-text-align-left\"><u>Qu\u2019il a bien d\u00e9couvert son \u00e2me mercenaire\u00a0!<\/u>\nEt que peu philosophe est ce qu\u2019il vient de faire\u00a0!<\/pre>\n<\/div><\/div>\n\n\n\n<p>En tout \u00eatre humain r\u00e9side une faille psychologique susceptible de r\u00e9duire \u00e0 n\u00e9ant son bon sens, qui le rend vuln\u00e9rable aux manipulations des escrocs, charlatans, parasites en tous genres. Telle est l\u2019une des grandes le\u00e7ons que Moli\u00e8re a voulu transmettre dans son \u0153uvre. Quand sont en jeu les questions d\u2019int\u00e9r\u00eat les plus intimes, \u00e0 savoir l\u2019ambition personnelle, le d\u00e9sir des richesses, la peur de la maladie et de la mort, l\u2019aspiration \u00e0 l\u2019\u00e9ternit\u00e9, l\u2019amour, un vice, une phobie, une passion profond\u00e9ment enracin\u00e9s, il n\u2019est rien qu\u2019on ne soit port\u00e9 \u00e0 croire, jusqu\u2019au point o\u00f9 tout discours d\u00e9mystificateur, aussi convaincant soit-il, se retrouve impuissant devant mur infranchissable, \u00e0 moins d\u2019un <em>biais<\/em> qui n\u2019ait rien \u00e0 devoir au raisonnement&#8230; Nous allons voir \u00e0 pr\u00e9sent, guid\u00e9s par cette boussole, comment les Tartuffes modernes ont <em>orgonis\u00e9<\/em> toute une partie de la population \u00e0 l\u2019occasion de la crise sanitaire de la Covid-19 qui ressemble de plus en plus \u00e0 un tunnel sans fin.<\/p>\n\n\n\n<p>Fran\u00e7ois Belliot, 1<sup>er<\/sup> d\u00e9cembre 2020<\/p>\n\n\n\n<p>Seconde partie le 8 d\u00e9cembre : Les Tartuffes et les Orgons modernes de la Covid-19 <\/p>\n\n<form action=\"https:\/\/www.paypal.com\/donate\" method=\"post\" target=\"_top\">\n<input type=\"hidden\" name=\"hosted_button_id\" value=\"TJ3ZM8YMEYAKQ\" \/>\n<input type=\"image\" src=\"https:\/\/www.paypalobjects.com\/fr_FR\/FR\/i\/btn\/btn_donateCC_LG.gif\" border=\"0\" name=\"submit\" title=\"PayPal - The safer, easier way to pay online!\" alt=\"Bouton Faites un don avec PayPal\" \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"\" border=\"0\" src=\"https:\/\/www.paypal.com\/fr_FR\/i\/scr\/pixel.gif\" width=\"1\" height=\"1\" \/>\n<\/form>","protected":false},"excerpt":{"rendered":"<p>\u00ab&nbsp;Il y a de certains esprits qu\u2019il ne faut prendre qu\u2019en biaisant&nbsp;\u00bb Val\u00e8re, dans L\u2019avare ou l\u2019\u00e9cole du mensonge, acte I, sc\u00e8ne 8 Introduction Si d\u2019aventure cette \u00e9tude se r\u00e9v\u00e9lait de quelque utilit\u00e9 pour arracher au moins quelques esprits pris au pi\u00e8ge dans la toile du discours sanitaire anti Covid martel\u00e9 quotidiennement depuis pr\u00e8s de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La Covid-19 au prisme de Moli\u00e8re (1\/3)&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80,73],"tags":[323,360,361,75,357,359,358],"class_list":["post-1135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escroqueries-mediatiques","category-litterature","tag-covid-19","tag-hydroxychloroquine","tag-medecine","tag-medias","tag-moliere","tag-orgon","tag-tartuffe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Covid-19 au prisme de Moli\u00e8re (1\/3) - Fran\u00e7ois Belliot<\/title>\n<meta name=\"description\" content=\"Si Moli\u00e8re revenait sur Terre en 2020, il trouverait dans la crise sanitaire actuelle un sujet collant parfaitement \u00e0 ses canevas f\u00e9tiches.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Covid-19 au prisme de Moli\u00e8re (1\/3) - Fran\u00e7ois Belliot\" \/>\n<meta property=\"og:description\" content=\"Si Moli\u00e8re revenait sur Terre en 2020, il trouverait dans la crise sanitaire actuelle un sujet collant parfaitement \u00e0 ses canevas f\u00e9tiches.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Fran\u00e7ois Belliot\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-30T16:57:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-20T16:13:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2287\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francoisbelliot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"francoisbelliot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/\",\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/\",\"name\":\"La Covid-19 au prisme de Moli\u00e8re (1\/3) - Fran\u00e7ois Belliot\",\"isPartOf\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg\",\"datePublished\":\"2020-11-30T16:57:10+00:00\",\"dateModified\":\"2024-06-20T16:13:39+00:00\",\"author\":{\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\"},\"description\":\"Si Moli\u00e8re revenait sur Terre en 2020, il trouverait dans la crise sanitaire actuelle un sujet collant parfaitement \u00e0 ses canevas f\u00e9tiches.\",\"breadcrumb\":{\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#primaryimage\",\"url\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg\",\"contentUrl\":\"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg\",\"width\":2287,\"height\":2560,\"caption\":\"Moli\u00e8re au XXi\u00e8me si\u00e8cle aurait certainement trouv\u00e9 dans la situation actuelle mati\u00e8re \u00e0 com\u00e9die.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/francoisbelliot.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Covid-19 au prisme de Moli\u00e8re (1\/3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/francoisbelliot.fr\/#website\",\"url\":\"https:\/\/francoisbelliot.fr\/\",\"name\":\"Fran\u00e7ois Belliot\",\"description\":\"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/francoisbelliot.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9\",\"name\":\"francoisbelliot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g\",\"caption\":\"francoisbelliot\"},\"url\":\"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Covid-19 au prisme de Moli\u00e8re (1\/3) - Fran\u00e7ois Belliot","description":"Si Moli\u00e8re revenait sur Terre en 2020, il trouverait dans la crise sanitaire actuelle un sujet collant parfaitement \u00e0 ses canevas f\u00e9tiches.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/","og_locale":"fr_FR","og_type":"article","og_title":"La Covid-19 au prisme de Moli\u00e8re (1\/3) - Fran\u00e7ois Belliot","og_description":"Si Moli\u00e8re revenait sur Terre en 2020, il trouverait dans la crise sanitaire actuelle un sujet collant parfaitement \u00e0 ses canevas f\u00e9tiches.","og_url":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/","og_site_name":"Fran\u00e7ois Belliot","article_published_time":"2020-11-30T16:57:10+00:00","article_modified_time":"2024-06-20T16:13:39+00:00","og_image":[{"width":2287,"height":2560,"url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg","type":"image\/jpeg"}],"author":"francoisbelliot","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"francoisbelliot","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/","url":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/","name":"La Covid-19 au prisme de Moli\u00e8re (1\/3) - Fran\u00e7ois Belliot","isPartOf":{"@id":"https:\/\/francoisbelliot.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#primaryimage"},"image":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#primaryimage"},"thumbnailUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg","datePublished":"2020-11-30T16:57:10+00:00","dateModified":"2024-06-20T16:13:39+00:00","author":{"@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9"},"description":"Si Moli\u00e8re revenait sur Terre en 2020, il trouverait dans la crise sanitaire actuelle un sujet collant parfaitement \u00e0 ses canevas f\u00e9tiches.","breadcrumb":{"@id":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#primaryimage","url":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg","contentUrl":"https:\/\/francoisbelliot.fr\/wp-content\/uploads\/2020\/11\/Moliere-par-mignard-tableau-scaled.jpg","width":2287,"height":2560,"caption":"Moli\u00e8re au XXi\u00e8me si\u00e8cle aurait certainement trouv\u00e9 dans la situation actuelle mati\u00e8re \u00e0 com\u00e9die."},{"@type":"BreadcrumbList","@id":"https:\/\/francoisbelliot.fr\/index.php\/2020\/11\/30\/la-covid-19-au-prisme-de-moliere-1-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/francoisbelliot.fr\/"},{"@type":"ListItem","position":2,"name":"La Covid-19 au prisme de Moli\u00e8re (1\/3)"}]},{"@type":"WebSite","@id":"https:\/\/francoisbelliot.fr\/#website","url":"https:\/\/francoisbelliot.fr\/","name":"Fran\u00e7ois Belliot","description":"litt\u00e9rature, g\u00e9opolitique, m\u00e9dias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/francoisbelliot.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/791f81a4c4fbc954624d3c5c758eb0a9","name":"francoisbelliot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/francoisbelliot.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b52cc48ac1e2056394ec5f771fa7c738?s=96&d=mm&r=g","caption":"francoisbelliot"},"url":"https:\/\/francoisbelliot.fr\/index.php\/author\/francoisbelliot\/"}]}},"_links":{"self":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":13,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"predecessor-version":[{"id":2198,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/posts\/1135\/revisions\/2198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media\/1137"}],"wp:attachment":[{"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/francoisbelliot.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}